{"id":230542,"date":"2024-06-11T13:49:00","date_gmt":"2024-06-11T11:49:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=230542"},"modified":"2024-06-11T15:23:29","modified_gmt":"2024-06-11T13:23:29","slug":"risultati-comunali-il-commento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/11\/risultati-comunali-il-commento\/","title":{"rendered":"RISULTATI COMUNALI, IL COMMENTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1065\" class=\"wp-image-230543\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/448099425_1009945247168873_2051770941149146079_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/448099425_1009945247168873_2051770941149146079_n.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/448099425_1009945247168873_2051770941149146079_n-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/448099425_1009945247168873_2051770941149146079_n-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/448099425_1009945247168873_2051770941149146079_n-768x511.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/448099425_1009945247168873_2051770941149146079_n-1536x1022.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>di <strong>Giuseppe Puppo<\/strong> ______&nbsp;&nbsp;<\/p>\n\n\n\n<p>E allora, sar\u00e0 ballottaggio. Questo il responso della lunga notte delle percentuali allo zero virgola e dell\u2019altalena delle speranze e dei timori.<\/p>\n\n\n\n<p>A dire la verit\u00e0, mentre scrivo mancano ancora i dati definitivi, quelli del Ministero dell\u2019Interno, gli unici che fanno testo, mancano i risultati di quattro sezioni su centodue e fra poco saranno passate ventiquattro ore esatte dall\u2019inizio dello spoglio. Per\u00f2 ci pu\u00f2 stare, non doveva succedere una lentezza simile, ma va bene, dopo aver visto i risultati delle elezioni presidenziali statunitensi ballare per giorni e giorni, dopo, dai, ci pu\u00f2 stare.<\/p>\n\n\n\n<p>Diamo per buone le percentuali acquisiste finora, che i risultati delle ultime quattro sezioni mancanti non dovrebbero modificare nella sostanza.<\/p>\n\n\n\n<p>Commentiamo il 49, 6 della Poli Bortone e il 47 di Salvemini.<\/p>\n\n\n\n<p>Sfiorata e sfumata la vittoria al primo turno della senatrice, ora deve ricominciare punto e a capo, per conquistare quella carica di sindaco cui tanto aspira nel suo progettato ritorno al futuro.<\/p>\n\n\n\n<p>Dalla sua c\u2019\u00e8 una coalizione apparentemente unita a questo giro, dopo tante laceranti divisioni di pi\u00f9 di un decennio a questa parte, cui, per usare un eufemismo, ella non \u00e8 stata certo estranea.<\/p>\n\n\n\n<p>Dir\u00f2 di pi\u00f9, unita non solo, ma che ha pure ritrovato entusiasmo sotto l\u2019egida della sua iconica candidatura, di una destra che \u00e8 nel dna della citt\u00e0 di Lecce dai tempi referendum sulla monarchia, ma che ci\u00f2 nonostante spesso non ha impedito risultati favorevoli all\u2019altra parte.<\/p>\n\n\n\n<p>Una unit\u00e0 e un entusiasmo che nemmeno l\u2019ultima sortita della &nbsp;Poli Bortone a favore del &nbsp;&nbsp;DDL ZAN da lei sottoscritto per Palazzo Carafa, pregiudiziale antifascista compresa, ha scalfito.<\/p>\n\n\n\n<p>Ma s\u00ec, le cose cambiano, e comunque quella Lecce di Sponziello, Almirante,&nbsp; Tatarella non esiste pi\u00f9, \u00e8 cambiato tutto, ed proprio questa la scommessa, l\u2019impossibile revival del passato,&nbsp; su cui ella si gioca la vittoria.<\/p>\n\n\n\n<p>Salvemini ha fatto il suo. Partito appena nove mesi fa gi\u00e0 battuto, a tal punto che nemmeno i suoi volevano ricandidarlo, \u00e8 riuscito a superare le perplessit\u00e0 del centro sinistra, con l\u2019 ottima mossa delle primarie e a ricompattarlo, quasi tutto. Gli mancano i soliti noti, i portatori di voti e di interessi personalistici, sempre pronti a riposizionarsi per tempo e a corre in soccorso del previsto vincitore, tipo Carlo Miglione, tipo Alfredo Pagliaro, i quali contribuirono in maniera determnante alla sua precedente afferazione e che invece adesso lo hanno abbandonato.<\/p>\n\n\n\n<p>Ora per\u00f2 se la gioca al ballottaggio, i cui esiti appaiono incerti e se vogliamo appassionanti come e anzi pi\u00f9 del primo turno.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Due parole sugli altri due candidati, che comunque non sono stati ininfluenti, in quanto il 3, 4 per cento circa che hanno preso in due, 1,7 a ciascuno, ha determinato&nbsp; il ballottaggio.<\/p>\n\n\n\n<p>Alberto Siculella fuori dal consiglio, dispiace, e dovrebbe dispiacere a tutti , dal momento che le sue due liste civiche erano la proposta pi\u00f9 interessante di questa campagna elettorale, soprattutto per il rispetto del territorio, il verde pubblico e oserei dire l\u2019ecologia dell\u2019anima.<\/p>\n\n\n\n<p>Niente da fare, 1,7 e nessun rappresentante, nonostante intelligenza e sostanza, che per\u00f2, se egli avr\u00e0 la capacit\u00e0 di non scoraggiarsi, potranno germogliare in futuro.<\/p>\n\n\n\n<p>Stesso risultato, 1,7, per Agostino Ciucci, che per\u00f2 non ha fatto proprio campagna elettorale, oggetto misterioso e per tanti versi emblematico, in questo strano mondo della politica leccese.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/11\/risultati-comunali-il-commento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/11\/risultati-comunali-il-commento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo ______&nbsp;&nbsp; E allora, sar\u00e0 ballottaggio. Questo il responso della lunga notte delle percentuali allo zero virgola e dell\u2019altalena delle speranze e dei timori. A dire la verit\u00e0, mentre scrivo mancano ancora i dati definitivi, quelli del Ministero dell\u2019Interno, gli unici che fanno testo, mancano i risultati di quattro sezioni su centodue e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":230543,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230542"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=230542"}],"version-history":[{"count":13,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230542\/revisions"}],"predecessor-version":[{"id":230568,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230542\/revisions\/230568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/230543"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=230542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=230542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=230542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}