{"id":231049,"date":"2024-06-26T16:44:50","date_gmt":"2024-06-26T14:44:50","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=231049"},"modified":"2024-06-26T16:46:20","modified_gmt":"2024-06-26T14:46:20","slug":"da-fuoco-alle-erbacce-per-ripulire-la-zona-e-provoca-un-vasto-incendio-nelle-campagne-di-santa-cesarea-terme-individuato-e-denunciato-a-piede-lbero","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/26\/da-fuoco-alle-erbacce-per-ripulire-la-zona-e-provoca-un-vasto-incendio-nelle-campagne-di-santa-cesarea-terme-individuato-e-denunciato-a-piede-lbero\/","title":{"rendered":"DA\u2019 FUOCO ALLE ERBACCE PER RIPULIRE LA SUA  ZONA E PROVOCA UN VASTO INCENDIO NELLE CAMPAGNE DI SANTA CESAREA TERME. INDIVIDUATO E DENUNCIATO A PIEDE LBERO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1156\" height=\"868\" class=\"wp-image-231050\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-1.jpg 1156w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-1-1024x769.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-1-768x577.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-1-400x300.jpg 400w\" sizes=\"(max-width: 1156px) 100vw, 1156px\" \/><\/p>\n\n\n\n<p>(e.l.) _______&nbsp;Ieri pomeriggio, grazie ad una tempestiva segnalazione di un cittadino, che aveva avvistato una colonna di fumo in fase di espansione, la Centrale Operativa dell\u2019 Arma dei Carabinieri ha allertato le pattuglie della Stazione di Poggiardo e del Nucleo Forestale di Otranto.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Queste, prontamente intervenute sul posto, in contrada \u201cLampitedde\u201d in agro di Santa Cesarea Terme, hanno constatato che l\u2019 incendio aveva gi\u00e0 percorso circa de ettari di terreni incolti, seminativi ed uliveti.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Indagini immediate esperite dai Forestali permettevano di risalire al responsabile, ancora in zona, che aveva dato fuoco alla vegetazione spontanea a ridosso di un muretto a secco e poi, con favore di vento, il focolaio aveva invaso i terreni retrostanti, con il rischio di ulteriore propagazione.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; I Carabinieri hanno quindi proceduto a deferire l\u2019 incendiario, un uomo di 51 anni, alla Procura della Repubblica di Lecce, in stato di libert\u00e0, contestandogli il reato di incendio colposo, per cui \u00e8 prevista la pena della reclusione da 3 a 7 anni.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Le fiamme, invece, sono state domate grazie all\u2019 intervento delle squadre della protezione civile e dei Vigili del Fuoco.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; I Carabinieri Forestali, dal 15 giugno scorso, data di attivazione del periodo di grave pericolosit\u00e0 per gli incendi boschivi, come decretato dalla Regione Puglia, hanno intensificato ed organizzato i servizi di pattuglia con finalit\u00e0 di prevenzione e di repressione dei reati.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Particolare attenzione \u00e8 rivolta alle aree pi\u00f9 sensibili, come per l\u2019 appunto quella di Santa Cesarea Terme, le cui estensioni a pineta e macchia mediterranea sono state ripetutamente martoriate negli scorsi anni.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1156\" height=\"868\" class=\"wp-image-231051\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-2.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-2.jpg 1156w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-2-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-2-1024x769.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-2-768x577.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/Incendio-2-400x300.jpg 400w\" sizes=\"(max-width: 1156px) 100vw, 1156px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/26\/da-fuoco-alle-erbacce-per-ripulire-la-zona-e-provoca-un-vasto-incendio-nelle-campagne-di-santa-cesarea-terme-individuato-e-denunciato-a-piede-lbero\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/26\/da-fuoco-alle-erbacce-per-ripulire-la-zona-e-provoca-un-vasto-incendio-nelle-campagne-di-santa-cesarea-terme-individuato-e-denunciato-a-piede-lbero\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) _______&nbsp;Ieri pomeriggio, grazie ad una tempestiva segnalazione di un cittadino, che aveva avvistato una colonna di fumo in fase di espansione, la Centrale Operativa dell\u2019 Arma dei Carabinieri ha allertato le pattuglie della Stazione di Poggiardo e del Nucleo Forestale di Otranto. &nbsp;&nbsp;&nbsp;&nbsp; Queste, prontamente intervenute sul posto, in contrada \u201cLampitedde\u201d in agro di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":231050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231049"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=231049"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231049\/revisions"}],"predecessor-version":[{"id":231053,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231049\/revisions\/231053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/231050"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=231049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=231049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=231049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}