{"id":23108,"date":"2014-01-03T11:53:37","date_gmt":"2014-01-03T11:53:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23108"},"modified":"2014-01-03T11:53:37","modified_gmt":"2014-01-03T11:53:37","slug":"forconi-a-palermo-fima-movimenti-siano-sentinelle-del-messaggio-apostolico","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/03\/forconi-a-palermo-fima-movimenti-siano-sentinelle-del-messaggio-apostolico\/","title":{"rendered":"Forconi a Palermo: Fima, movimenti siano sentinelle del messaggio apostolico"},"content":{"rendered":"<p>\u201c<em>C\u2019\u00e8 una sola cosa che accomuna i forconi e le sigle presenti ieri alla manifestazione di Palermo: il messaggio del Papa. Di fronte alla globalizzazione dell\u2019 indifferenza, ad una economia che esclude e uccide, ad un denaro che governa invece di servire, il comune denominatore di tutti i partecipanti \u00e8 uno solo: sollecitare una redistribuzione dei redditi in Italia, in Europa e nel mondo, per combattere la disuguaglianza economica<\/em>\u201d. Lo ha dichiarato Saverio De Bonis, coordinatore della Fima, federazione italiana movimenti agricoli, dopo il sit-in di Palermo davanti a Palazzo d\u2019 Orleans.<br \/>\n\u201cChi volesse denigrare questa verit\u00e0 &#8211; aggiunge il portavoce della Fima &#8211;\u00a0 avanzando pregiudizi di natura politica o presunte contese di leadership, \u00e8 semplicemente dalla parte del nemico. Un nemico invisibile che il giorno di Natale \u00e8 apparso criticando l\u2019 esortazione <em>Evangelii Gaudium<\/em> di Papa Francesco, attraverso la bibbia della comunit\u00e0 finanziaria d\u2019 Europa, il Financial Times.<br \/>\nE\u2019 con questo spirito che la Fima ha partecipato all\u2019 appello di Martino Morsello, leader nazionale dei Forconi, insieme a Francesco Crupi, leader dei Forconi in Sicilia e a Danilo Calvani, leader del Coordinamento 9 Dicembre che raggruppa il 99% dei presidi italiani, dichiarando apertamente che tutti i movimenti o i coordinamenti hanno un solo obiettivo: diventare le sentinelle del messaggio del Papa con la mobilitazione pacifica e non violenta e con la proposta costruttiva.<br \/>\nLa Fima vigiler\u00e0, insieme agli altri gruppi e movimenti, affinch\u00e9 tale messaggio non passi inascoltato ed inviter\u00e0 le istituzioni italiane ed europee, per le rispettive competenze, ad assumere con rapidit\u00e0 e urgenza le necessarie riforme di politica agricola, fiscale, monetaria ed economica, per un nuovo modello di sviluppo che metta al centro l\u2019 uomo e la sua dignit\u00e0.<br \/>\n\u201cQuesta &#8211; conclude De Bonis &#8211; \u00e8 la vera rivoluzione che spetta a tutte le comunit\u00e0 cristiane che non vogliono rimanere con le mani in tasca a guardare, mentre il popolo soffre. Non \u00e8 giusto che il fatturato della finanza globale sia dieci volte pi\u00f9 grande dell\u2019 economia reale! Cos\u00ec la finanza fagocita l\u2019 economia, l\u2019 economia fagocita la politica, la politica fagocita i sindacati e il popolo non lo tutela nessuno, se non la Chiesa. I capipopolo che non hanno compreso queste cose e pensano di speculare attraverso i media sulla disperazione della gente, sono al servizio di altri interessi o di privilegi personali.\u201d<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/03\/forconi-a-palermo-fima-movimenti-siano-sentinelle-del-messaggio-apostolico\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/03\/forconi-a-palermo-fima-movimenti-siano-sentinelle-del-messaggio-apostolico\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u201cC\u2019\u00e8 una sola cosa che accomuna i forconi e le sigle presenti ieri alla manifestazione di Palermo: il messaggio del Papa. Di fronte alla globalizzazione dell\u2019 indifferenza, ad una economia che esclude e uccide, ad un denaro che governa invece di servire, il comune denominatore di tutti i partecipanti \u00e8 uno solo: sollecitare una redistribuzione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23108"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23108"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23108\/revisions"}],"predecessor-version":[{"id":23109,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23108\/revisions\/23109"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}