{"id":231090,"date":"2024-06-27T18:12:56","date_gmt":"2024-06-27T16:12:56","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=231090"},"modified":"2024-06-27T18:16:52","modified_gmt":"2024-06-27T16:16:52","slug":"preservare-il-vecchio-bagolaro-albero-simbolo-identitario-di-specchia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/27\/preservare-il-vecchio-bagolaro-albero-simbolo-identitario-di-specchia\/","title":{"rendered":"\u201cPreservare il vecchio bagolaro, albero simbolo identitario di Specchia\u201d"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"450\" class=\"wp-image-231091\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/unnamed.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/unnamed.png 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/unnamed-300x169.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/unnamed-768x432.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. Annalisa Ausilio di change.org ci manda il seguente comunicato _______&nbsp;<\/p>\n\n\n\n<p><em>Specchia (Lecce)&nbsp;<\/em>&#8211; Ha superato le 16 mila firme&nbsp;<a href=\"http:\/\/change.org\/SalviamoAlberoSpecchia\" target=\"_blank\" rel=\"noreferrer noopener\">la petizione lanciata sulla piattaforma online Change.org in difesa dell\u2019albero secolare al centro di Specchia<\/a>. Un gruppo di cittadini sensibili alle tematiche ambientali hanno costituito il \u2018Comitato Salviamo il Bagolaro\u2019 con il chiaro obiettivo di scongiurare l\u2019abbattimento di uno dei simboli del paese dopo una determina comunale che stabilisce l\u2019eradicazione della pianta per mettere in sicurezza l\u2019area.&nbsp;<\/p>\n\n\n\n<p><br>\u201cLa nostra \u00e8 una lotta contro il tempo &#8211; si legge nel testo dell\u2019appello &#8211; vogliamo sensibilizzare gli amministratori ad aprire un dialogo per vagliare ogni strada possibile\u201d. La mobilitazione per la salvaguardia dell\u2019albero centenario inizia tempo fa. \u201cDopo il cedimento di una porzione del muretto esterno e delle sottostanti strutture &#8211; spiegano i promotori &#8211; l\u2019amministrazione comunale ha chiuso la strada e sono state condotte analisi tecniche da un agronomo e un geologo. Risulterebbe che le relazioni dei due tecnici non arrivino ad un unanime parere sulla sorte della pianta\u201d.&nbsp;<\/p>\n\n\n\n<p>Di fronte al possibile abbattimento dell\u2019albero, \u00e8 iniziata nei mesi scorsi la mobilitazione dei cittadini che, dopo le prime rassicurazioni sul destino della pianta da parte dell\u2019Amministrazione, hanno appreso \u201clo scorso 21 Giugno la determina del tecnico comunale che stabilisce l\u2019abbattimento dell\u2019albero\u201d. Una decisione motivata dalla \u201cnecessit\u00e0 di messa in sicurezza ottimizzando le risorse economiche disponibili. Non sarebbero stati trovati fondi sufficienti per sistemare le strutture murarie e salvaguardare la pianta\u201d.<\/p>\n\n\n\n<p><br>Da qui l\u2019appello rivolto direttamente agli amministratori locali: \u201cvista l\u2019importanza storico culturale che l\u2019albero ha per il paese &#8211; continua la petizione &#8211; chiediamo una soluzione condivisa con la cittadinanza e le associazioni per garantire la sicurezza pubblica e, allo stesso, preservare il vecchio bagolaro, simbolo identitario di Specchia\u201d.<\/p>\n\n\n\n<p><a href=\"http:\/\/change.org\/SalviamoAlberoSpecchia\" target=\"_blank\" rel=\"noreferrer noopener\">Change.org\/SalviamoAlberoSpecchia&nbsp;<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/27\/preservare-il-vecchio-bagolaro-albero-simbolo-identitario-di-specchia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/27\/preservare-il-vecchio-bagolaro-albero-simbolo-identitario-di-specchia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Annalisa Ausilio di change.org ci manda il seguente comunicato _______&nbsp; Specchia (Lecce)&nbsp;&#8211; Ha superato le 16 mila firme&nbsp;la petizione lanciata sulla piattaforma online Change.org in difesa dell\u2019albero secolare al centro di Specchia. Un gruppo di cittadini sensibili alle tematiche ambientali hanno costituito il \u2018Comitato Salviamo il Bagolaro\u2019 con il chiaro obiettivo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":231091,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231090"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=231090"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231090\/revisions"}],"predecessor-version":[{"id":231093,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231090\/revisions\/231093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/231091"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=231090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=231090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=231090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}