{"id":231359,"date":"2024-07-05T15:21:35","date_gmt":"2024-07-05T13:21:35","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=231359"},"modified":"2024-07-05T15:21:38","modified_gmt":"2024-07-05T13:21:38","slug":"moda-mode-la-spesa-del-sabato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/05\/moda-mode-la-spesa-del-sabato\/","title":{"rendered":"MODA \/ MODE \u2013 LA SPESA DEL SABATO"},"content":{"rendered":"\n<p>di <strong>Elena Vada<\/strong> \u00a0______\u00a0<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"593\" height=\"443\" class=\"wp-image-231360\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/WCCOR1_0KOBENAF-018.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/WCCOR1_0KOBENAF-018.jpg 593w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/WCCOR1_0KOBENAF-018-300x224.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/WCCOR1_0KOBENAF-018-400x300.jpg 400w\" sizes=\"(max-width: 593px) 100vw, 593px\" \/><\/p>\n\n\n\n<p>Ogni &#8220;pranzo della domenica&#8221; \u00e8, quasi\u00a0 sempre, preceduto dalla spesa, del sabato mattina.<\/p>\n\n\n\n<p>Una intera famigliola: babbo, mamma e due bimbi (4\/5 anni), si addentrano in un grande e famoso Ipermercato. Una giungla di reparti, corsie, celle frigorifere, scomparti, banchi, dove sono esposti migliaia di prodotti.&nbsp;<\/p>\n\n\n\n<p>I nostri eroi dell&#8217; acquisto, vi si muovono con disinvoltura. Inizia il rito della spesa settimanale. Seguiamoli.<\/p>\n\n\n\n<p>Lei (Pia) &#8211; a lui &#8211; (Pierugo): &#8220;Ma non era meglio che tu restassi a casa con i bambini?! Guarda toccano tutto e riempiono il carrello di schifezze&#8230; &#8216;Luca, Paolo, state fermi, non toccate!&#8217;<\/p>\n\n\n\n<p>&nbsp;O,&#8230; sei venuto &#8216;per controllare&#8217;?&#8221; esclama titubante e perplessa Pia, guardando il marito, corrucciato.<\/p>\n\n\n\n<p>Pierugo: &#8220;Ma no cara, sono qui per aiutarti a caricare tutte le robe pesanti: sacco di patate, acqua minerale, bibite, detersivi, crocchette del cane&#8230; e il resto&#8230;&nbsp;<\/p>\n\n\n\n<p>Poi, rivolgendosi alla moglie, inquieto e irritato: &#8220;Nooo, non prendere questo, c&#8217;\u00e8 il 3&#215;2, guarda com&#8217;\u00e8 conveniente!<\/p>\n\n\n\n<p>&#8220;Non \u00e8 una marca di qualit\u00e0. Non \u00e8 quella che adopero io&#8230;<\/p>\n\n\n\n<p>&#8220;Ma che differenza c&#8217;\u00e8?!&nbsp;<\/p>\n\n\n\n<p>&#8220;C&#8217;\u00e8 che si compra quello che dico io e BASTA!<\/p>\n\n\n\n<p>&#8220;Ha ragione mia madre. Sei una spendacciona&#8230;<\/p>\n\n\n\n<p>&#8220;Sempre mammma!&#8230; &#8216;Mammina ha detto, mammina ha fatto. Fatti insegnare da mammina&#8217;. Che barba! Ti rendi conto che da otto anni, vivi con me e non pi\u00f9 con mammina tua!?<\/p>\n\n\n\n<p>&#8220;Ma ti fa comodo che tenga i bambini, di pomeriggio, dopo l&#8217;asilo!&nbsp;<\/p>\n\n\n\n<p>&#8220;Quante storie&#8230; Piuttosto, vai a prendere riso, biscotti, e pasta non &#8216;fascista&#8217;<\/p>\n\n\n\n<p>&#8220;Aspetta che leggo le etichette per vedere se ci sono farine solo italiane&#8230; niente grilli o cavallette. Ma sulla pasta fascista, c&#8217;\u00e8 la foto del Duce? Fammi capire qual \u00e8 &#8230;<\/p>\n\n\n\n<p>&#8220;\u00c8 la R&#8230;o, quella che piace a te<\/p>\n\n\n\n<p>&#8220;Ma vadano a quel paese i fascisti, i comunisti, i verdi, i gialli, eccetera, con le loro stupidate!<\/p>\n\n\n\n<p>&#8220;Gi\u00e0. Ma, accelera. Stiamo freschi se devi leggere tutte le etichette, ci mettiamo una settimana, per fare questa spesa.<\/p>\n\n\n\n<p>&#8220;Si, leggo tutte le etichette, per capire gli additivi, i grassi, gli edulcoranti e le scadenze.<\/p>\n\n\n\n<p>Pia, rivolta ai figli: &#8220;O comprate le patatine, o le barrette di cioccolato, o i gelati, o le merendine&#8230;<\/p>\n\n\n\n<p>Luca e Paolino: &#8220;Voglio le automobiline&#8230; Voglio i pennarelli. Voglio le pistola ad acqua&#8230; Voglio l&#8217; ovetto&#8230; &#8221;&nbsp;<\/p>\n\n\n\n<p>Mettono nel carrello, e i genitori tolgono.<\/p>\n\n\n\n<p>Pia: &#8220;L&#8217; erba voglio non cresce neanche nel giardino del re!&nbsp;<\/p>\n\n\n\n<p>PIERUGOOO, amoreee, non devi guardare trapano, tasselli, viti e quell&#8217;altra roba che mi hai detto???<\/p>\n\n\n\n<p>Il reparto &#8220;Bricolage&#8221; \u00e8 la in fondo&#8230;. Vai caro, Vai,Vai, Vaiii&#8230; e portati dietro i bambini.<\/p>\n\n\n\n<p>Ci troviamo, dopo, alle casse.<\/p>\n\n\n\n<p>E, prendi tu, l&#8217;acqua, le bibite e i succhi di frutta.<\/p>\n\n\n\n<p>Il trucco \u00e8 riuscito! Pia, trionfante, si avvia velocemente, al reparto surgelati, odiato da suo marito.<\/p>\n\n\n\n<p>Prende, al volo, le borse termiche, che serviranno al buon mantenimento dei prodotti, ma, soprattutto, li terranno celati agli occhi indiscreti di Pierugo, che li detesta.<\/p>\n\n\n\n<p>Dopo dieci minuti, eccoli, ritornare tutti e tre, come &#8216;desperados&#8217;: padre e bimbi, ridotti una schifezza. Piagnucolanti, imbrattati di cioccolato, gocciolanti morfello e alla disperata ricerca di un bagno, perch\u00e9 scappa pure la pip\u00ec. Un disastro!<\/p>\n\n\n\n<p>&#8220;Ecco mamma, finalmente!<\/p>\n\n\n\n<p>&#8211; Piaaa, siamo qui &#8211; urla Pierugo &#8211; Portali in bagno, a lavare le manine&#8221;<\/p>\n\n\n\n<p>Intanto, approfittando dell&#8217; assenza della moglie, lui d\u00e0 una sbirciatina al contenuto del carrello e visti i surgelati, s&#8217;inquieta moltissimo e l&#8217; aspetta al varco.<\/p>\n\n\n\n<p>&#8220;Surgelati eh?! Tutte porcherie. Chiss\u00e0 cosa c&#8217;\u00e8 dentro. Chi li ha fatti. Come sono fatti. Dove li hanno fatti.<\/p>\n\n\n\n<p>Tu, figlia di una leccese, che prepara tutto a mano, tutto genuino, ci fai mangiare queste schifezze.<\/p>\n\n\n\n<p>Pia: &#8220;E si, alle sera alle sette, quando rientro da lavoro, mi metto in cucina a farvi leccornie.<\/p>\n\n\n\n<p>Orecchiette con le cime di rapa, magari.<\/p>\n\n\n\n<p>Ancora grazie, se ho la forza di mettere un surgelato nel microonde.<\/p>\n\n\n\n<p>L&#8217; alternativa \u00e8 il minestrone piemontese, di tua madre&#8230; ogni sera, tutte le sere!<\/p>\n\n\n\n<p>Pierugo: &#8220;Ma, almeno \u00e8 GENUINO!<\/p>\n\n\n\n<p>Pia: &#8220;Vabb\u00e8, penso di aver preso tutto. Prepariamo la Carta di Credito per il &#8216;salasso&#8217;.<\/p>\n\n\n\n<p>Domani pasta al sugo, arrosto al forno con patate, una buona insalatina e la torta di mele.<\/p>\n\n\n\n<p>Pierugo: &#8220;Ma domani, c&#8217;\u00e8 il &#8216;pranzo della domenica&#8217; da mamma. Ci saranno anche mio fratello e mia cognata, con i bambini. Mia madre far\u00e0: acciughe al verde, agnolotti in brodo e bollito di manzo.<\/p>\n\n\n\n<p>Pia: &#8220;Che novit\u00e0! Il solito men\u00f9, insomma! Sono dieci anni che ci cucina le stesse cose. Con la, saltuaria, variante del risotto ai fegatini e le uova sode ripiene. Ma domani c&#8217;\u00e8 tuo fratello, il suo preferito&#8230; forse ci far\u00e0 gallina ruspante&#8230; lessa, ovvio.<\/p>\n\n\n\n<p>&#8220;E dai, tra un po&#8217; scenderemo nel Salento, dai tuoi genitori e allora sar\u00e0 &#8220;Pranzo della domenica&#8221; tutti i giorni. Scommetto che tua madre, ha gi\u00e0 cominciato a cucinare&#8221;.<\/p>\n\n\n\n<p>&#8220;Credo di s\u00ec&#8230; ed io mi sogno: linguine ai frutti di mare, ciceri e tria, tajeddrha, turcinieddrhi e pasticciotti.<\/p>\n\n\n\n<p>Pierugo: &#8220;Arabo, arabo, parlate e mangiate arabo, al tuo paese&#8230; e devo ingoiare tutto, se no tua madre si offende&#8221;<\/p>\n\n\n\n<p>Pia: &#8220;Ma se divori tutti i piatti mugolando di gusto e fai pure la &#8216;scarpetta&#8217;!<\/p>\n\n\n\n<p>Del resto, al ritorno dalle ferie, potrai mangiare minestrone e bollito tutto l&#8217;anno&#8221;.<\/p>\n\n\n\n<p>Si avviano alle casse. L&#8217; indomani ci sar\u00e0 il &#8216;pranzo tradizionale&#8217; con la famiglia e non importa, quali siano le ricette preparate.<\/p>\n\n\n\n<p>Saranno seduti a tavola, per mangiare, chiacchierare, discutere e, a volte, per aggiustare situazioni.&nbsp;<\/p>\n\n\n\n<p>Per volersi bene e ricordare che &#8216;stare insieme&#8217; \u00e8 bello!<\/p>\n\n\n\n<p>Al Nord, come al Sud, intorno a buoni cibi italiani, con parenti e amici&#8230; in armonia e allegria.\u00a0<\/p>\n\n\n\n<p>Quindi: buona domenica e buon appetito a tutti!<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/05\/moda-mode-la-spesa-del-sabato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/05\/moda-mode-la-spesa-del-sabato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Elena Vada \u00a0______\u00a0 Ogni &#8220;pranzo della domenica&#8221; \u00e8, quasi\u00a0 sempre, preceduto dalla spesa, del sabato mattina. Una intera famigliola: babbo, mamma e due bimbi (4\/5 anni), si addentrano in un grande e famoso Ipermercato. Una giungla di reparti, corsie, celle frigorifere, scomparti, banchi, dove sono esposti migliaia di prodotti.&nbsp; I nostri eroi dell&#8217; acquisto, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":231360,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231359"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=231359"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231359\/revisions"}],"predecessor-version":[{"id":231361,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231359\/revisions\/231361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/231360"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=231359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=231359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=231359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}