{"id":231498,"date":"2024-07-08T14:05:34","date_gmt":"2024-07-08T12:05:34","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=231498"},"modified":"2024-07-08T16:49:36","modified_gmt":"2024-07-08T14:49:36","slug":"operazione-della-finanza","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/08\/operazione-della-finanza\/","title":{"rendered":"OPERAZIONE DELLA FINANZA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1920\" height=\"919\" class=\"wp-image-231499\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/08072024_091245_08.07.2024-ecotassa-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/08072024_091245_08.07.2024-ecotassa-1.jpg 1920w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/08072024_091245_08.07.2024-ecotassa-1-300x144.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/08072024_091245_08.07.2024-ecotassa-1-1024x490.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/08072024_091245_08.07.2024-ecotassa-1-768x368.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/08072024_091245_08.07.2024-ecotassa-1-1536x735.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n\n\n\n<p>(e.l.) _______\u00a0\u00a0Lo scorso mese di gennaio i Finanzieri del Gruppo Taranto avevano individuato un autotrasportatore intento a scaricare su un fondo agricolo del comune di Faggiano materiale edile di risulta del peso complessivo di circa sette tonnellate.<\/p>\n\n\n\n<p>Verificata l\u2019illiceit\u00e0 di tale condotta, il conducente del mezzo era stato denunciato a piede liber . con il contestuale sequestro dell\u2019area e dei rifiuti illecitamente depositati.<\/p>\n\n\n\n<p>Adesso, Aall\u2019esito dei conseguenti approfondimenti amministratibi, \u00e8 stata constatata l\u2019evasione dell\u2019ecotassa per un importo complessivo di oltre 70 mila euro.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/08\/operazione-della-finanza\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/08\/operazione-della-finanza\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) _______\u00a0\u00a0Lo scorso mese di gennaio i Finanzieri del Gruppo Taranto avevano individuato un autotrasportatore intento a scaricare su un fondo agricolo del comune di Faggiano materiale edile di risulta del peso complessivo di circa sette tonnellate. Verificata l\u2019illiceit\u00e0 di tale condotta, il conducente del mezzo era stato denunciato a piede liber . con il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":231499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231498"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=231498"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231498\/revisions"}],"predecessor-version":[{"id":231500,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231498\/revisions\/231500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/231499"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=231498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=231498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=231498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}