{"id":23170,"date":"2014-01-05T12:10:24","date_gmt":"2014-01-05T12:10:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23170"},"modified":"2014-01-05T12:11:09","modified_gmt":"2014-01-05T12:11:09","slug":"calendario-2014-moda-e-arte","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/05\/calendario-2014-moda-e-arte\/","title":{"rendered":"CALENDARIO 2014 MODA E ARTE"},"content":{"rendered":"<p>Il calendario realizzato dalla stilista Daniela Melcore \u00e8 in distribuzione. Quanti sono interessati possono rivolgersi al Centro Ascolto Donna, oppure ritirarli presso la nostra redazione.<\/p>\n<p>Il ricavato sar\u00e0 completamente devoluto a favore dell&#8217;Associazione Giovanile Thalassemici della provincia di Lecce.<a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/CALENDARIO-2014-MODA.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/CALENDARIO-2014-MODA-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-23171\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/05\/calendario-2014-moda-e-arte\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/05\/calendario-2014-moda-e-arte\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il calendario realizzato dalla stilista Daniela Melcore \u00e8 in distribuzione. Quanti sono interessati possono rivolgersi al Centro Ascolto Donna, oppure ritirarli presso la nostra redazione. Il ricavato sar\u00e0 completamente devoluto a favore dell&#8217;Associazione Giovanile Thalassemici della provincia di Lecce.<\/p>\n","protected":false},"author":4,"featured_media":23171,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23170"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23170"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23170\/revisions"}],"predecessor-version":[{"id":23175,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23170\/revisions\/23175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/23171"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}