{"id":231904,"date":"2024-07-19T16:58:07","date_gmt":"2024-07-19T14:58:07","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=231904"},"modified":"2024-07-20T19:09:22","modified_gmt":"2024-07-20T17:09:22","slug":"luniversita-di-torino-denuncia-il-massiccio-impiego-nonostante-i-divieti-dei-pesticidi-in-agricoltura-e-ne-documenta-gli-effetti-devastanti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/19\/luniversita-di-torino-denuncia-il-massiccio-impiego-nonostante-i-divieti-dei-pesticidi-in-agricoltura-e-ne-documenta-gli-effetti-devastanti\/","title":{"rendered":"L\u2019UNIVERSITA\u2019 DI TORINO DENUNCIA IL MASSICCIO IMPIEGO, NONOSTANTE I DIVIETI, DEI PESTICIDI IN AGRICOLTURA E NE DOCUMENTA GLI EFFETTI DEVASTANTI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1000\" class=\"wp-image-231908\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/Pestizidbild1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/Pestizidbild1.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/Pestizidbild1-300x188.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/Pestizidbild1-1024x640.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/Pestizidbild1-768x480.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/Pestizidbild1-1536x960.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. L\u2019Universit\u00e0 di Torino ci manda il seguente comunicato _______&nbsp;<\/p>\n\n\n\n<p><strong>I PESTICIDI UTILIZZATI PER L\u2019EMERGENZA AGRICOLA SONO ALTAMENTE TOSSICI PER API, AMBIENTE E SALUTE UMANA<\/strong><\/p>\n\n\n\n<p><em>Una ricerca pubblicata su Science of the Total Environment e coordinata da Simone Tosi, docente del Dipartimento di Scienze Agrarie, Forestali e Alimentari dell\u2019Universit\u00e0 di Torino, dimostra che pesticidi non approvati a causa del loro impattosulla salute umana e sull\u2019ambiente vengono frequentemente autorizzati in via \u201cemergenziale\u201d, causando alti rischi<\/em><\/p>\n\n\n\n<p>Una&nbsp;<strong>studio&nbsp;<\/strong>appena pubblicato su&nbsp;<a href=\"https:\/\/email.tmg.vrfy.email\/c\/eJxEz0GOrCAQgOHTwJJQVTTIgsXbeI0OFqXNi0pHiMnM6Sc9mznB__0lsUMJWhIEBJrIE2k5ct2f_S2lftd2SqKYnTzCQqCcPfrm0RxSai7lkt5NHfqVlnUiFn5YjjFG7_PqHT5oKgw5IwddE1p0NkAEawOQEQuCkQqJXwidV86OYzP3tX6ZX4Le02uMd1f0T-GscC6tmnZtCmewBix4hfN_07mONuS8zSdgIDiEoK9Uz7UpZ3dhFr7amTl_qH9fz1oSAgA5PZK-E_4EAAD__0fFUL8\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Science of the Total Environment<\/strong><\/a>, condotto dal&nbsp;<a href=\"https:\/\/email.tmg.vrfy.email\/c\/eJxEzzluwzAQAMDXkCWxB0VKBYs0-obBY20voMOQGAvJ64OkyQ9mWqqeJFpJGAl55MBsZc263M6XNP3WfZPEU_YyxMJoPKznI5BbpWlu7ZDzdNrtM0EeScZhKBUkFqwU0beKIY6hZIbRaiIgDxEnBIjITgCFJm4soTD5YDz09eHex_3L_RHskp69v07DH4ZmQ_N1Xa6ILLm4z0377rQbmrXbI-l2342HRWqVeuxbrvnX9Z-4aUuEiOxtT_ad6CcAAP__419NBA\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>BeeLab<\/em><\/strong><\/a>, il Laboratorio sulla Salute e sul Comportamento degli Impollinatori coordinato dal Prof.&nbsp;<strong>Simone Tosi<\/strong><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"1000\" class=\"wp-image-231907\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/252152875_1002457040332929_1704116999942147006_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/252152875_1002457040332929_1704116999942147006_n.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/252152875_1002457040332929_1704116999942147006_n-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/252152875_1002457040332929_1704116999942147006_n-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/252152875_1002457040332929_1704116999942147006_n-768x768.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/252152875_1002457040332929_1704116999942147006_n-60x60.jpg 60w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\n\n\n<p>docente del&nbsp;<strong>Dipartimento di Scienze Agrarie, Forestali e Alimentari&nbsp;<\/strong>dell\u2019<strong>Universit\u00e0 di Torino<\/strong>, ha investigato sull\u2019utilizzo di autorizzazioni emergenziali \u201cin deroga\u201d dei pesticidi e sui conseguenti effetti collaterali per la salute umana, degli impollinatori e dell\u2019ambiente intero.<\/p>\n\n\n\n<p>I pesticidi autorizzati in deroga possono essere utilizzati indipendentemente dal risultato negativo del processo di Valutazione del Rischio, che include una serie di test sperimentali necessari a stimare la contaminazione ambientale e gli effetti collaterali di questi prodotti, valutandone infine l\u2019impatto per l\u2019uomo e l\u2019ambiente. Tali autorizzazioni in deroga dei pesticidi permettono quindi di controllare emergenze agricole sorvolando sui danni collaterali causati. Vi sono perci\u00f2 dei limiti: tali deroghe possono solo essere concesse per emergenze circoscritte nel tempo e nello spazio.<\/p>\n\n\n\n<p>\u201c<em>L&#8217;Unione Europea regola l\u2019autorizzazione dei pesticidi attraverso il processo di Valutazione del Rischio con lo scopo inderogabile di salvaguardare la salute dell\u2019uomo e dell\u2019ambiente<\/em>\u201d racconta il Prof.&nbsp;<strong>Simone Tosi<\/strong>, coordinatore della ricerca.&nbsp;<strong>Luca Carisio&nbsp;<\/strong>dell\u2019Istituto Zooprofilattico Sperimentale del Piemonte Liguria e Valle d&#8217;Aosta e primo autore dello studio, continua: \u201c<em>Tuttavia, gli Stati Membri possono agire in deroga a questo processo e concedere l&#8217;Autorizzazione d\u2019Emergenza di pesticidi non autorizzati tramite la Valutazione del Rischio. Per gli elevati rischi connessi, queste Autorizzazioni d\u2019Emergenza sono permesse solo in circostanze eccezionali di emergenza agricola. Il loro uso deve per\u00f2 essere limitato: le deroghe non possono essere pi\u00f9 lunghe di 120 giorni, e devono essere svolte ricerche simultanee sulle strategie alternative e pi\u00f9 sostenibili<\/em>.\u201d<\/p>\n\n\n\n<p>Questa prima valutazione scientifica approfondita dei processi di Autorizzazione d\u2019Emergenza dimostra come siano ampiamente utilizzati dai Paesi Membri dell\u2019Unione Europea. Tuttavia, molte di queste autorizzazioni emergenziali risultano sorprendentemente non conformi alle normative UE, poich\u00e9 concesse per periodi pi\u00f9 lunghi di quanto prescritto dalla legge e rinnovate in modo ricorrente per gestire la stessa emergenza nel tempo. Inoltre, il&nbsp;<strong>21%<\/strong>&nbsp;di queste autorizzazioni ha permesso l&#8217;uso di pesticidi altamente tossici, che non sono approvati dai processi regolari di Valutazione del Rischio.<\/p>\n\n\n\n<p>\u201c<em>Il nostro studio dimostra che l&#8217;ampio uso delle Autorizzazioni d\u2019Emergenza nel tempo e nello spazio porta alla contaminazione ambientale da parte di numerose sostanze attive non approvate e altamente tossiche<\/em>\u201d dichiara il  \u201c<em>Viviamo in uno stato di stabile emergenza agricola che agisce in deroga al Regolamento Europeo, con profonde implicazioni per gli esseri umani, gli altri animali e l&#8217;ambiente.<\/em>&nbsp;<em>Questa ricerca ha l\u2019obiettivo di contribuire allo sviluppo di un ambiente e di un&#8217;agricoltura pi\u00f9 sostenibili e sicuri per gli esseri umani e gli altri animali\u201d.<\/em><\/p>\n\n\n\n<p>L&#8217;uso prolungato delle Autorizzazioni d\u2019Emergenza e il limitato sviluppo di alternative sollevano preoccupazioni sulla sostenibilit\u00e0 delle pratiche agricole ed i relativi impatti sulla salute a lungo termine. \u201c<em>La nostra ricerca intende facilitare l&#8217;implementazione di strategie di controllo sostenibili perch\u00e9 il nostro ambiente diventi pi\u00f9 sano e sicuro; infatti, abbiamo descritto le emergenze agricole pi\u00f9 frequenti e quindi le ricerche da prioritizzare<\/em>\u201d spiega&nbsp;<strong>Luca Carisio<\/strong>.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"225\" class=\"wp-image-231906\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/download-2.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/download-2.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/download-2-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/download-2-60x60.jpg 60w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n\n\n\n<p>Link all\u2019articolo&nbsp;<a href=\"https:\/\/email.tmg.vrfy.email\/c\/eJxEz0GOrCAQgOHTwJJQVTTIgsXbeI0OFqXNi0pHiMnM6Sc9mznB__0lsUMJWhIEBJrIE2k5ct2f_S2lftd2SqKYnTzCQqCcPfrm0RxSai7lkt5NHfqVlnUiFn5YjjFG7_PqHT5oKgw5IwddE1p0NkAEawOQEQuCkQqJXwidV86OYzP3tX6ZX4Le02uMd1f0T-GscC6tmnZtCmewBix4hfN_07mONuS8zSdgIDiEoK9Uz7UpZ3dhFr7amTl_qH9fz1oSAgA5PZK-E_4EAAD__0fFUL8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/j.scitotenv.2024.174217<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/19\/luniversita-di-torino-denuncia-il-massiccio-impiego-nonostante-i-divieti-dei-pesticidi-in-agricoltura-e-ne-documenta-gli-effetti-devastanti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/19\/luniversita-di-torino-denuncia-il-massiccio-impiego-nonostante-i-divieti-dei-pesticidi-in-agricoltura-e-ne-documenta-gli-effetti-devastanti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. L\u2019Universit\u00e0 di Torino ci manda il seguente comunicato _______&nbsp; I PESTICIDI UTILIZZATI PER L\u2019EMERGENZA AGRICOLA SONO ALTAMENTE TOSSICI PER API, AMBIENTE E SALUTE UMANA Una ricerca pubblicata su Science of the Total Environment e coordinata da Simone Tosi, docente del Dipartimento di Scienze Agrarie, Forestali e Alimentari dell\u2019Universit\u00e0 di Torino, dimostra [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":231908,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,31,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231904"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=231904"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231904\/revisions"}],"predecessor-version":[{"id":231937,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231904\/revisions\/231937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/231908"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=231904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=231904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=231904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}