{"id":231909,"date":"2024-07-19T17:48:27","date_gmt":"2024-07-19T15:48:27","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=231909"},"modified":"2024-07-21T08:10:27","modified_gmt":"2024-07-21T06:10:27","slug":"borsellino-tanti-giovani-per-non-dimenticare-resta-il-fatto-pero-che-dopo-32-anni-dalla-strage-ci-sono-ancora-buchi-nei-57-giorni","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/19\/borsellino-tanti-giovani-per-non-dimenticare-resta-il-fatto-pero-che-dopo-32-anni-dalla-strage-ci-sono-ancora-buchi-nei-57-giorni\/","title":{"rendered":"BORSELLINO: TANTI GIOVANI PER NON DIMENTICARE, RESTA PERO&#8217; IL FATTO CHE DOPO 32 ANNI DALLA STRAGE CI SONO ANCORA &#8220;BUCHI&#8221; NEI 57 GIORNI."},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2000\" height=\"1333\" class=\"wp-image-231911\" style=\"width: 900px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/borsellino-via-damelio-mafia-melcore-leccecronaca.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/borsellino-via-damelio-mafia-melcore-leccecronaca.jpg 2000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/borsellino-via-damelio-mafia-melcore-leccecronaca-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/borsellino-via-damelio-mafia-melcore-leccecronaca-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/borsellino-via-damelio-mafia-melcore-leccecronaca-768x512.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/borsellino-via-damelio-mafia-melcore-leccecronaca-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>Melcore Valerio______Tantissimi i giovani che oggi si sono riuniti sotto l&#8217;albero di Paolo Borsellino in via D&#8217;Amelio a Palermo, per ricordare l&#8217;eroismo di quest&#8217;uomo e della sua scorta. Per ricordare le stragi che hanno insanguinato la bellissima citt\u00e0 siciliana e dire NO ALLA MAFIA.<br>Per altro verso  per\u00f2 non possiamo non ricordare da\u00a0<strong>32 anni<\/strong>\u00a0aspettiamo che la verit\u00e0 venga a galla, le ferite inferte alla nostra nazione dalle\u00a0<strong>stragi del 23 maggio e 19 luglio<\/strong> non si sono mai rimarginate.  Da decenni i familiari delle vittime denunciano i depistaggi avvenuti ad opera di coloro che avrebbero dovuto scoprire la verit\u00e0. Domande che i familiari e insieme a loro tutto il paese pone da 32 anni e che non trovano risposte. Eppure come scrive l&#8217;agenzia di stampa AGI le:  &#8220;tracce&#8221; le abbiamo, talvolta sta solo nel volerle leggere e metterle a sistema. Basti pensare che solo nell&#8217;ultimo anno abbiamo avuto contezza di una riunione alla quale il dottor Paolo Borsellino partecipo&#8217; nell&#8217;ultimo periodo della sua vita. E c\u2019\u00e8 da domandarsi come sia possibile che, ancora, ci siano momenti non investigati adeguatamente in quei 57 giorni che separano Capaci da Via D&#8217;Amelio&#8221;.<br>Poi vi sono le polemiche. Salvatore Borsellino rimprovera a Maria Falcone l&#8217;utilizzo politico delle manifestazioni in ricordo del fratello. Ma questo lo si comprende, basti pensare, come ricorda in un&#8217;intervista rilasciata al sottoscritto il socialista Claudio Martelli, all&#8217;epoca dei fatti Ministro di Grazia e Giustizia, che Falcone e Borsellino furono ferocemente osteggiati dal Partito Comunista, poi dopo la loro morte sono stati proprio i comunisti, oggi nel PD, che cercano di intestarsi le battaglie contro la mafia.<br>Leccecronaca.it vuole anch&#8217;essa, nel suo piccolo, vuole rendere omaggio a questi eroi dei giorni nostri e lo facciamo riproponendo un articolo di qualche anno fa che ci ricorda che la mafia si combatte anche attraverso i nostri gesti quotidiani, comportamenti legati alla capacit\u00e0 di dire ogni tanto NO. No! non sono disposto a questo compromesso, no! non sono disposto a sottomettermi in maniera vergognosa per avere il mio piccolo tornaconto.<\/p>\n\n\n\n<p>IN RICORDO DI PAOLO BORSELLINO E GIOVANNI FALCONE<\/p>\n\n\n\n<p><em>\u201c Questa sera alle ore 18:30 La Lista Civica Il Cavaliere aprir\u00e0 la campagna elettorale sul tema: la Mafia nel nostro paese\u201d<\/em>, e poi il ritornello rafforzativo,&nbsp;<em>\u201d ore 18:30 per la Lista il Cavaliere parler\u00e0 Valerio Melcore\u201d<\/em>.<br>Era un sabato di 29 anni fa, il magistrato Giovanni Falcone saltava in aria insieme alla moglie Francesca Morvillo e a tre uomini della scorta Rocco Dicillo, Vito Schifani ed il \u201cnostro\u201d&nbsp; Antonio Montinaro.<br>La notizia era appena stata data, quando io mi accingevo a tenere un comizio nella piazza di Cavallino, un comune alle porte di Lecce, &nbsp;per le elezioni amministrative.<br>L\u2019auto aveva girato tutto il giorno per annunciare che la lista che capeggiavo avrebbe aperto la campagna elettorale, una lista civica espressione di un circolo culturale.<\/p>\n\n\n\n<p>Il 23 maggio 1992, alle ore 17:58 gli uomini di Cosa Nostra schiacciarono il tasto del telecomando che azion\u00f2 &nbsp;il meccanismo collegato al tritolo, &nbsp;posto sotto quel tratto di strada che conduceva a Capaci, nel momento in cui la macchina del giudice transitava in quel luogo.<\/p>\n\n\n\n<p>Falcone, un uomo lasciato solo, dallo Stato italiano, &nbsp;a combattere la mafia.<br>Continuer\u00e0 la sua battaglia, un suo amico fraterno, Paolo Borsellino, dimostrando un coraggio da leone, il quale&nbsp;pur essendo consapevole di non poter contare sulle istituzioni, &nbsp;sapendo che, &nbsp;come lui stesso ebbe a sostenere, era un morto che camminava, prosegu\u00ec per la sua strada.&nbsp;A distanza di poco tempo dalla morte del suo amico, &nbsp;fecero saltare in aria anche lui. Una macchina imbottita di esplosivo fu parcheggiata sotto casa della madre che lui andava a trovare tutti i giorni.<\/p>\n\n\n\n<p>Due giudici, due amici fraterni, uniti nella vita e nella morte, due uomini che dichiaravano apertamente simpatie politiche differenti uno di destra &nbsp;e l\u2019altro di sinistra, il missino e il socialista, e di questo ne ridevano e ci scherzavano su senza che ci\u00f2 incrinasse la loro amicizia il loro modo di intendere la lotta &nbsp;alla mafia.<br>Anche in queste piccole cose questi due uomini hanno tanto da insegnarci.<\/p>\n\n\n\n<p>Non so se il loro eroico comportamento, il loro sacrificio sia servito per combattere la mafia, ce lo dovrebbero dire gli addetti ai lavori, certamente \u00e8 servito a noi cittadini per farci capire che gli Italiani, non sono tutti disponibili ai piccoli e grandi compromessi, e che se \u00e8 capitato a loro di essere isolati prima, e uccisi dopo, non ci dobbiamo meravigliare se anche a noi nel nostro piccolo vengono riservati ostracismi, tentativi di isolamento e discredito, quando ci opponiamo a quei comportamenti \u201dmafiosi\u201d messi in campo in casa nostra dai potentati economici locali e dai loro servitori politici.<br>Spesso noi cittadini siamo convinti che siano i politici a comandare &nbsp;gli imprenditori, ma invece \u00e8 esattamente il contrario, specie quando si tratta di imprenditoria assistita.<\/p>\n\n\n\n<p>Il sacrificio di questi nostri connazionali, il loro esempio in vita e, nel caso di Borsellino, anche la capacit\u00e0 di affrontare la morte annunciata, sono degli esempi &nbsp;che ci fanno sentire orgogliosi di appartenere a questo popolo, mentre tutti i giorni la classe politica, quella delle ipocrite commemorazioni ci fa vergognare di essere italiani.<\/p>\n\n\n\n<p>Per cui se loro arrivarono a perdere il bene pi\u00f9 prezioso, la vita, allora ognuno di noi pu\u00f2 donare un p\u00f2 del suo tempo, della sua energia e del suo denaro per cercare di migliorare la societ\u00e0 in cui viviamo e in cui vivranno probabilmente i nostri figli.<\/p>\n\n\n\n<p>Il loro sacrifico a tanti italiani ha dato la forza di andare avanti, quando si sono combattute battaglie contro il malcostume politico e non era raro sentirsi ripetere:&nbsp;<em>\u201d ma chi te lo fa fare, ci rimetti e basta, nessuno ti ringrazier\u00e0 per quello che fai, ti farai solo nemici\u201d<\/em>, quando tutti ti &nbsp; invitavano a fare appello al buon senso, pensando ai due Magistrati, trovavi la forza e le motivazioni per andare avanti per la tua strada a testa bassa, magari pagando alla fine il tuo piccolo conticino, dovendo affrontare un processo per diffamazione, con il tuo conto in banca che si riduceva.<br>Ma ce lo ricordiamo il giorno in cui avvenne quell\u2019orribile tragedia, ve lo ricordate, io si?<\/p>\n\n\n\n<p>Ripercorrendo quei momenti, mi sembra di risentire la voce dei miei amici e sostenitori che strillavano dal microfono dell\u2019altoparlante. L\u2019emozione era tanta, sapevamo di essere soli contro tutti, contro tutti i partiti, che in quel Comune per una strana alchimia i cui elementi e la cui combinazione in quel momento non comprendevamo, erano tutti d\u2019accordo, partiti di destra e di sinistra, tutti d\u2019accordo nella realizzazioni di grandi opere inquinanti o di strutture che avrebbero impoverito il nostro territorio.<\/p>\n\n\n\n<p>Invece &nbsp;i cittadini che ci davano ragione erano tanti, venivano di nascosto a darci attestati di stima, ci incoraggiavano a fare quelle battaglie che erano sacrosante, ma ci confessavano anche, candidamente, che non ci avrebbero votato, a causa del solito ricatto occupazionale e della capacit\u00e0 dei partiti, vera o presunta, di controllare ogni singolo voto.<\/p>\n\n\n\n<p>Erano le 18:30 ero appena salito sul palco, Daniele Casilli, uno dei ragazzi della lista, improvvis\u00f2 una presentazione, e siccome era notorio che le altre liste avrebbero aperta la campagna elettorale, con personaggi in vista, chi con il senatore x, chi con il deputato y, l\u2019amico a dimostrazione del fatto che non avevamo padrini e padroni, come recitava il nostro slogan, ironicamente inizi\u00f2 \u201c il nostro deputato purtroppo si \u00e8 perso per strada cari concittadini per cui vi dovete accontentarvi del nostro capolista, che voi tutti conoscete\u201d.<\/p>\n\n\n\n<p>Dato che il tutto era improvvisato, ero cos\u00ec attento ad ascoltare cosa diceva chi mi presentava, che quando trafelata arriv\u00f2 davanti al palco Giovanna, la moglie di Sergio Lettere, un altro nostro candidato, gli feci segno di non disturbare, ma lei insistette &nbsp;mi chiese di abbassarmi mi si avvicin\u00f2 e senti confusamente:<em>\u201cFalcone, Falcone con la moglie\u2026l\u2019 hanno fatto saltare \u201c io che dicevo Falcone chi? \u2013 il Giudice Falcone, l\u2019hanno detto il televisione, dillo Valerio la mafia ha ucciso Falcone con la moglie\u201d<\/em>&nbsp; in quel momento non ebbi n\u00e9 il tempo per capire, cosa mi stesse dicendo di preciso la mia amica e se anche avessi compreso, forse l\u00ec per l\u00ec non avrei saputo cosa dire, di quanto era accaduto in Sicilia, in quel momento &nbsp;la Mafia con la M maiuscola mi sembrava cos\u00ec lontana, cos\u00ec distante dalla nostra piccola battaglia, quella contro la mafia dei partiti e dei potentati economici locali.<br>Intanto l\u2019amico al microfono si accingeva a darmi la parola, mentre Giovanna tentava di informarmi, Daniele, l\u2019improvvisato presentatore dopo aver pi\u00f9 volte ripetuto:&nbsp;<em>\u201ce ora lascio la parola a Valerio Melcore\u2026e ora la parola a Valerio Melcore\u201d<\/em>, guardandomi dall\u2019alto mentre io piegato su un ginocchio ascoltavo Giovanna, che&nbsp; con le parole ma soprattutto con la concitazione dei gesti cercava di farmi capire la gravit\u00e0 dell\u2019accaduto,&nbsp;Daniele&nbsp;ignaro di ci\u00f2 che avveniva al bordo del palco, dopo che per la terza volta aveva ripetuto che mi cedeva la parola, preso dallo sconforto, continu\u00f2:<em>\u201d cari concittadini stasera ci siamo giocati prima l\u2019onorevole che si \u00e8 perso per strada e adesso pure il capolista che si \u00e8 inginocchiato davanti a questa bella signora, e pare proprio che non mi ascolti\u201d<\/em>&nbsp;, fu cos\u00ec che Piero Linciano che era la mia destra mi stratton\u00f2, presi la parola e tenni il comizio come previsto. Non feci cenno della morte di Falcone com\u2019era giusto che fosse.<\/p>\n\n\n\n<p>Quella campagna elettorale ci port\u00f2 in Consiglio comunale, cinque anni di opposizione durissima, caratterizzati da lusinghe prima e minacce poi, trascurammo lavoro e tempo libero, pagando pesantemente di tasca nostra il piacere di poter liberamente dire quanto pensavamo, e di dare voce a chi non poteva o non voleva esporsi.<br>Questo ci diede anche la consapevolezza che volere \u00e8 potere, che credere che certe battaglie si possano fare e vincere \u00e8 possibile e che \u00e8 anche possibile dimostrare ai cittadini che &nbsp;fare politica in modo diverso si pu\u00f2.<\/p>\n\n\n\n<p>Molti mi chiedono se \u00e8 servito a qualcosa, tutto quel tempo, quell\u2019energia, quel denaro che io e i miei amici abbiamo speso per cercare di rendere il nostro paese migliore, mentre i partiti, tutti i partiti, si spartivano la torta.<\/p>\n\n\n\n<p>Ha avuto un senso visto che non ho fatto carriera politica e non ho avuto alcun ritorno economico o professionale?<\/p>\n\n\n\n<p>La risposta \u00e8 certamente SI!<\/p>\n\n\n\n<p>Quando abbiamo capito la portata delle battaglie combattute anche all\u2019interno delle istituzioni da uomini come Falcone, abbiamo compreso che anche le nostre piccole battaglie avevano un senso, perch\u00e9 aiutavano la comunit\u00e0 a prendere coscienza della realt\u00e0 che viveva, ma soprattutto \u00e8 servito per la consapevolezza che cresceva in noi quando subivamo attacchi ingiustificati, quando tentavano di renderci ridicoli, ma sopratutto di isolarci, a volte anche riuscendoci.<br>Allora quando ascolti frasi come:&nbsp;<em>\u201d la mafia prima ti isola e poi ti uccide<\/em>\u201c, comprendi davvero cosa vuol dire, se sulla tua pelle hai subito quell\u2019isolamento. Comprendi i meccanismi, l\u2019amico che fino al giorno prima prendeva il caff\u00e8 con te e si fermava a chiacchierare, dopo che hai iniziato una certa battaglia, ti accorgi che quando l\u2019incontri ha sempre un impegno urgente, che quell\u2019altro amico fa finta di non vederti si gira dall\u2019altra parte per non esporsi non far vedere che condivide le tue battaglie.<\/p>\n\n\n\n<p>E dover prendere atto che mentre tu tentavi di mettere insieme semplici cittadini, per renderli liberi dalla paura, per tentare di trasformarli da sudditi in cittadini attivi, dall\u2019altra parte c\u2019erano importanti uomini delle istituzioni di destra e di sinistra, o uomini del clero che rendevano omaggio pubblicamente al ras locale.<br>Tutto ci\u00f2 ti rende consapevole della societ\u00e0 e del tempo in cui vivi e capisci che la mafia non \u00e8 una parola lontana che riguarda la Sicilia e non c\u2019\u00e8 la piccola e la grande mafia, ma ci sono comportamenti mafiosi, che generano atteggiamenti omertosi che solo una cittadinanza attiva pu\u00f2 impedire che crescano e che nel tempo abbiano a &nbsp;ripetersi.<br>Certo \u00e8 dura, ma cambiare si pu\u00f2, cambiare soprattutto si deve.<br>Ci vuole costanza e, le persone giuste, i giusti tempi.<\/p>\n\n\n\n<p>Non \u00e8 facile, ma oggi sicuramente \u00e8 pi\u00f9 facile di ieri.______<\/p>\n\n\n\n<p>(Nella foto il nostro Direttore Editoriale Valerio Melcore in via D\u2019Amelio dove si \u00e8 recato per un doveroso omaggio al Giudice Paolo Borsellino. L&#8217;articolo \u00e8 stato pubblicato su <strong>leccecronaca.it<\/strong> nel 2015).<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/19\/borsellino-tanti-giovani-per-non-dimenticare-resta-il-fatto-pero-che-dopo-32-anni-dalla-strage-ci-sono-ancora-buchi-nei-57-giorni\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/19\/borsellino-tanti-giovani-per-non-dimenticare-resta-il-fatto-pero-che-dopo-32-anni-dalla-strage-ci-sono-ancora-buchi-nei-57-giorni\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Melcore Valerio______Tantissimi i giovani che oggi si sono riuniti sotto l&#8217;albero di Paolo Borsellino in via D&#8217;Amelio a Palermo, per ricordare l&#8217;eroismo di quest&#8217;uomo e della sua scorta. Per ricordare le stragi che hanno insanguinato la bellissima citt\u00e0 siciliana e dire NO ALLA MAFIA.Per altro verso per\u00f2 non possiamo non ricordare da\u00a032 anni\u00a0aspettiamo che la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231909"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=231909"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231909\/revisions"}],"predecessor-version":[{"id":231962,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231909\/revisions\/231962"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=231909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=231909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=231909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}