{"id":231987,"date":"2024-07-21T18:20:00","date_gmt":"2024-07-21T16:20:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=231987"},"modified":"2024-07-21T19:08:08","modified_gmt":"2024-07-21T17:08:08","slug":"anziana-muore-in-incidente-stradale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/21\/anziana-muore-in-incidente-stradale\/","title":{"rendered":"ANZIANA MUORE IN INCIDENTE STRADALE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"635\" height=\"270\" class=\"wp-image-231988\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/ospedale-Panico-Tricase-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/ospedale-Panico-Tricase-1.jpg 635w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/ospedale-Panico-Tricase-1-300x128.jpg 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/><\/p>\n\n\n\n<p>(e.l.) ______\u00a0 Ieri sera nel centro abitato di Santa Maria di Leuca c\u2018\u00e8 stato un tragico incidente stradale. Il bilancio \u00e8 di un morto e due feriti.<\/p>\n\n\n\n<p>La vittima \u00e8 Maria Panzera, 80 anni, di Castrignano del Capo.<\/p>\n\n\n\n<p>Viaggiava su una Fiat Punto <span style=\"font-size: revert; color: initial;\">che, per cause ancora da accertare<\/span>, si \u00e8 scontrata con una Fiat Brava .<\/p>\n\n\n\n<p>Per lei le conseguenze sono state fatali. Portata d\u2019urgenza all\u2019ospedale Panico di Tricase (nella foto) \u00e8 morta poco dopo il ricovero a causa della gravit\u00e0 delle lesioni riportate.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Indagini della Polizia Locale in corso di svolgimento per accertare dinamica e cause di quanto accaduto.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/21\/anziana-muore-in-incidente-stradale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/21\/anziana-muore-in-incidente-stradale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0 Ieri sera nel centro abitato di Santa Maria di Leuca c\u2018\u00e8 stato un tragico incidente stradale. Il bilancio \u00e8 di un morto e due feriti. La vittima \u00e8 Maria Panzera, 80 anni, di Castrignano del Capo. Viaggiava su una Fiat Punto che, per cause ancora da accertare, si \u00e8 scontrata con una Fiat [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":231988,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231987"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=231987"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231987\/revisions"}],"predecessor-version":[{"id":231989,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/231987\/revisions\/231989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/231988"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=231987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=231987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=231987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}