{"id":232026,"date":"2024-07-23T12:59:00","date_gmt":"2024-07-23T10:59:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=232026"},"modified":"2024-07-23T17:19:24","modified_gmt":"2024-07-23T15:19:24","slug":"intascava-i-soldi-delle-aste-giudiziarie-arrestato-avvocato-tarantino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/23\/intascava-i-soldi-delle-aste-giudiziarie-arrestato-avvocato-tarantino\/","title":{"rendered":"INTASCAVA I SOLDI DELLE ASTE GIUDIZIARIE, ARRESTATO AVVOCATO"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1920\" height=\"1117\" class=\"wp-image-232027\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/23072024_090825_23.07.2024-peculato.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/23072024_090825_23.07.2024-peculato.jpg 1920w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/23072024_090825_23.07.2024-peculato-300x175.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/23072024_090825_23.07.2024-peculato-1024x596.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/23072024_090825_23.07.2024-peculato-768x447.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/23072024_090825_23.07.2024-peculato-1536x894.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n\n\n\n<p>(e.l.) ______  Ieri militari della Guardia di Finanza di Taranto hanno eseguito un\u2019ordinanza cautelare di arresti domiciliari nei confronti di un avvocato tarantino incaricato della vendita degli immobili pignorati nell\u2019ambito di numerose procedure esecutive immobiliari incardinate presso il Tribunale.<\/p>\n\n\n\n<p>L\u2019 accusa \u00e8 di peculato aggravato e continuato, per illecita appropriazione, dal 2021 al 2023, di circa 270 mila euro, sottratti dai conti correnti intestati alle singole procedure esecutive.<\/p>\n\n\n\n<p>L\u2019Autorit\u00e0 Giudiziaria ha altres\u00ec disposto il sequestro, anche per equivalente, di beni e disponibilit\u00e0 finanziarie a lui riconducibili.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/23\/intascava-i-soldi-delle-aste-giudiziarie-arrestato-avvocato-tarantino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/23\/intascava-i-soldi-delle-aste-giudiziarie-arrestato-avvocato-tarantino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Ieri militari della Guardia di Finanza di Taranto hanno eseguito un\u2019ordinanza cautelare di arresti domiciliari nei confronti di un avvocato tarantino incaricato della vendita degli immobili pignorati nell\u2019ambito di numerose procedure esecutive immobiliari incardinate presso il Tribunale. L\u2019 accusa \u00e8 di peculato aggravato e continuato, per illecita appropriazione, dal 2021 al 2023, di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":232027,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232026"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=232026"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232026\/revisions"}],"predecessor-version":[{"id":232033,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232026\/revisions\/232033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/232027"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=232026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=232026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=232026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}