{"id":232077,"date":"2024-07-25T00:02:00","date_gmt":"2024-07-24T22:02:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=232077"},"modified":"2024-07-24T18:39:55","modified_gmt":"2024-07-24T16:39:55","slug":"latiano-celebra-i-flora-dall800-ad-oggi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/25\/latiano-celebra-i-flora-dall800-ad-oggi\/","title":{"rendered":"LATIANO CELEBRA \u201cI\u00a0Flora, dall&#8217;800 ad oggi\u201d"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1200\" height=\"1600\" class=\"wp-image-232078\" style=\"width: 1299px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/IMG-iflora.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/IMG-iflora.jpg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/IMG-iflora-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/IMG-iflora-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/IMG-iflora-1152x1536.jpg 1152w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n\n\n\n<p>di <strong>Raffaele Polo<\/strong> &nbsp;______&nbsp;<\/p>\n\n\n\n<p>A rendere ancora pi\u00f9 tenace il legame tra la citt\u00e0 di Latiano e la famiglia del pittore Agesilao Flora, dopo la mostra allestita nell&#8217;Atrio del Palazzo Imperiali, l&#8217;Amministrazione comunale accoglier\u00e0 con un evento pubblico il dono della famiglia Flora: tre tele che riproducono altrettanti capolavori dell&#8217;arte, realizzate da Francesco Flora. <\/p>\n\n\n\n<p>A conclusione della mostra, infatti, il prof. Salvatore Luperto, direttore artistico del Museo Pietro Cavoti di Galatina e del Museo d&#8217;arte contemporanea di Matino far\u00e0 scoprire il mondo dei capolavori d&#8217;arte riprodotti,con curiosit\u00e0 e interessanti riflessioni su repliche e copie.. Dopo i saluti del Sindaco Mino Maiorano, introdurranno la serata l&#8217;assessore alla Cultura, dott.ssa Monica Albano, e l&#8217;arch. Enzo Flora, fratello di Francesco, in rappresentanza della famiglia Flora.<\/p>\n\n\n\n<p>La manifestazione, denominata \u201cI&nbsp; Flora, dall&#8217;800 ad oggi\u201d \u00e8 prevista&nbsp; per luned\u00ec 29 luglio, dalle ore 20.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/25\/latiano-celebra-i-flora-dall800-ad-oggi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/07\/25\/latiano-celebra-i-flora-dall800-ad-oggi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo &nbsp;______&nbsp; A rendere ancora pi\u00f9 tenace il legame tra la citt\u00e0 di Latiano e la famiglia del pittore Agesilao Flora, dopo la mostra allestita nell&#8217;Atrio del Palazzo Imperiali, l&#8217;Amministrazione comunale accoglier\u00e0 con un evento pubblico il dono della famiglia Flora: tre tele che riproducono altrettanti capolavori dell&#8217;arte, realizzate da Francesco Flora. A [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":232078,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232077"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=232077"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232077\/revisions"}],"predecessor-version":[{"id":232080,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232077\/revisions\/232080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/232078"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=232077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=232077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=232077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}