{"id":2321,"date":"2012-06-26T16:42:24","date_gmt":"2012-06-26T16:42:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=2321"},"modified":"2012-06-26T17:01:23","modified_gmt":"2012-06-26T17:01:23","slug":"il-fanfulla-torna-al-suo-antico-splendore","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/26\/il-fanfulla-torna-al-suo-antico-splendore\/","title":{"rendered":"IL \u201cFANFULLA\u201d TORNA AL SUO ANTICO SPLENDORE"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/26\/il-fanfulla-torna-al-suo-antico-splendore\/fanfulla1\/\" rel=\"attachment wp-att-2323\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/fanfulla1-300x283.jpg\" alt=\"\" title=\"fanfulla\" width=\"300\" height=\"283\" class=\"alignnone size-medium wp-image-2323\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/fanfulla1-300x283.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/fanfulla1.jpg 355w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Marted\u00ec 26 giugno, alle ore 20,<\/strong> <strong>sar\u00e0 presentata alla citt\u00e0<\/strong>, nella sua nuova veste, <strong>la statua del Fanfulla<\/strong>, di recente restaurata dall\u2019Amministrazione Comunale di Lecce. Il monumento cittadino, realizzato in gesso da Antonio Bortone nel 1876, venne fuso in bronzo nel 1921 e inaugurato l\u2019anno seguente. E\u2019 collocato <strong>nella piazzetta<\/strong> <strong>Raimondello Orsini<\/strong>, nel cuore del centro storico di Lecce, a due passi dal teatro Romano. Gli interventi di restauro sono stati effettuati grazie ad un finanziamento del <em>Lions Club Lecce Messapia<\/em>. Il direttore dei lavori \u00e8 l\u2019architetto Patrizia Erroi, coordinatore del settore Lavori Pubblici dell\u2019Ufficio Centro Storico del Comune di Lecce.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/26\/il-fanfulla-torna-al-suo-antico-splendore\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/26\/il-fanfulla-torna-al-suo-antico-splendore\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Marted\u00ec 26 giugno, alle ore 20, sar\u00e0 presentata alla citt\u00e0, nella sua nuova veste, la statua del Fanfulla, di recente restaurata dall\u2019Amministrazione Comunale di Lecce. Il monumento cittadino, realizzato in gesso da Antonio Bortone nel 1876, venne fuso in bronzo nel 1921 e inaugurato l\u2019anno seguente. E\u2019 collocato nella piazzetta Raimondello Orsini, nel cuore [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2323,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2321"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=2321"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2321\/revisions"}],"predecessor-version":[{"id":2352,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2321\/revisions\/2352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/2323"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=2321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=2321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=2321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}