{"id":232296,"date":"2024-08-04T15:30:00","date_gmt":"2024-08-04T13:30:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=232296"},"modified":"2024-08-06T14:09:37","modified_gmt":"2024-08-06T12:09:37","slug":"il-pranzo-della-domenica-da-giovanni-dagostino-nemmeno-un-panino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/04\/il-pranzo-della-domenica-da-giovanni-dagostino-nemmeno-un-panino\/","title":{"rendered":"IL PRANZO DELLA DOMENICA \/\u00a0DA GIOVANNI D\u2019AGOSTINO NEMMENO UN PANINO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1500\" height=\"1000\" class=\"wp-image-232297\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/17219041dago.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/17219041dago.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/17219041dago-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/17219041dago-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/07\/17219041dago-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n\n\n\n<p>di&nbsp;<strong>Raffaele Polo<\/strong>&nbsp;&nbsp;______&nbsp;&nbsp;\u00c9 un artista, Giovanni D\u2019Agostino. Eclettico e geniale, non ci aspettiamo molto dal suo \u2018pranzo\u2019 ma certamente ci dir\u00e0 molte cose interessanti. <\/p>\n\n\n\n<p>Lo troviamo nella sua casa di Leverano, davanti al pianoforte. Niente tavola imbandita, come avevamo preventivato&#8230; <\/p>\n\n\n\n<p>Con un sorriso, ci accoglie:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/p>\n\n\n\n<p>\u00abCaro Raffaele, mi dispiace riceverti seduto al pianoforte, ma mi trovo impegnato a comporre un brano per Coro e Orchestra che non mi permette di fermare l\u2019elaborato. Ancora poche battute e avr\u00f2 il piacere di mettermi a disposizione per un piacevole conversazione. <\/p>\n\n\n\n<p>Non avendo avuto il tempo di dedicarmi alla cucina, sia pure per preparare un piatto di spaghetti aglio olio e peperoncino, per il pranzo ci dobbiamo accontentare di un panino al tonno con formaggio svizzero e capperi. Abbiamo la frutta a cui seguir\u00e0 magari il dessert con un pasticciotto leccese, apprezzato anche in altre regioni del bel paese&#8230;\u00bb<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abMa allora sei un compositore? Hai deciso, finalmente\u00bb, gli chiediamo con un pizzico di ironia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abMi sento favorito dalla sorte a enunciare la mia professione: quella di medico, in cui il caso mi ha voluto. La mia intenzione era iscrivermi a Biologia all\u2019 universit\u00e0 di Bari, ma un caro amico vicino di casa e mio padre hanno complottato per iscrivermi a Medicina all\u2019universit\u00e0 di Chieti. Essendo questo amico universitario a Pescara che dista non pi\u00f9 di trenta Km da Chieti si \u00e8 interessato per la documentazione, e questo solo con l\u2019obiettivo di stare insieme per il corso universitario.&nbsp; <\/p>\n\n\n\n<p>Svolgo quindi l\u2019attivit\u00e0 di medico che mi ha dato la possibilit\u00e0 di sondare la sofferenza della gente. Per quanto possibile esercito la mia professione con seriet\u00e0 e con umanit\u00e0 dando ascolto anche a coloro che hanno bisogno di conforto pi\u00f9 che di farmaci. Posso dire che sono ben apprezzato dai miei pazienti, che accolgo con indole amichevole, affidandosi a me, nel corso dei miei molti anni di professione, in numero ragguardevole.<\/p>\n\n\n\n<p>A questo mio impegno ne ho aggiunto un altro a cui mi dedico fin da ragazzo: la letteratura. Scrivo poesie che ho raccolte in un testo \u201cTerra incolta\u201d per la casa editrice Esperidi. Dico dei sogni, delle speranze, delle paure e delle sofferenze della gente, e racconto il Salento, la mia terra natia di cui sono innamorato. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Altro interesse letterario \u00e8 lo scrivere in prosa. Ebbene s\u00ec, scrivo romanzi, e l\u2019ultimo \u00e8 stato \u201cBenedetta\u201d che racconta di una bambina rapita, edito da \u201cIl raggio verde\u201d. Protagonista di questo romanzo, ispirato ad un evento reale, \u00e8 il commissario \u201cRaffaele Polo\u201d che dedica tutto se stesso alla soluzione del caso. Mi ha ispirato il fatto che Raffaele indaga, analizza esamina molti libri di scrittori per dare loro una forma risolutiva per essere pubblicati.<\/p>\n\n\n\n<p>Nei miei romanzi metto sempre in primo piano i sentimenti umani che ci approcciano con gli altri. Amore, odio, rabbia, orgoglio, piet\u00e0, coraggio, speranza, guidano la nostra esistenza, e sono la storia di ognuno di noi\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ci sentiamo di perdonare Giovanni per il mancato desinare: chi l\u2019avrebbe detto che, di colpo, sarei diventato un affermato Commissario, sia pure in termini letterari? Ma non ha finito, il nostro amico medico-poeta-musicista&#8230;<\/p>\n\n\n\n<p>\u00abLa mia performance, per\u00f2, non si esaurisce con la letteratura, perch\u00e9 da circa quarant\u2019anni mi dedico con passione a quella che per me \u00e8 la buona musica.<\/p>\n\n\n\n<p>Racconto come \u00e8 successo. Una sera di un fine estate, mio figlio Daniele di appena sei anni ascolt\u00f2 musica per pianoforte eseguita da un ragazzo. Rest\u00f2 affascinato tanto da chiedermi di voler imparare a suonare il pianoforte. Venne un maestro a fargli lezione a domicilio, cos\u00ec anch\u2019io cominciai a studiare musica. Ben presto ero in grado di comporre musica leggera, liscio, pizziche, ma non mi bastava. Mi rivolsi a un professore di conservatorio, il M\u00b0 Luigi Quarta, per imparare pianoforte, armonia e composizione di grandi opere. \u00c8 stato cos\u00ec che con mia penna ho composto opere liriche, concerti per pianoforte e orchestra, musica per coro e ben altro. <\/p>\n\n\n\n<p>Con edizioni Lulu.com ho pubblicato diversi libri di musica. La mia musica, come la mia arte nello scrivere, \u00e8 votata ai sentimenti: compongo melodie che raccontano una storia per emozionare e rendere l\u2019animo sereno. Un momento di dolcezza che solo la buona musica sa dare e, di cui, abbiamo tanto bisogno\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Il maestro D\u2019Agostino, con aria ispirata, si rituffa nei suoi accordi, si era parlato di un panino ma con che coraggio potremmo occuparci di cose da mangiare quando l\u2019atmosfera \u00e8 quella magica delle composizioni artistiche?&#8230;<\/p>\n\n\n\n<p>______&nbsp;<\/p>\n\n\n\n<p><strong>( 11 \u2010 continua )<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/04\/il-pranzo-della-domenica-da-giovanni-dagostino-nemmeno-un-panino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/04\/il-pranzo-della-domenica-da-giovanni-dagostino-nemmeno-un-panino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di&nbsp;Raffaele Polo&nbsp;&nbsp;______&nbsp;&nbsp;\u00c9 un artista, Giovanni D\u2019Agostino. Eclettico e geniale, non ci aspettiamo molto dal suo \u2018pranzo\u2019 ma certamente ci dir\u00e0 molte cose interessanti. Lo troviamo nella sua casa di Leverano, davanti al pianoforte. Niente tavola imbandita, come avevamo preventivato&#8230; Con un sorriso, ci accoglie:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u00abCaro Raffaele, mi dispiace riceverti seduto al pianoforte, ma mi trovo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":232297,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232296"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=232296"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232296\/revisions"}],"predecessor-version":[{"id":232564,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232296\/revisions\/232564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/232297"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=232296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=232296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=232296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}