{"id":232693,"date":"2024-08-10T13:21:05","date_gmt":"2024-08-10T11:21:05","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=232693"},"modified":"2024-08-10T13:32:35","modified_gmt":"2024-08-10T11:32:35","slug":"vada-alle-olimpiadi-quattordicesima-giornata-di-gare-lultima-domenica-11","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/10\/vada-alle-olimpiadi-quattordicesima-giornata-di-gare-lultima-domenica-11\/","title":{"rendered":"VADA ALLE OLIMPIADI \/\u00a0QUATTORDICESIMA GIORNATA DI GARE. L&#8217;ULTIMA DOMENICA 11"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"526\" height=\"584\" class=\"wp-image-232694\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/454668019_1052472516246291_3848756047440383427_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/454668019_1052472516246291_3848756047440383427_n.jpg 526w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/454668019_1052472516246291_3848756047440383427_n-270x300.jpg 270w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/><\/p>\n\n\n\n<p>di <strong>Elena Vada<\/strong> ______\u00a0\u00a0<\/p>\n\n\n\n<p>Quante medaglie di legno (quarti posti) abbiamo? Tante. Ho perso il conto. Ma se le sommassimo a quelle effettive, autentiche, guadagnate, saliremmo ai primi posti della classifica olimpica.<\/p>\n\n\n\n<p>Stupido ragionamento, che faccio per consolarmi &#8230; ma non regge. Un certo rammarico, per\u00f2, in alcune occasioni, \u00e8 stato sentito.<\/p>\n\n\n\n<p>NUOTO 10KM di fondo:&nbsp;Domenico Acerenza \u00e8 quarto nelle acque della Senna. Oro all&#8217;ungherese Kristof. Gregorio Paltrinieri, crollato negli ultimi metri, \u00e8 nono.\u00ab<\/p>\n\n\n\n<p>Bellissimo campo di gara anche a livello di pubblico. Una delle pi\u00f9 belle gare nelle acque libere mai fatte, lasciando le storie dei giorni passati. Ma non mi ritufferei nella Senna,&nbsp;ora speriamo di stare bene nei prossimi giorni senn\u00f2 qualcuno dovr\u00e0 assumersi le sue responsabilit\u00e0\u00bb dichiara Acerenza. Nuotare nella m&#8230;. non deve essere stato piacevole.<\/p>\n\n\n\n<p>TUFFI:&nbsp;Chiara Pellacani&nbsp;ha chiuso al quarto posto la finale dal trampolino 3 metri.&nbsp;<\/p>\n\n\n\n<p>SURF KITE :&nbsp;Sfuma la medaglia per&nbsp;Riccardo Pianosi, che colleziona un terzo, un quarto e un secondo posto, dopo essere passato dalle semifinali e chiude ai piedi del podio. Quarto.<\/p>\n\n\n\n<p>GINNASTICA RITMICA: le \u00abFarfalle\u00bb azzurre si sono qualificate per la&nbsp;finale&nbsp;dell&#8217;all- around delle Olimpiadi di Parigi con il secondo punteggio.&nbsp;Martina Centofanti, Agnese Duranti, Alessia Maurelli, Daniela Mogurean e Laura Paris hanno totalizzato 69.350 punti.<\/p>\n\n\n\n<p>Sofia Raffaeli (Fiamme Oro) 20anni di Chiaravalle provincia di Ancona, ha vinto il&nbsp; BRONZO nel concorso generale della ginnastica ritmica. Ottavo posto per&nbsp;Milena Baldassarri. L&#8217;azzurra, che aveva dominato le qualificazioni, commette due fatali errori. Questa \u00e8 pur sempre la prima nostra medaglia, nel singolo di ritmica All Around. Sofia ci dice: &#8220;Dopo ieri, credevo di poter vincere, ma non siamo perfetti e non si pu\u00f2 avere tutto ci\u00f2 che si vuole&#8221;&#8230; e le sono scese sul viso, lacrime composte&#8230;&nbsp;<\/p>\n\n\n\n<p>ATLETICA &#8211; 4&#215;100:&nbsp;Gli azzurri :&nbsp;Melluzzo, Jacobs, Patta e Tortu, campioni&nbsp;olimpici uscenti, hanno concluso al quarto posto col primato stagionale. Oro al Canada, Argento al Sud Africa, Bronzo alla Gran Bretagna.<\/p>\n\n\n\n<p>ATLETICA &#8211; 10.000m femminili. Grande, grande, grande impresa dell&#8217;azzurra&nbsp;Nadia Battocletti&nbsp;che vince la medaglia d&#8217; ARGENTO Dopo il quarto posto nei 5000 la campionessa europea ha avuto la gioia di conquistare un secondo posto, che proprio non si aspettava. Oro alla kenyana Beatrice Chebet. Bronzo all&#8217;olandese Sifan Hassan. Nadia dichiara: &#8220;Pap\u00e0 (Giuliano, il suo allenatore, ndr) mi aveva detto: &#8216;Pu\u00f2 bastare cosi, non esageriamo, meglio la salute&#8217;. Ma io volevo divertirmi ancora un po&#8217;, sono entrata in campo con il sorriso e tanta leggerezza e spensieratezza&#8221; che tranquilla e consapevole serenit\u00e0, sprigiona questa ragazza che lancia un bellissimo messaggio per tutti: sorriso, leggerezza e spensieratezza.&nbsp;<\/p>\n\n\n\n<p>Cos\u00ec dovrebbero essere affrontati i GIOCHI Olimpici! Senza l&#8217; incubo del risultato a tutti i costi, anche se, \u00e8 vero, si gareggia per vincere.<\/p>\n\n\n\n<p>ATLETICA &#8211; SALTO TRIPLO : Andy Diaz Hernandez ha vinto il BRONZO chiudendo la gara con&nbsp;la misura di 17.64. Oro allo spagnolo Jordan Alejandro Diaz Fortun,&nbsp;argento al portoghese Pedro Pich. Il nostro Andy 28anni \u00e8 nativo di L&#8217; Avana, Cuba. Vive a&nbsp;Livorno e si allena sotto la tutela di Fabrizio&nbsp; Donato, bronzo olimpico 2012 in questa disciplina. Il 23 febbraio 2023, ha ottenuto la cittadinanza italiana&nbsp;a seguito di una delibera del Consiglio dei Ministri,&nbsp;su proposta del Ministro dell\u2019interno, Matteo Piantedosi. Dice: &#8220;Grazie Italia, ma posso fare ancora di pi\u00f9&#8221;.<\/p>\n\n\n\n<p>TAEKWONDO:&nbsp;Simone Alessio, campione del mondo&nbsp; in carica,&nbsp;ha vinto la medaglia di BRONZO nella categoria 80 kg. battendo lo&nbsp;statunitense CJ Nickolas.<\/p>\n\n\n\n<p>CICLISMO SU PISTA FEMMINILE: Chiara Consonni (Fiamme Oro) 25anni di Ponte San Pietro provincia di Bergamo&nbsp;e&nbsp;Vittoria Guazzini (Fiamme Oro) 24anni di Pontedera provincia di Pisa, vincono il nostro undicesimo ORO. Meravigliosa medaglia, anche perch\u00e9 inaspettata. Grazie ragazze.<\/p>\n\n\n\n<p>SOLLEVAMENTO PESI: Antonino Pizzolato ( Fiamme Oro) detto Nino 28anni di Castelvetrano, Trapani, ha vinto la medaglia di BRONZO nel sollevamento pesi categoria 89 kg. nonostante i tanti problemi fisici, ce la fatta! Grazie.<\/p>\n\n\n\n<p>PALLAVOLO MASCHILE: USA batte Italia 3 a 0. Dice il CT&nbsp; Fef\u00e8 De Giorgi:<\/p>\n\n\n\n<p>&#8220;Questa \u00e8 una squadra giovane che deve fare esperienza, dobbiamo cercare ancora di migliorare. E&#8217; un percorso comunque virtuoso. Se ci stacchiamo dall&#8217;amarezza della mancata medaglia, c&#8217;\u00e8 da stare positivi. Questo gruppo ha margini di miglioramento e li avr\u00e0 per molti anni&#8221;.&nbsp;<\/p>\n\n\n\n<p>GOLF: la bellissima Alessandra Fanali \u00e8 52^<\/p>\n\n\n\n<p>CALCIO MASCHILE: la&nbsp;Spagna&nbsp;ha vinto il torneo olimpico maschile di calcio, battendo 5-3 nei supplementari la Francia guidata da Thierry Henry.&nbsp;<\/p>\n\n\n\n<p>BOXE DONNE: l&#8217; algerina Imane Khelif vince l&#8217; oro battendo la la cinese Yang, campionessa mondiale in carica<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/10\/vada-alle-olimpiadi-quattordicesima-giornata-di-gare-lultima-domenica-11\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/10\/vada-alle-olimpiadi-quattordicesima-giornata-di-gare-lultima-domenica-11\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Elena Vada ______\u00a0\u00a0 Quante medaglie di legno (quarti posti) abbiamo? Tante. Ho perso il conto. Ma se le sommassimo a quelle effettive, autentiche, guadagnate, saliremmo ai primi posti della classifica olimpica. Stupido ragionamento, che faccio per consolarmi &#8230; ma non regge. Un certo rammarico, per\u00f2, in alcune occasioni, \u00e8 stato sentito. NUOTO 10KM di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":232694,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232693"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=232693"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232693\/revisions"}],"predecessor-version":[{"id":232695,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232693\/revisions\/232695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/232694"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=232693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=232693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=232693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}