{"id":23270,"date":"2014-01-09T11:50:55","date_gmt":"2014-01-09T11:50:55","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23270"},"modified":"2014-01-09T11:50:55","modified_gmt":"2014-01-09T11:50:55","slug":"sulle-droghe-leggere-cinica-campagna-di-distrazione-di-massa-di-vendola","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/09\/sulle-droghe-leggere-cinica-campagna-di-distrazione-di-massa-di-vendola\/","title":{"rendered":"Sulle droghe leggere cinica campagna di distrazione di massa di Vendola"},"content":{"rendered":"<p><span style=\"font-family: 'Times New Roman'\">Il Vice-Presidente vicario del Gruppo PDL\/FI alla Regione Puglia Erio Congedo ha diffuso la seguente nota:<\/span><span>\u00a0<\/span><span style=\"font-family: 'Times New Roman'\">\u201cCon l\u2019ennesima fuga dai problemi veri della comunit\u00e0 pugliese ed in particolare della sua componente giovanile &#8211; a cominciare ad esempio dal record nazionale di perdita di posti di lavoro e dal flop delle politiche in materia di occupazione &#8211; Vendola ritorna sulla liberalizzazione delle cosiddette droghe leggere, fingendo di ignorare che esse, normalmente, altro non sono che l\u2019iniziazione a quelle cosiddette pesanti, con quel che ne consegue.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'\">Il dibattito sulla questione \u00e8 aperto da tempo &#8211; personalmente sono risolutamente contrario a politiche di legalizzazione ed alla distinzione fra droghe leggere e pesanti -, ma ci\u00f2 che in questo momento emerge \u00e8 il tentativo del Governatore di Puglia di aggrapparsi a campagne di distrazione di massa che gli evitino di misurarsi con i consuntivi deludenti della sua stagione di governo.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'\">Se poi l\u2019obiettivo \u00e8 recuperare il consenso perduto per i risultati del suo Governo, soffiando sul fuoco di fenomeni sociali che possono distruggere giovani vite e famiglie, saremmo di fronte ad un cinismo che preferisco non qualificare.\u201d<\/span><\/p>\n<div><span style=\"font-family: 'Times New Roman'\"><br \/>\n<\/span><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/09\/sulle-droghe-leggere-cinica-campagna-di-distrazione-di-massa-di-vendola\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/09\/sulle-droghe-leggere-cinica-campagna-di-distrazione-di-massa-di-vendola\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il Vice-Presidente vicario del Gruppo PDL\/FI alla Regione Puglia Erio Congedo ha diffuso la seguente nota:\u00a0\u201cCon l\u2019ennesima fuga dai problemi veri della comunit\u00e0 pugliese ed in particolare della sua componente giovanile &#8211; a cominciare ad esempio dal record nazionale di perdita di posti di lavoro e dal flop delle politiche in materia di occupazione &#8211; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23270"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23270"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23270\/revisions"}],"predecessor-version":[{"id":23272,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23270\/revisions\/23272"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}