{"id":232734,"date":"2024-08-11T14:03:26","date_gmt":"2024-08-11T12:03:26","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=232734"},"modified":"2024-08-11T14:03:30","modified_gmt":"2024-08-11T12:03:30","slug":"esplosione-in-un-trullo-a-cisternino-un-morto-e-un-ferito","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/11\/esplosione-in-un-trullo-a-cisternino-un-morto-e-un-ferito\/","title":{"rendered":"ESPLOSIONE IN UN TRULLO A CISTERNINO, UN MORTO E UN FERITO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1280\" height=\"720\" class=\"wp-image-232736\" style=\"width: 150px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/103405976-31c5c860-8bd2-4d95-8df3-c12386d18d8e.webp\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/103405976-31c5c860-8bd2-4d95-8df3-c12386d18d8e.webp 1280w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/103405976-31c5c860-8bd2-4d95-8df3-c12386d18d8e-300x169.webp 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/103405976-31c5c860-8bd2-4d95-8df3-c12386d18d8e-1024x576.webp 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/103405976-31c5c860-8bd2-4d95-8df3-c12386d18d8e-768x432.webp 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" class=\"wp-image-232737\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/sebbu.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/sebbu.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/sebbu-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/sebbu-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n\n\n\n<p>(e.l.) ______\u00a0 Questa  mattina c&#8217;\u00e8 stata una forte esplosione, verosimilmente causata da una fuga di gas, all&#8217;interno di un trullo\u00a0nelle campagne di Cisternino.<\/p>\n\n\n\n<p>Il bilancio \u00e8 di un morto e un ferito. La vittima, rimasta intrappolato sotto le macerie, \u00e8 <span style=\"font-size: revert; color: initial;\">Nicola Salatino<\/span>, 55  anni, <span style=\"font-size: revert; color: initial;\">di Bari, ingegnere, in vacanza con la moglie, rimasta a sua volta ferita e ricoverata all&#8217;ospedale Perrino di Brindisi.<\/span>    <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Nicola Salatino, ingegnere di Bariin vacanza con la moglie, rimasta a sua volta ferita e ricoverata all&#8217;ospedale Perrino di Brindisi.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/11\/esplosione-in-un-trullo-a-cisternino-un-morto-e-un-ferito\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/11\/esplosione-in-un-trullo-a-cisternino-un-morto-e-un-ferito\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0 Questa mattina c&#8217;\u00e8 stata una forte esplosione, verosimilmente causata da una fuga di gas, all&#8217;interno di un trullo\u00a0nelle campagne di Cisternino. Il bilancio \u00e8 di un morto e un ferito. La vittima, rimasta intrappolato sotto le macerie, \u00e8 Nicola Salatino, 55 anni, di Bari, ingegnere, in vacanza con la moglie, rimasta a sua [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":232737,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232734"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=232734"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232734\/revisions"}],"predecessor-version":[{"id":232738,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232734\/revisions\/232738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/232737"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=232734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=232734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=232734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}