{"id":232802,"date":"2024-08-13T17:56:11","date_gmt":"2024-08-13T15:56:11","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=232802"},"modified":"2024-08-13T18:06:47","modified_gmt":"2024-08-13T16:06:47","slug":"report-della-polizia-di-stato-su-arresto-giovane-romeno-presunto-ladro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/13\/report-della-polizia-di-stato-su-arresto-giovane-romeno-presunto-ladro\/","title":{"rendered":"REPORT DELLA POLIZIA DI STATO SU ARRESTO ROMENO PRESUNTO LADRO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"530\" class=\"wp-image-232805\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/1723541924379058_l-logo.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/1723541924379058_l-logo.jpg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/1723541924379058_l-logo-300x177.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/1723541924379058_l-logo-768x452.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n\n\n\n<p>Durante un\u2019attivit\u00e0 di pattugliamento, i poliziotti della squadra volante del Commissariato di P.S. di Gallipoli domenica 11 hanno riconosciuto un giovane noto per essere dedito ai furti.<\/p>\n\n\n\n<p>Fermato per un controllo pi\u00f9 approfondito, il giovane, un 22enne di origini rumene ma ormai stanziato nel Salento, ha tentato la fuga che, per\u00f2, \u00e8 durata poco perch\u00e9 \u00e8 stato acciuffato dopo un inseguimento a piedi dagli stessi poliziotti.<\/p>\n\n\n\n<p>Nonostante le fasi concitate del controllo di polizia, visto che il giovane non si \u00e8 dimostrato affatto collaborativo, tanto da danneggiare con dei calci anche l\u2019auto di servizio e provocare contusioni ai poliziotti, questi ultimi sono riusciti a portarlo in Commissariato, con non poche difficolt\u00e0, e arrestarlo per i reati di resistenza a pubblico ufficiale, ricettazione, porto abusivo di arma, possesso ingiustificato di arnesi atti allo scasso e indebito utilizzo di strumenti di pagamento diverso dai contanti per avere, poco prima, prelevato del denaro contante presso una tabaccheria di Gallipoli, previo utilizzo di una carta di credito di provenienza delittuosa.<\/p>\n\n\n\n<p>Durante il controllo, \u00e8 stato rinvenuto un trapano ed un seghetto elettrico, trasportati nel proprio zaino, da ritenersi oggetti atti allo scasso, visto anche i numerosi precedenti specifici.<\/p>\n\n\n\n<p>Durante la perquisizione personale, gli agenti insospettiti da un \u201cclick\u201d hanno rinvenuto, occultato negli indumenti intimi, un coltello a scatto con lama a punta della lunghezza di circa 20 cm.<\/p>\n\n\n\n<p>Per tutti questi motivi, su disposizione del pubblico ministero di turno, il giovane \u00e8 stato tratto in arresto e portato in carcere e, dopo l\u2019udienza di convalida dell\u2019arresto, \u00e8 stato sottoposto alla misura dell\u2019obbligo di presentazione alla polizia giudiziaria del comune di residenza.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/13\/report-della-polizia-di-stato-su-arresto-giovane-romeno-presunto-ladro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/13\/report-della-polizia-di-stato-su-arresto-giovane-romeno-presunto-ladro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Durante un\u2019attivit\u00e0 di pattugliamento, i poliziotti della squadra volante del Commissariato di P.S. di Gallipoli domenica 11 hanno riconosciuto un giovane noto per essere dedito ai furti. Fermato per un controllo pi\u00f9 approfondito, il giovane, un 22enne di origini rumene ma ormai stanziato nel Salento, ha tentato la fuga che, per\u00f2, \u00e8 durata poco perch\u00e9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":232805,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232802"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=232802"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232802\/revisions"}],"predecessor-version":[{"id":232808,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/232802\/revisions\/232808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/232805"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=232802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=232802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=232802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}