{"id":23283,"date":"2014-01-10T08:23:53","date_gmt":"2014-01-10T08:23:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23283"},"modified":"2014-01-10T09:30:17","modified_gmt":"2014-01-10T09:30:17","slug":"giovanna-canzano-intervista-claudio-moffa-sul-suo-ultimo-libro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/10\/giovanna-canzano-intervista-claudio-moffa-sul-suo-ultimo-libro\/","title":{"rendered":"Giovanna Canzano intervista Claudio Moffa sul suo ultimo libro"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/10\/giovanna-canzano-intervista-claudio-moffa-sul-suo-ultimo-libro\/claudio-moffa\/\" rel=\"attachment wp-att-23284\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/Claudio-Moffa-150x150.jpg\" alt=\"\" title=\"Claudio Moffa\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-23284\" \/><\/a>Per rompere la gabbia del debito \u2026 Produttori di tutto il mondo unitevi<\/strong><\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>Nel suo ultimo libro ci sono molte affermazioni &#8216;forti&#8217;. Forse quella di maggiore impatto \u00e8 &#8220;libera impresa in Stato padrone dell&#8217;emissione monetaria&#8221;. Ma lei \u00e8 diventato liberista?<\/em>http:\/\/www.italiasociale.net\/immagini13\/2013-12-30-1.jpg<\/p>\n<p><strong>R\u00a0<\/strong>No, continuo a pensare che il modello migliore per il nostro paese sia un&#8217;economia mista, con alcuni settori strategici nelle mani dello Stato come \u00e8 stato fino al 1992. Ma il liberismo va comunque rideclinato, e anche chi \u00e8 contro il liberismo deve impegnarsi in questo senso: bisogna distinguere tra liberismo d&#8217;impresa produttiva e liberismo finanziario. Il primo ha una sua legittimit\u00e0, tale anche perch\u00e9 normato e in permanente dialettica con i sindacati e i governi. Il secondo tipo di liberismo naviga invece nell&#8217;assoluto vuoto normativo, \u00e8 una attivit\u00e0 borderline tra furbizia, truffa, guadagni comunque illeciti: le banche che accumulano masse di denaro enormi attraverso la riserva frazionaria e l&#8217;anatocismo, i futures, il caso Madoff. Un potere che oggi \u00e8 non di supporto, ma antagonista al mondo della produzione, un po&#8217; come fotografato da Hobson nella seconda met\u00e0 dell&#8217;Ottocento. I capitalisti industriali e i produttori dipendenti hanno da questo punto di vista non dico gli stessi interessi, ma interessi convergenti nell\u2019azione di contrasto della crisi.<\/p>\n<p><strong><em>Un minuto di silenzio per imprenditori e disoccupati suicidi<\/em><\/strong><\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>Ma c\u2019\u00e8 questa coscienza nel mondo imprenditoriale? E non c\u2019\u00e8 il rischio che l\u2019oggettiva comunanza di interessi venga strumentalizzata da imprenditori senza scrupoli per indebolire ancora di pi\u00f9 i lavoratori dipendenti?<\/em><\/p>\n<p><strong>R\u00a0<\/strong>Un pericolo del genere c\u2019\u00e8, ma la convergenza \u00e8 oggettiva. In occasione della presentazione del mio libro all\u2019Universit\u00e0 di Teramo, il Presidente della Confindustria locale ha lamentato la sua delusione dopo il regalo di 149 miliardi di euro alle Banche da parte della BCE, nel dicembre 2011: &#8220;finalmente adesso le banche ci daranno crediti per la ripresa. Ma poi non \u00e8 stato cos\u00ec, e son rimasto deluso&#8221;. Cos\u00ec mi ha detto, e su una banca di emissione di Stato non ha opposto contro argomentazioni in difesa della \u2018libert\u00e0\u2019 e dell\u2019&#8221;autonomia&#8221; dell\u2019Istituto di emissione. La libera impresa produttiva non c\u2019entra nulla con il liberismo finanziario, anzi sono fenomeni opposti e antagonisti..<\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>&#8220;Produttori di tutto il mondo unitevi&#8221; \u00e8 uno slogan che campeggiava sullo schermo dell\u2019aula dove si svolgeva la presentazione del suo libro a Teramo<\/em><\/p>\n<p><strong>R\u00a0<\/strong>\u00c8 cos\u00ec, \u00e8 una piccola provocazione che riassume schematicamente quel che penso e che accompagnava il mio intervento. La crisi \u00e8 epocale. Il liberismo finanziario uccide tutto il mondo della produzione, anche in senso letterale: alle migliaia e migliaia di piccole e medie imprese che chiudono i battenti, come da reportage RAI di qualche mese fa di Riccardo Iacona, corrispondono i suicidi di imprenditori e la povert\u00e0 di milioni di famiglie italiane. Durante il convegno-presentazione all&#8217;Universit\u00e0, su richiesta di uno dei relatori abbiamo tenuto un minuto di silenzio in piedi a ricordo degli imprenditori suicidatisi negli ultimi anni. Io ho aggiunto, &#8220;ricordiamo anche i disoccupati&#8221; che hanno fatto la stessa fine o che vivono comunque una situazione di miseria gravissima. Il problema \u00e8 appunto questo, una sorta di patto tra Produttori contro la crisi e le logiche del capitale speculativo e bancario, quello che per dirla con Marx &#8220;rapina l&#8217;altrui ricchezza gi\u00e0 creata&#8221;.<\/p>\n<p><strong><em>Una trasversalit\u00e0 assoluta: viva il liberale William Mackenzie King<\/em><\/strong><\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>Ma come si fa a vincere una battaglia contro dei poteri cos\u00ec forti?<\/em><\/p>\n<p><strong>R\u00a0<\/strong>Con l\u2019affinamento dell\u2019analisi, con la memoria storica e con una trasversalit\u00e0 assoluta, sociale &#8211; tutti i ceti produttori di ricchezza reale \u2013 etico-religiosa \u2013 Islam e Cristianesimo hanno nel loro dna le potenzialit\u00e0 per collaborare su questo terreno \u2013 e politica. La trasversalit\u00e0 \u00e8 sicuramente l\u2019opzione fondamentale. Non ha senso richiudersi nel proprio ghetto ideologico e politico, a fronte di un problema cos\u00ec grave, e quando vediamo che dagli anni Novanta ad oggi ci sono stati progetti di legge targati con le pi\u00f9 disparate sigle, AN e PRC, IdV e Pdl, Storace e Lega. Nel libro cito come esempio simbolo un ministro liberale canadese di cui ho appreso l&#8217;esistenza da un saggio di Sergio Cesaratto di due o tre anni fa. William Mackenzie King sosteneva, lui liberale, che lo Stato deve gestire l&#8217;emissione monetaria. Oggi invece la Banca d&#8217;Italia \u00e8 privata. E io preferisco di gran lunga un liberale alla Mackenzie che uno di quei noiosi &#8216;marxisti&#8217; che pretendono che la crisi scoppiata nel 2008 nelle viscere della Lehman Bank e degli imbrogli finanziari sia una crisi da sovrapproduzione. Sovrapproduzione o rarefazione della moneta?<\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>\u00c8 per sostenere la trasversalit\u00e0, che lei teorizza una continuit\u00e0 tra fascismo e repubblica per quel che attiene alla sovranit\u00e0 monetaria?<\/em><\/p>\n<p><strong>R\u00a0<\/strong>Non mi sognerei mai di piegare i fatti &#8211; e un fatto di questa portata &#8211; a esigenze &#8216;politich\u00c8 sia pure emergenziali. E tuttavia, premesso che la storia dell&#8217;emissione monetaria in Italia \u00e8 una grotta oscura e profonda &#8211; stiamo parlando di storia delle banche &#8211; e io mi ci sono addentrato per pochi passi, la continuit\u00e0 \u00e8 un dato di fatto.<\/p>\n<p><strong><em>La continuit\u00e0 Fascismo-Repubblica: la Banca d\u2019Banca d\u2019Italia come l\u2019Agip salvata da Mattei<\/em><\/strong><\/p>\n<p>\u00c8 accaduto con la Banca d&#8217;Italia quel che era successo all&#8217;AGIP, il carrozzone fascista che il liberista Bonomi voleva far chiudere a Mattei, e che Mattei salv\u00f2 facendo sponda sul governo Parri. Nel mio libro non cito solo uno studioso che sostiene questa tesi &#8211; Puccini &#8211; ma anche un vecchio libro della Savelli, la casa editrice di estrema sinistra degli anni Settanta, nel quale uno studioso marxista dell&#8217;epoca spende parole sostanzialmente positive per l&#8217;opzione mussoliniana del 1936. Ed erano gli anni Settanta. La trasversalit\u00e0 dunque non \u00e8 da giustificare con l\u2019invenzione o la forzatura della storia, ma \u00e8 giustificata dalla Storia, anche se \u00e8 indigesta a quei \u2018compagni\u2019 e \u2018camerati\u2019 fermi nel culto di un passato che non esiste pi\u00f9.<\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>Camerati e compagni? In realt\u00e0 mi pare che anche un intellettuale centrista come Paolo Mieli ha criticato recentemente destra e sinistra per la perdita delle loro identit\u00e0, lamentando la confusione tra la gente.<\/em><\/p>\n<p><strong>R\u00a0<\/strong>S\u00ec ho sentito anch\u2019io quell\u2019intervento a Omnibus, e l\u2019ho trovato curioso, perch\u00e9 negli anni Novanta fu proprio Mieli a portare alla luce i momenti di convergenza e alleanza tra repubblichini di Sal\u00f2 e partigiani comunisti. Era, se ricordo bene l&#8217;epoca di Fiuggi, ma quella di oggi mi sembra lo stesso un\u2019analisi parziale rispetto all\u2019epoca che stiamo vivendo, la dittatura del capitale finanziario e bancario sulla sfera produttiva. Mieli ultimamente \u00e8 venuto un paio di volte a Teramo, una volta per parlare della falsificazione della storia col sindaco Brucchi: peccato che io stavo a Roma, mi sarebbe piaciuto ascoltarlo. Comunque, tornando a Omnibus, oggi come oggi bisogna seguire il Mieli degli anni Novanta. Trasversalit\u00e0 sociale tra produttori, e politica tra destra e sinistra. La fabbrica Trombari dei primi anni Settanta su cui ironizzava Ivan Della Mea, con l&#8217;imprenditore ex partigiano pronto a sparare sugli operai in sciopero, non esiste pi\u00f9 nemmeno come parto della fantasia artistica di quel cantautore: \u00e8 morta con la crisi, come tante altre. Occorre convergenza e trasversalit\u00e0. Sui contenuti, cio\u00e8 il ripristino della sovranit\u00e0 monetaria, il debito e il cruciale nodo dell&#8217; Europa, questa Europa delle banche e delle finanze.<\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>Lei non si pronuncia pro o contro l&#8217;uscita dall&#8217;euro. Perch\u00e9?<\/em><\/p>\n<p><strong>R\u00a0<\/strong>Essenzialmente per due motivi: perch\u00e9 come politologo internazionalista mi sono reso conto che le monete transnazionali hanno un peso e una importanza riconosciuta a suo tempo, in alternativa al dollaro, da paesi come la Libia, la Siria, l&#8217;Iran. E soprattutto perch\u00e9 uscire dall&#8217;euro pu\u00f2 diventare una mera operazione di depistaggio della rabbia popolare, se a questa misura, assolutamente legittima ove non ci siano alternative, non se ne accompagna un&#8217;altra, e cio\u00e8 il ritorno in mani pubbliche della Banca d&#8217;Italia. La Banca centrale deve tornare allo Stato: solo in questo modo l&#8217;Italia potr\u00e0 diventare veramente sovrana sulla propria moneta. In caso contrario Roma guadagner\u00e0 qualcosa giocando sui rapporti non pi\u00f9 fissi con le altre monete europee, e sulla svalutazione per rilanciare le esportazioni. Ma la vera sovranit\u00e0, quella che dovrebbe essere sancita dalla Costituzione come quarto principio e potere fondativo della Repubblica, \u00e8 quella che garantisce allo Stato il monopolio dell&#8217;emissione monetaria.<\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>Solo rinazionalizzando la Banca d\u2019Italia lo Stato pu\u00f2 tornare sovrano sulla moneta?<\/em><\/p>\n<p><strong>R\u00a0<\/strong>Le vie sono in realt\u00e0 tre: rinazionalizzazione della Banca d\u2019Italia, un nuovo Istituto centrale d\u2019emissione monetaria, oppure biglietti di stato di corso legale stampati dalla Zecca, sotto il controllo del Ministero del Tesoro. Negli ultimi due casi la Banca d\u2019Italia resta privata, ma diventa una grande Banca come tutte le altre, senza cio\u00e8 potere di signoraggio. La terza opzione \u00e8 quella pi\u00f9 semplice tecnicamente, ma pi\u00f9 difficile politicamente. Ma qui interviene l\u2019altro punto di forza da recuperare per affrontare la difficile battaglia, la memoria storica.<\/p>\n<p><strong><em>La storia \u00e8 dalla nostra parte: occorre recuperare la memoria della Banca centrale a capitale pubblico e dei Biglietti di stato di De Gasperi e Moro per far capire che la battaglia \u00e8 difficile ma pu\u00f2 essere vinta<\/em><\/strong><\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>Nel suo libro in effetti lei pubblica documenti di epoca romana, medievale e moderna<\/em><\/p>\n<p><strong>R\u00a0<\/strong>S\u00ec, quel capitolo serve a comprendere soprattutto che se fosse vero come pochi ormai sostengono che l\u2019emissione monetaria non da\u2019 reddito, non si capisce perch\u00e9 il suo controllo abbia dato origine a conflitti continui nel corso della storia. Ma qui mi riferisco alla memoria pi\u00f9 recente: trovo incredibile che molti sostenitori della sovranit\u00e0 monetaria non citino mai il 1992 come una svolta storica cruciale e deleteria del nostro paese, il vero punto di rottura dopo il 1936. In quell\u2019anno \u2013 che \u00e8 anche l\u2019anno del panfilo Britannia, Amato nazionalizz\u00f2 l\u2019industria di Stato, e dunque l\u2019IRI e dunque le BIN, le banche di interesse nazionale azioniste della Banca d\u2019Italia. In questo modo surrettizio \u00e8 stata privatizzata la Banca centrale. Invece a destra e a sinistra si tende a non ricordare la svolta: a destra, perch\u00e9 per i nostalgici del fascismo l\u2019Italia ebbe sovranit\u00e0 monetaria solo fino alla fine della guerra; a sinistra perch\u00e9 i postcomunisti di Occhetto avevano trasformato il vecchio PCI in sinistra finanziaria e sono stati corresponsabili della distruzione di tutto quanto costruito in precedenza, ivi compresa privatizzazione dell\u2019industria di Stato.<\/p>\n<p><strong><em>D\u00a0<\/em><\/strong><em>Una memoria negativa. Ma questa memoria ha per\u00f2 anche un risvolto positivo: e cio\u00e8 che chi chiede la sovranit\u00e0 monetaria non sta proponendo fantasticherie impossibili, perch\u00e9 la svolta \u00e8 relativamente recente \u2026<\/em><\/p>\n<p><strong>R\u00a0<\/strong>Giustissimo, \u00e8 proprio quello che io sostengo. La sovranit\u00e0 monetaria ha una storia in Italia, persino nella versione radicale dell\u2019emissione diretta da parte dello Stato: in epoca monarchica, fascista e repubblicana, la Zecca ha stampato direttamente biglietti di stato a corso legale. Gli ultimi sono stati le 500 lire degli anni Settanta. Dunque non si sta proponendo di andare sulla luna, ma di riflettere sulle esperienze gi\u00e0 vissute, rielaborandole e migliorandole. E anche sul debito il discorso \u00e8 lo stesso: s\u00ec il debito \u00e8 alla fine una truffa, perch\u00e9 connesso alla mancanza di potere di emissione monetaria da parte dello Stato, perch\u00e9 gravato da immorale anatocismo, ma allora si pu\u00f2 recuperare il discorso che fu dei paesi in via di sviluppo degli anni Ottanta, \u2018rinegoziar\u00c8 il debito. Si possono trovare alleati nel mondo cristiano e musulmano, entrambi con alle spalle una tradizione antiusuraria su cui riflettere e da aggiornare. Solo cos\u00ec si riesce a diventare maggioranza. E beninteso, di nuovo, io non piego la lettura storica all\u2019emergenza di oggi, ma semplicemente la recupero per capire meglio le radici della realt\u00e0 che viviamo, e per contribuire alla sua trasformazione. \u00c8 un approccio non solo utile, ma indispensabile: la storia \u00e8 dalla nostra parte.<\/p>\n<p>http:\/\/www.italiasociale.net\/immagini13\/2013-12-30-2.jpg<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>LE FRASI<\/strong><\/p>\n<p>&#8220;<em>il liberismo va comunque rideclinato, e anche chi \u00e8 contro il liberismo deve impegnarsi in questo senso: bisogna distinguere tra liberismo d&#8217;impresa produttiva e liberismo finanziario. Il primo ha una sua legittimit\u00e0, tale anche perch\u00e9 normato e in permanente dialettica con i sindacati e i governi. Il secondo tipo di liberismo naviga invece nell&#8217;assoluto vuoto normativo, \u00e8 una attivit\u00e0 borderline tra furbizia, truffa, guadagni comunque illeciti<\/em>&#8221;<\/p>\n<p>&#8220;<em>Mieli ultimamente \u00e8 venuto un paio di volte a Teramo, una volta per parlare della falsificazione della storia col sindaco Brucchi: peccato che io stavo a Roma, mi sarebbe piaciuto ascoltarlo. Comunque, tornando a Omnibus, oggi come oggi bisogna seguire il Mieli degli anni Novanta. Trasversalit\u00e0 sociale tra produttori, e politica tra destra e sinistra. La fabbrica Trombari dei primi anni Settanta su cui ironizzava Ivan Della Mea, con l&#8217;imprenditore ex partigiano pronto a sparare sugli operai in sciopero, non esiste pi\u00f9 nemmeno come parto della fantasia artistica di quel cantautore: \u00e8 morta con la crisi, come tante altre<\/em>\u00a0&#8221;<\/p>\n<p>&#8220;<em>uscire dall&#8217;euro pu\u00f2 diventare una mera operazione di depistaggio della rabbia popolare, se a questa misura, assolutamente legittima ove non ci siano alternative, non se ne accompagna un&#8217;altra, e cio\u00e8 il ritorno in mani pubbliche della Banca d&#8217;Italia.<\/em>&#8221;<\/p>\n<p>&#8220;<em>trovo incredibile che molti sostenitori della sovranit\u00e0 monetaria non citino mai il 1992 come una svolta storica cruciale e deleteria del nostro paese, il vero punto di rottura dopo il 1936. In quell\u2019anno \u2013 che \u00e8 anche l\u2019anno del panfilo Britannia, Amato nazionalizz\u00f2 l\u2019industria di Stato, e dunque l\u2019IRI e dunque le BIN, le banche di interesse nazionale azioniste della Banca d\u2019Italia. In questo modo surrettizio \u00e8 stata privatizzata la Banca centrale.<\/em>&#8221;<\/p>\n<p>&#8220;<em>La sovranit\u00e0 monetaria ha una storia in Italia, persino nella versione radicale dell\u2019emissione diretta da parte dello Stato: in epoca monarchica, fascista e repubblicana, la Zecca ha stampato direttamente biglietti di stato a corso legale. Gli ultimi sono stati le 500 lire degli anni Settanta. Dunque non si sta proponendo di andare sulla luna, ma di riflettere sulle esperienze gi\u00e0 vissute, rielaborandole e migliorandole<\/em>&#8221;<\/p>\n<p>&#8220;<em>preferisco di gran lunga un liberale alla Mackenzie che uno di quei noiosi &#8216;marxisti&#8217; che pretendono che la crisi scoppiata nel 2008 nelle viscere della Lehman Bank e degli imbrogli finanziari sia una crisi da sovrapproduzione.<\/em>&#8221;<\/p>\n<p>&nbsp;<\/p>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/10\/giovanna-canzano-intervista-claudio-moffa-sul-suo-ultimo-libro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/10\/giovanna-canzano-intervista-claudio-moffa-sul-suo-ultimo-libro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Per rompere la gabbia del debito \u2026 Produttori di tutto il mondo unitevi D\u00a0Nel suo ultimo libro ci sono molte affermazioni &#8216;forti&#8217;. Forse quella di maggiore impatto \u00e8 &#8220;libera impresa in Stato padrone dell&#8217;emissione monetaria&#8221;. Ma lei \u00e8 diventato liberista?http:\/\/www.italiasociale.net\/immagini13\/2013-12-30-1.jpg R\u00a0No, continuo a pensare che il modello migliore per il nostro paese sia un&#8217;economia mista, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23284,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,57],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23283"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23283"}],"version-history":[{"count":15,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23283\/revisions"}],"predecessor-version":[{"id":23310,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23283\/revisions\/23310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/23284"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}