{"id":233081,"date":"2024-08-25T15:30:00","date_gmt":"2024-08-25T13:30:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=233081"},"modified":"2024-08-30T13:22:04","modified_gmt":"2024-08-30T11:22:04","slug":"il-pranzo-della-domenica-alberto-de-lazzari-pane-amore-e-fantasia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/25\/il-pranzo-della-domenica-alberto-de-lazzari-pane-amore-e-fantasia\/","title":{"rendered":"IL PRANZO DELLA DOMENICA \/ CON ALBERTO DE LAZZARI PANE, AMORE E FANTASIA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"885\" height=\"942\" class=\"wp-image-233082\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/albertodelazzari.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/albertodelazzari.jpg 885w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/albertodelazzari-282x300.jpg 282w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/albertodelazzari-768x817.jpg 768w\" sizes=\"(max-width: 885px) 100vw, 885px\" \/><\/p>\n\n\n\n<p>di <strong>Raffaele Polo<\/strong> ______<\/p>\n\n\n\n<p>\u00c8 l\u00ec, in un angolo, gli ospiti del pranzo di nozze sono andati via in festosa animazione, lui ha lavorato incessantemente, ha prodotto decine e decine di caricature e adesso sorseggia una birra e mi invita a fargli compagnia.&nbsp; <\/p>\n\n\n\n<p>\u00abFacciamo il pranzo della domenica? Va bene, ma a modo mio&#8230;\u00bb mi dice Alberto De Lazzari, con la sua inconfondibile e marcata cadenza lombarda. <\/p>\n\n\n\n<p>\u00abIl primo piatto che ti voglio offrire si chiama &#8216;piccoli semi&#8217;: \u00e8 un piatto ricco di semi piantato da mio padre nell&#8217;orticello di casa nostra&#8230; mio padre disegnava, a lui piaceva molto rilassarsi disegnando volti, alberi, case, chiese. Io avevo 3-4 anni e un giorno mio padre decise di comprare un kit da disegnatore al piccolo Alberto, dicendo &#8216;queste sono le tue matite, quando devi fare dei lavori, usa le tue matite&#8217;. Questi si chiamano &#8216;primi semi&#8217;: entrano nella terra,&nbsp; germogliano e favoriscono la nascita dei secondi piatti&#8230;\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Originale e inimitabile, Alberto continua, con lo sguardo ironico: \u00abSecondo piatto, la mia adolescenza negli anni Settanta era molto condizionata dall&#8217;appartenenza alla classe operaia, non era facile raggiungere un obiettivo e la mia strada \u00e8 stata sempre piena di incerti, alti e bassi e compagnia bella. Diciamo che per me, figlio di operai, la carriera di &#8216;artista&#8217; era praticamente proibita, non avevo agganci, non c&#8217;erano disponibilit\u00e0 economiche&#8230;<\/p>\n\n\n\n<p>A venti anni ho provato a fare diversi mestieri, assaggiando un po&#8217; il tonno, la carne, la pasta fatta in tutti i modi, ma in tutti i posti dove ho assaggiato qualcosa, mi hanno sempre detto: &#8216;Scusa, ma tu qui, non ti dispiacere, non c&#8217;entri niente&#8217;. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Tanti mestieri, tutti umili, ma nessuno duraturo. Ma ovunque abbia provato, non ho digerito nulla&#8230;\u00bb. <\/p>\n\n\n\n<p>Un sorso di birra, un saluto a chi lo ringrazia da lontano per la caricatura particolarmente azzeccata e Alberto passa ai contorni :\u00abDai 22 anni comincio coi &#8216;corsi&#8217; dedicati a disegno e pubblicit\u00e0: tante esperienze, non ne ho terminato nessuno, ma ricordo che ho provato due piatti difficili da digerire: uno durava 5 anni, era diurno, sette ore al giorno, l&#8217;altra pietanza \u00e8 stata il &#8216;Corso per disegnatori di cartoni animati&#8217; a Milano, ho resistito tre mesi. Era bello, si usava la moviola per i montaggi. Quindi diciamo che i segreti dell&#8217;animazione me li sono portati via, poi un biennio con storia dell&#8217;arte, psicologia, marketing. Ho scoperto che la grafica pubblicitaria, applicata a un target&nbsp; con&nbsp; l&#8217;aiuto della psicologia \u00e8 qualcosa di mostruoso, ce l&#8217;abbiamo attorno tutti, studiavamo la pubblicit\u00e0 per far venire il bisogno alla gente di un determinato prodotto di cui, fino a quel giorno, non avevano alcun interesse. Al professore ho detto: \u201cMa questo \u00e8 diabolico\u201d e il professore mi ha fulminato con lo sguardo, facendomi capire che, anche l\u00ec, non c&#8217;era posto per me&#8230;\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&nbsp;Approdato a Lecce per amore (sempre l&#8217;amore&#8230;) Alberto ci offre adesso il dessert: <\/p>\n\n\n\n<p>\u00abPer concludere, ho aperto il mio studio pubblicitario, l&#8217;ho mantenuto per anni, ho seguito i VIP di Lecce che dicono di essere VIP ma poi ti accorgi di quanto sono VIP quando devono saldarti il lavoro. Comunque, nonostante la tecnologia che continua a sopraffarci, ho ripreso la vecchia matita e mi son messo a fare le caricature alle feste, eventi e matrimoni, sto meglio, vivo una vita migliore e non rimpiango certo Berlusconi e Tremonti&#8230;\u00bb<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Alberto, nonostante tanti anni di permanenza salentina, hai sempre la spiccata cadenza lombarda. Come mai?<\/p>\n\n\n\n<p>\u00abA me, dove mi mettono, parlo sempre come mi han fatto mia mamma e mio pap\u00e0&#8230; Ma debbo dire che Lecce mi ha fatto innamorare, in tutti i sensi. Con il lavoro che hanno fatto gli scalpellini del Barocco, dovevo scegliere tra Firenze e Lecce, ma i fiorentini mi sono antipatici, quando sento parlare Renzi ho un brivido, ho fatto bene a scegliere Lecce.\u00bb<\/p>\n\n\n\n<p>Arriva una signora che vuole la sua caricatura, assieme all&#8217;adorato barboncino. Alberto non fa una grinza, mi strizza l&#8217;occhio e ricomincia il suo lavoro, la sua missione&#8230; <\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1587\" height=\"1600\" class=\"wp-image-233083\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/de-lazzari.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/de-lazzari.jpg 1587w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/de-lazzari-298x300.jpg 298w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/de-lazzari-1016x1024.jpg 1016w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/de-lazzari-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/de-lazzari-768x774.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/de-lazzari-1524x1536.jpg 1524w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/de-lazzari-60x60.jpg 60w\" sizes=\"(max-width: 1587px) 100vw, 1587px\" \/><\/p>\n\n\n\n<p>______ <\/p>\n\n\n\n<p><strong>( 14 \u2010 continua )<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/25\/il-pranzo-della-domenica-alberto-de-lazzari-pane-amore-e-fantasia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/25\/il-pranzo-della-domenica-alberto-de-lazzari-pane-amore-e-fantasia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo ______ \u00c8 l\u00ec, in un angolo, gli ospiti del pranzo di nozze sono andati via in festosa animazione, lui ha lavorato incessantemente, ha prodotto decine e decine di caricature e adesso sorseggia una birra e mi invita a fargli compagnia.&nbsp; \u00abFacciamo il pranzo della domenica? Va bene, ma a modo mio&#8230;\u00bb mi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":233082,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233081"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=233081"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233081\/revisions"}],"predecessor-version":[{"id":233086,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233081\/revisions\/233086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/233082"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=233081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=233081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=233081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}