{"id":233129,"date":"2024-08-24T12:24:00","date_gmt":"2024-08-24T10:24:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=233129"},"modified":"2024-08-24T12:24:04","modified_gmt":"2024-08-24T10:24:04","slug":"report-della-finanza-su-controlli-taxi-e-navette","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/24\/report-della-finanza-su-controlli-taxi-e-navette\/","title":{"rendered":"REPORT DELLA FINANZA SU CONTROLLI TAXI E NAVETTE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"599\" class=\"wp-image-233130\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/gf1ok.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/gf1ok.jpg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/gf1ok-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/gf1ok-768x511.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n\n\n\n<p>I finanzieri del Comando Provinciale di Lecce, in considerazione dell\u2019incremento dei flussi turistici che si registrano nella stagione estiva, hanno intensificato l\u2019attivit\u00e0 a contrasto dell\u2019economia sommersa anche in materia di servizi di navette e di taxi non autorizzati lungo tutto il tratto costiero salentino.<\/p>\n\n\n\n<p>Le Fiamme Gialle della Compagnia di Gallipoli e delle Tenenze di Tricase, Casarano e Porto Cesareo nell\u2019ultimo periodo hanno individuato e sottoposto a controllo circa 100 veicoli adibiti al trasporto di persone ed accertato nei confronti di 17 soggetti l\u2019esercizio abusivo di noleggio con conducente.<\/p>\n\n\n\n<p>Si tratta in prevalenza di soggetti sconosciuti al fisco, che esercitano l\u2019attivit\u00e0 in assenza di qualsivoglia autorizzazione, del tutto inottemperanti agli obblighi di natura fiscale e contributiva. Per stabilire l\u2019esatta natura del servizio reso dai conducenti controllati, i militari hanno raccolto le dichiarazioni dei turisti trasportati a bordo delle predette navette.<\/p>\n\n\n\n<p>Parallelamente, sono in corso approfondimenti fiscali finalizzati alla ricostruzione del volume di affari dei soggetti verbalizzati esercenti l\u2019attivit\u00e0 economica in modo abituale, al fine di procedere alla tassazione dei proventi conseguiti grazie all\u2019attivit\u00e0 abusiva scoperta.<\/p>\n\n\n\n<p>I primi riscontri, anche mediante l\u2019acquisizione di dati extra-contabili nonch\u00e9 rilevamenti delle zone ZTC e ZTL insistenti presso i maggiori scali aeroportuali pugliesi, hanno consentito di constatare e di segnalare ai competenti uffici finanziari, a seguito di approfondita verifica fiscale, elementi positivi di reddito non dichiarati pari a circa 270.000 euro.<\/p>\n\n\n\n<p>L\u2019attivit\u00e0 delle Fiamme Gialle, che si inquadra nel pi\u00f9 ampio dispositivo di controllo del territorio predisposto e coordinato dal Comando Provinciale di Lecce, proseguir\u00e0 per tutta la stagione estiva al fine di contrastare efficacemente le varie forme di abusivismo ai danni dell\u2019economia sana e della concorrenza leale di mercato, anche a tutela dei numerosi visitatori che si recano nei Comuni della Provincia a pi\u00f9 alta vocazione turistica.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/24\/report-della-finanza-su-controlli-taxi-e-navette\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/24\/report-della-finanza-su-controlli-taxi-e-navette\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I finanzieri del Comando Provinciale di Lecce, in considerazione dell\u2019incremento dei flussi turistici che si registrano nella stagione estiva, hanno intensificato l\u2019attivit\u00e0 a contrasto dell\u2019economia sommersa anche in materia di servizi di navette e di taxi non autorizzati lungo tutto il tratto costiero salentino. Le Fiamme Gialle della Compagnia di Gallipoli e delle Tenenze di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":233130,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233129"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=233129"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233129\/revisions"}],"predecessor-version":[{"id":233131,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233129\/revisions\/233131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/233130"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=233129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=233129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=233129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}