{"id":233404,"date":"2024-08-30T15:47:17","date_gmt":"2024-08-30T13:47:17","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=233404"},"modified":"2024-08-30T15:47:21","modified_gmt":"2024-08-30T13:47:21","slug":"report-dei-carabinieri-su-arresto-per-droga-a-tricase","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/30\/report-dei-carabinieri-su-arresto-per-droga-a-tricase\/","title":{"rendered":"REPORT DEI CARABINIERI SU ARRESTO PER DROGA A TRICASE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"735\" height=\"495\" class=\"wp-image-233405\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/moadesso.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/moadesso.jpg 735w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/08\/moadesso-300x202.jpg 300w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/><\/p>\n\n\n\n<p>Sarebbe un uomo del luogo che, nella tarda serata di ieri, \u00e8 stato arrestato nella flagranza di reato dai Carabinieri della Stazione di Specchia, poich\u00e9 ritenuto presunto responsabile di detenzione ai fini di spaccio di sostanze stupefacenti e resistenza a pubblico ufficiale.<br>I militari dell\u2019Arma hanno fermato un\u2019autovettura, durante un posto di controllo, poich\u00e9 insospettiti dall\u2019atteggiamento dell\u2019occupante. Effettuata un\u2019ispezione approfondita del veicolo, i Carabinieri hanno rinvenuto, occultato all\u2019interno della tasca porta oggetti dello sportello lato guida, un involucro di cellophane contenente sostanza presumibilmente stupefacente del tipo cocaina dal peso dii 100 grammi circa.<\/p>\n\n\n\n<p>Colto in flagranza, l\u2019uomo \u00e8 riuscito ad avviare l\u2019autovettura e a darsi a precipitosa fuga. Nella concitazione, un Carabiniere \u00e8 restato impigliato per qualche secondo nella portiera ed \u00e8 stato trascinato per alcuni metri procurandosi una contusione ad entrambe le ginocchia. <\/p>\n\n\n\n<p>Immediato l\u2019intervento dei colleghi e successivamente del 118. <\/p>\n\n\n\n<p>Ne \u00e8 nato un inseguimento nel corso del quale l\u2019uomo ha attraversato le vie del centro cittadino a folle velocit\u00e0 e controsenso andando a collidere con un palo della pubblica illuminazione. <\/p>\n\n\n\n<p>Per lui la corsa terminava in via Sigismondo Castromediano di Tricase allorquando veniva bloccato dai militari.<br>Constatato ci\u00f2, i militari hanno esteso la perquisizione anche all\u2019abitazione dell\u2019uomo, rinvenendo ulteriori 40 grammi del tipo cocaina, 12 grammi circa e 12 spinelli di altra sostanza stupefacente verosimilmente marijuana, nonch\u00e9 materiale per il confezionamento e due bilancini di precisione.<br>La droga sequestrata sar\u00e0 campionata ed analizzata dal Laboratorio di Analisi delle Sostanze<br>Stupefacenti del Comando Provinciale di Taranto per le rituali verifiche qualitative e ponderali.<br>Il giovane, come disposto dal P.M. di turno presso la Procura della Repubblica di Lecce che conduce le indagini, \u00e8 stato arrestato e condotto presso la Casa Circondariale Borgo San Nicola del capoluogo salentino.<br>Si evidenzia che, essendo il procedimento penale nella fase preliminare, la persona arrestata \u00e8 da ritenersi sottoposta alle indagini e quindi presunta innocente fino a sentenza definitiva.<br>Lecce, 30.08.2024.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/30\/report-dei-carabinieri-su-arresto-per-droga-a-tricase\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/08\/30\/report-dei-carabinieri-su-arresto-per-droga-a-tricase\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Sarebbe un uomo del luogo che, nella tarda serata di ieri, \u00e8 stato arrestato nella flagranza di reato dai Carabinieri della Stazione di Specchia, poich\u00e9 ritenuto presunto responsabile di detenzione ai fini di spaccio di sostanze stupefacenti e resistenza a pubblico ufficiale.I militari dell\u2019Arma hanno fermato un\u2019autovettura, durante un posto di controllo, poich\u00e9 insospettiti dall\u2019atteggiamento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":233405,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233404"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=233404"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233404\/revisions"}],"predecessor-version":[{"id":233406,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/233404\/revisions\/233406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/233405"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=233404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=233404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=233404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}