{"id":23364,"date":"2014-01-11T08:54:25","date_gmt":"2014-01-11T08:54:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23364"},"modified":"2014-01-11T08:59:29","modified_gmt":"2014-01-11T08:59:29","slug":"23364","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/11\/23364\/","title":{"rendered":"I DIFENSORI DELLA PATRIA IN GALERA, GLI INCAPACI E I DISONESTI AL GOVERNO"},"content":{"rendered":"<p><span style=\"font-family: 'Times New Roman'\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/Maro.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/Maro-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-23366\" \/><\/a>\u201cL\u2019incredibile vicenda che sta ancora bloccando in\u00a0\u00a0India i due fanti di marina pugliesi Salvatore Girone e Massimiliano Latorre, rei di avere fatto il loro dovere di Soldati in territorio italiano qual \u00e8 una nave battente la nostra bandiera in acque internazionali, invece di avviarsi a soluzione come ci \u00e8 stato ripetutamente fatto credere, sta ingarbugliandosi sempre di pi\u00f9. &#8221; Questo \u00e8<\/span>\u00a0quanto ha dichiarato<span style=\"font-family: 'Times New Roman'\">\u00a0i<\/span>l Vice-Presidente vicario del Gruppo PDL\/FI alla Regione Puglia erio Congedo in una nota. Poi aggiunge &#8221; <span style=\"font-family: 'Times New Roman'\">A nulla, peraltro, \u00e8 valso il loro gesto di riconsegnarsi ai loro carcerieri quando \u00e8 stato loro richiesto, pur essendo tornati al sicuro alle loro famiglie, visto e considerato che rischia di prospettarsi per loro addirittura un\u2019imputazione passibile di pena di morte.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'\">A fronte di questa autentica umiliazione della nostra Nazione, l\u2019azione del nostro Governo, appare sempre pi\u00f9 debole, inefficace e rassegnata.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'\">Occorre pertanto una mobilitazione molto pi\u00f9 forte di quella che evidentemente finora non \u00e8 bastata. Il Consiglio della Regione di cui sono figli questi valorosi Servitori della Patria, che con la loro dignit\u00e0 stanno dando onore alla loro Terra, non pu\u00f2 a tal riguardo non assumere un ruolo di punta, ribadendo con ancor maggiore determinazione quanto gi\u00e0 ha unanimemente sostenuto.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'\">Propongo, pertanto, un Consiglio Regionale monotematico, che mobiliti l\u2019intera comunit\u00e0 pugliese, sia perch\u00e8 giunga pi\u00f9 forte ai nostri due mar\u00f2 la solidariet\u00e0 della loro Terra, sia per lanciare al nostro Governo nazionale un invito fermo ad un\u2019azione pi\u00f9 incisiva per il loro ritorno in Patria.\u201d<\/span><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/11\/23364\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/11\/23364\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u201cL\u2019incredibile vicenda che sta ancora bloccando in\u00a0\u00a0India i due fanti di marina pugliesi Salvatore Girone e Massimiliano Latorre, rei di avere fatto il loro dovere di Soldati in territorio italiano qual \u00e8 una nave battente la nostra bandiera in acque internazionali, invece di avviarsi a soluzione come ci \u00e8 stato ripetutamente fatto credere, sta ingarbugliandosi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":23366,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23364"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23364"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23364\/revisions"}],"predecessor-version":[{"id":23370,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23364\/revisions\/23370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/23366"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}