{"id":234192,"date":"2024-09-24T14:19:52","date_gmt":"2024-09-24T12:19:52","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=234192"},"modified":"2024-09-24T14:32:21","modified_gmt":"2024-09-24T12:32:21","slug":"la-polemica-gli-alberi-non-sono-pericolosi-gli-stupidi-si","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/09\/24\/la-polemica-gli-alberi-non-sono-pericolosi-gli-stupidi-si\/","title":{"rendered":"LA POLEMICA \/ GLI ALBERI NON SONO PERICOLOSI, GLI STUPIDI SI&#8217;"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"936\" height=\"673\" class=\"wp-image-234193\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/09\/461160169_822985776716146_2283244511849382291_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/09\/461160169_822985776716146_2283244511849382291_n.jpg 936w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/09\/461160169_822985776716146_2283244511849382291_n-300x216.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/09\/461160169_822985776716146_2283244511849382291_n-768x552.jpg 768w\" sizes=\"(max-width: 936px) 100vw, 936px\" \/><\/p>\n\n\n\n<p>Riceviamo dal Coordinamento per gli Alberi e il Verde Urbano Lecce e volentieri pubblichiamo il seguente comunicato ______<\/p>\n\n\n\n<p>Il <a href=\"https:\/\/www.facebook.com\/CoordinamentoAlberiVerdeUrbanoLecce?__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=-]K-R\">Coordinamento per gli Alberi e il Verde Urbano Lecce<\/a> non pu\u00f2 fare a meno di osservare con preoccupazione la sintesi semplicistica e fuorviante che alcuni giornalisti continuano a utilizzare nei propri articoli ogni qual volta si verifica il cedimento di un albero di pino in citt\u00e0:<\/p>\n\n\n\n<p>i pini sono pericolosi e vanno sostituiti.<\/p>\n\n\n\n<p>Il rischio di cedimento e caduta di grandi alberi allarma tutti ma la gestione del rischio non coincide con l&#8217;eliminazione a prescindere in base alla specie arborea (pino nello specifico). Essa si attua con un serio monitoraggio dello stato di salute dei grandi alberi cittadini, che debbono essere osservati anche sondando l&#8217;apparato radicale, registrando i lavori stradali che possano aver compromesso la stabilit\u00e0 della pianta, rimuovendo bitume, cemento ed altri materiali in prossimit\u00e0 di tronco e radici, allargando e adeguando le aiuole, preferendo materiali traspiranti per le zone di calpestio e tanto altro ancora.<\/p>\n\n\n\n<p>L&#8217;albero che ha ceduto recentemente in via Siracusa a Lecce mostrava un apparato radicale totalmente compromesso, a causa di attacco fungino, e alla base del tronco era presente materiale edilizio (malta o calce), di certo nocivo per la salute dell&#8217;albero.<\/p>\n\n\n\n<p>In pi\u00f9 non sappiamo se esso sia stato interessato in passato da interventi pubblici compiuti in prossimit\u00e0 delle radici, che potrebbero averne innescato il processo di deterioramento.<\/p>\n\n\n\n<p>Come gi\u00e0 abbiamo pi\u00f9 volte sollecitato e proposto per iscritto alla precedente amministrazione, consideriamo il monitoraggio programmato degli alberi in citt\u00e0 e la gestione del rischio una prassi imprescindibile al fine di individuare per tempo situazioni pericolose per la comunit\u00e0 ed evitare pure le facili e pericolose generalizzazioni atte a giustificare preventivi abbattimenti di massa.<\/p>\n\n\n\n<p>Ciclicamente alcuni giornalisti e testate disinformate ripropongono i pi\u00f9 stantii e superati luoghi comuni sugli alberi, ignorando l&#8217;ampia letteratura scientifica e le tecniche diffusamente adottate per la tutela di un patrimonio indispensabile e la sicurezza di persone e cose.<\/p>\n\n\n\n<p>Ciclicamente torniamo a scrivere e ribadire che gli alberi non sono pericolosi, l&#8217;umana superficialit\u00e0 s\u00ec.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/coordinamentoalberieverdeurbanolecce?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#coordinamentoalberieverdeurbanolecce<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/alberiincitt%C3%A0?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#alberiincitt\u00e0<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/gestionedelrischio?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#gestionedelrischio<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/stoptaglioalberi?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#stoptaglioalberi<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/arboricoltura?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#arboricoltura<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/polverisottili?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#polverisottili<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/biodiversita?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#biodiversita<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/isoledicalore?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#isoledicalore<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/desertoincitt%C3%A0?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#desertoincitt\u00e0<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/lecce2024?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#lecce2024<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/alberibenecomune?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#alberibenecomune<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/benicomuni?__eep__=6&amp;__cft__[0]=AZX-FVWhwgf-NogUnwC2drkPECChsYWQ-CtAHwKynf0gs_IjLchOYXeRouoirfxieML3hR3LxhtIdq4r_X8uhibepQaYATMySAvvS8ovsfX1TIukGVGJ4XTUy8aONFfxNdgtKil3wGRB4lZCxtrFj6u9RCAB6e0aTRKOHd5yZkeqeg&amp;__tn__=*NK-R\">#benicomuni<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/09\/24\/la-polemica-gli-alberi-non-sono-pericolosi-gli-stupidi-si\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/09\/24\/la-polemica-gli-alberi-non-sono-pericolosi-gli-stupidi-si\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo dal Coordinamento per gli Alberi e il Verde Urbano Lecce e volentieri pubblichiamo il seguente comunicato ______ Il Coordinamento per gli Alberi e il Verde Urbano Lecce non pu\u00f2 fare a meno di osservare con preoccupazione la sintesi semplicistica e fuorviante che alcuni giornalisti continuano a utilizzare nei propri articoli ogni qual volta si [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":234193,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/234192"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=234192"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/234192\/revisions"}],"predecessor-version":[{"id":234194,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/234192\/revisions\/234194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/234193"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=234192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=234192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=234192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}