{"id":234299,"date":"2024-09-28T15:04:42","date_gmt":"2024-09-28T13:04:42","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=234299"},"modified":"2024-09-28T15:04:46","modified_gmt":"2024-09-28T13:04:46","slug":"report-dei-carabinieri-su-sequestro-generi-alimentari-conservati-male","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/09\/28\/report-dei-carabinieri-su-sequestro-generi-alimentari-conservati-male\/","title":{"rendered":"REPORT DEI CARABINIERI SU SEQUESTRO GENERI ALIMENTARI CONSERVATI MALE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"895\" height=\"565\" class=\"wp-image-234300\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/09\/ccpaese.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/09\/ccpaese.png 895w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/09\/ccpaese-300x189.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/09\/ccpaese-768x485.png 768w\" sizes=\"(max-width: 895px) 100vw, 895px\" \/><\/p>\n\n\n\n<p>I Carabinieri di Tricase, insieme al NAS di Lecce, hanno ispezionato un negozio alimentare. Riscontrate gravi violazioni delle normative sanitarie. Scoperti 18 kg di alimenti in cattivo stato di conservazione, decongelati e contaminati. L&#8217;attivit\u00e0 era priva di autorizzazioni.<\/p>\n\n\n\n<p><br>Nella mattinata di ieri, i Carabinieri della Stazione di Tricase, unitamente a personale specializzato dei Carabinieri del NAS di Lecce, hanno effettuato servizi di controllo del territorio, nel corso dei quali sono stati ispezionati anche vari esercizi commerciali.<\/p>\n\n\n\n<p><br>Durante l\u2019ispezione di un negozio alimentare \u00e8 emersa una grave violazione delle normative sanitarie. \u00c8 stato accertato, che all&#8217;interno di un pozzetto congelatore spento, il titolare deteneva per la successiva vendita al pubblico 18 kg di alimenti in cattivo stato di conservazione, completamente decongelati, ammuffiti, invasi da parassiti e insudiciati. Immediata \u00e8 stata la segnalazione dei Carabinieri alla Procura della Repubblica del capoluogo salentino per il reato di detenzione di alimenti in cattivo stato di conservazione.<br><\/p>\n\n\n\n<p>In aggiunta, sono state elevate sanzioni amministrative per un totale di oltre 11.000 euro, in quanto il titolare aveva avviato l&#8217;attivit\u00e0 commerciale in modo totalmente abusivo, privo di qualsivoglia autorizzazione amministrativa e sanitaria, e senza aver adottato le procedure di autocontrollo previste dalla normativa vigente.<br>Gli alimenti sono stati sequestrati penalmente e affidati in custodia al NAS di Lecce, che ha disposto la diffida alla prosecuzione dell&#8217;attivit\u00e0 commerciale. Inoltre, le autorit\u00e0 amministrative e sanitarie sono state informate per le necessarie azioni di competenza.<br>La sicurezza alimentare \u00e8 una priorit\u00e0 per i Carabinieri e per le autorit\u00e0 competenti, che continueranno a svolgere con rigore il proprio operato nel monitoraggio e controllo dei servizi alla cittadinanza.<br>\u00c8 importante sottolineare che la posizione dell\u2019indagato \u00e8 al vaglio dell\u2019Autorit\u00e0 Giudiziaria. Nonostante i gravi indizi di colpevolezza a suo carico, vale per lui il principio della presunzione di innocenza, pertanto non pu\u00f2 essere considerato colpevole sino alla condanna definitiva.<br>Lecce, 28 settembre 2024.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/09\/28\/report-dei-carabinieri-su-sequestro-generi-alimentari-conservati-male\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/09\/28\/report-dei-carabinieri-su-sequestro-generi-alimentari-conservati-male\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I Carabinieri di Tricase, insieme al NAS di Lecce, hanno ispezionato un negozio alimentare. Riscontrate gravi violazioni delle normative sanitarie. Scoperti 18 kg di alimenti in cattivo stato di conservazione, decongelati e contaminati. L&#8217;attivit\u00e0 era priva di autorizzazioni. Nella mattinata di ieri, i Carabinieri della Stazione di Tricase, unitamente a personale specializzato dei Carabinieri del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":234300,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/234299"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=234299"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/234299\/revisions"}],"predecessor-version":[{"id":234301,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/234299\/revisions\/234301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/234300"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=234299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=234299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=234299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}