{"id":236174,"date":"2024-11-15T16:38:00","date_gmt":"2024-11-15T15:38:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=236174"},"modified":"2024-11-15T17:46:01","modified_gmt":"2024-11-15T16:46:01","slug":"controlli-dei-carabinieri-sulla-sicurezza-dei-luoghi-di-lavoro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/15\/controlli-dei-carabinieri-sulla-sicurezza-dei-luoghi-di-lavoro\/","title":{"rendered":"CONTROLLI DEI CARABINIERI SULLA SICUREZZA DEI LUOGHI DI LAVORO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1189\" height=\"1535\" class=\"wp-image-236175\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/caralav.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/caralav.jpg 1189w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/caralav-232x300.jpg 232w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/caralav-793x1024.jpg 793w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/caralav-768x991.jpg 768w\" sizes=\"(max-width: 1189px) 100vw, 1189px\" \/><\/p>\n\n\n\n<p>Report del Comando Provinciale dei Carabinieri di Lecce ______ Diversi infortuni avvenuti in questo ultimo periodo nella nostra provincia soprattutto &#8211; nella fervente attivit\u00e0 in edilizia &#8211; hanno visto l\u2019intensificarsi dei controlli da parte del Nucleo Carabinieri Ispettorato del Lavoro di Lecce in collaborazione con il personale dell\u2019Arma Territoriale. Le verifiche si sono focalizzate soprattutto nel settore edile con particolare attenzione all\u2019osservanza della normativa in materia di tutela della salute e sicurezza sui luoghi di lavoro, senza tralasciare il rispetto delle regole in materia di lavoro e legislazione sociale. I controlli nel periodo in esame hanno riguardato ben 18 imprese edili dislocate nei comuni di Ugento, Casarano, Galatina, Lecce, Surbo e Squinzano risultate tutte irregolari. Su 42 posizioni lavorative verificate, 29 risultavano irregolari e 8 lavoratori erano sconosciuti alla P.A. poich\u00e9 \u201cin nero\u201d e privi di qualsiasi forma assicurativa, motivo per il quale sono stati emessi 4 provvedimenti di sospensione dell\u2019attivit\u00e0 imprenditoriale. Un ulteriore provvedimento di sospensione dell\u2019attivit\u00e0 imprenditoriale \u00e8 stato irrogato per gravi violazioni in materia di tutela della salute e sicurezza sui luoghi di lavoro. In totale, a seguito delle violazioni rilevate 16 imprenditori saranno denunciati all\u2019Autorit\u00e0 Giudiziaria, inoltre sono state comminate sanzioni amministrative per complessivi \u20ac 38.000 circa e ammende per \u20ac 103.000 circa. I controlli continueranno incessanti in tutti i settori, con un\u2019attenzione particolare a quello edile al fine di garantire la tutela della salute e la sicurezza nei luoghi di lavoro.<br>Lecce, 15 novembre 2024<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/15\/controlli-dei-carabinieri-sulla-sicurezza-dei-luoghi-di-lavoro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/15\/controlli-dei-carabinieri-sulla-sicurezza-dei-luoghi-di-lavoro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report del Comando Provinciale dei Carabinieri di Lecce ______ Diversi infortuni avvenuti in questo ultimo periodo nella nostra provincia soprattutto &#8211; nella fervente attivit\u00e0 in edilizia &#8211; hanno visto l\u2019intensificarsi dei controlli da parte del Nucleo Carabinieri Ispettorato del Lavoro di Lecce in collaborazione con il personale dell\u2019Arma Territoriale. Le verifiche si sono focalizzate soprattutto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":236175,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/236174"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=236174"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/236174\/revisions"}],"predecessor-version":[{"id":236176,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/236174\/revisions\/236176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/236175"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=236174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=236174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=236174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}