{"id":236557,"date":"2024-11-25T13:41:25","date_gmt":"2024-11-25T12:41:25","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=236557"},"modified":"2024-11-25T13:41:29","modified_gmt":"2024-11-25T12:41:29","slug":"questo-non-e-amore-la-polizia-di-stato-contro-la-violenza-sulle-donne","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/25\/questo-non-e-amore-la-polizia-di-stato-contro-la-violenza-sulle-donne\/","title":{"rendered":"&#8220;Questo non \u00e8 amore&#8221;. LA POLIZIA DI STATO CONTRO LA VIOLENZA SULLE DONNE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2031\" height=\"2048\" class=\"wp-image-236558\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/questo-non-e-amore.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/questo-non-e-amore.jpeg 2031w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/questo-non-e-amore-298x300.jpeg 298w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/questo-non-e-amore-1016x1024.jpeg 1016w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/questo-non-e-amore-150x150.jpeg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/questo-non-e-amore-768x774.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/questo-non-e-amore-1523x1536.jpeg 1523w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/11\/questo-non-e-amore-60x60.jpeg 60w\" sizes=\"(max-width: 2031px) 100vw, 2031px\" \/><\/p>\n\n\n\n<p>Comunicazione istituzionale della Polizia di Stato _______ <\/p>\n\n\n\n<p>In questo mese di novembre in occasione della Campagna permanente della Polizia di Stato &#8220;QUESTO NON E&#8217; AMORE\u201d contro la violenza di genere, operatori della Polizia di Stato specializzati sull\u2019argomento hanno preso parte a convegni e incontri in numerosissimi comuni della Provincia, anche con un ufficio mobile, il CAMPER simbolo della campagna, che oggi stazioner\u00e0 nelle principali piazze di Lecce e in prossimit\u00e0 delle scuole.<\/p>\n\n\n\n<p>Per quanto riguarda il bilancio dei provvedimenti emessi dal Questore, si \u00e8 registrato un notevole incremento rispetto al 2023 degli <strong>Ammonimenti <\/strong>per atti persecutori e violenza domestica.<\/p>\n\n\n\n<p>Tale aumento, relativo all\u2019attivit\u00e0 preventiva connessa agli ammonimenti per violenza domestica, si \u00e8 registrato in seguito all\u2019emanazione della Direttiva nr. 814 del 18 gennaio 2024 della Procura della Repubblica di Lecce, che dispone che la Divisione Anticrimine della Questure di Lecce riceva da tutte le forze di polizia presenti in provincia, le segnalazioni dei \u201creati spia\u201d della violenza domestica.<\/p>\n\n\n\n<p>Una volta ricevuta la segnalazione, gli operatori della suddetta Divisione effettuano gli accertamenti necessari per un\u2019approfondita istruttoria al fine dell\u2019eventuale emissione della misura dell\u2019ammonimento da parte del Questore.<\/p>\n\n\n\n<p>Per quanto riguarda il bilancio relativo ai risultati del locale Protocollo Zeus Finis-Terrae<a href=\"#_ftn1\" id=\"_ftnref1\">[1]<\/a>, al 31 Ottobre 2024 il numero dei soggetti ammoniti invitati a contattare Centri specialistici con cui sono in atto Protocolli di collaborazione e che si sono effettivamente presentati \u00e8 in costante aumento. Dall\u2019avvio del Protocollo, sono stati invitati ad aderire ai percorsi di recupero facoltativi 90 autori di condotte violente, 50 dei quali si sono effettivamente presentati.<\/p>\n\n\n\n<p>Lecce, 25 novembre 2024<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> Nel 2023 vi \u00e8 stata la sottoscrizione di un protocollo d\u2019intesa tra il Questore di Lecce e il Presidente di Medihospes Societ\u00e0 Cooperativa Onlus, conosciuto in ambito nazionale come protocollo Zeus e denominato in sede locale <strong>Protocollo Zeus Finis-Terrae<\/strong> per caratterizzarne il legame con il territorio, essendo la locuzione Finibus-Terrae utilizzata dagli antichi romani per individuare quel territorio della penisola italiana posto nella parte sud orientale. Tale protocollo ha lo scopo di fornire ai destinatari di provvedimenti di ammonimento del Questore, per atti persecutori e violenza domestica, servizi assistenziali con percorsi di consapevolezza e revisione critica degli agiti violenti, al fine di contenere al massimo i casi di recidiva in un\u2019ottica di maggiore tutela delle vittime.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/25\/questo-non-e-amore-la-polizia-di-stato-contro-la-violenza-sulle-donne\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/25\/questo-non-e-amore-la-polizia-di-stato-contro-la-violenza-sulle-donne\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Comunicazione istituzionale della Polizia di Stato _______ In questo mese di novembre in occasione della Campagna permanente della Polizia di Stato &#8220;QUESTO NON E&#8217; AMORE\u201d contro la violenza di genere, operatori della Polizia di Stato specializzati sull\u2019argomento hanno preso parte a convegni e incontri in numerosissimi comuni della Provincia, anche con un ufficio mobile, il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":236558,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/236557"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=236557"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/236557\/revisions"}],"predecessor-version":[{"id":236559,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/236557\/revisions\/236559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/236558"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=236557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=236557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=236557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}