{"id":237095,"date":"2024-12-06T17:24:00","date_gmt":"2024-12-06T16:24:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=237095"},"modified":"2024-12-09T11:26:31","modified_gmt":"2024-12-09T10:26:31","slug":"il-gasdotto-tap-ha-delle-crepe","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/06\/il-gasdotto-tap-ha-delle-crepe\/","title":{"rendered":"IL GASDOTTO TAP HA DELLE CREPE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1124\" height=\"775\" class=\"wp-image-237096\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/462585176_552189124399477_7212149274518492897_n.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/462585176_552189124399477_7212149274518492897_n.png 1124w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/462585176_552189124399477_7212149274518492897_n-300x207.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/462585176_552189124399477_7212149274518492897_n-1024x706.png 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/462585176_552189124399477_7212149274518492897_n-768x530.png 768w\" sizes=\"(max-width: 1124px) 100vw, 1124px\" \/><\/p>\n\n\n\n<p>di <strong>Giuseppe Puppo<\/strong>  _______<em><strong> &#8220;Clamoroso ma non troppo, visto che le criticit\u00e0 dell&#8217;installazione in mare era un punto fermo dei dubbi che aleggiavano tra gli addetti ai lavori. Come in un film di cui si \u00e8 visto il trailer il TAP non tradisce. Dalla procedura di &#8216;esclusione VIA&#8217; apparsa in questi giorni sul sito del Ministero dell&#8217;Ambiente, il TAP \u00e8 bisognoso di lavori di manutenzione in mare<\/strong><\/em>&#8220;.<\/p>\n\n\n\n<p>Comincia cos\u00ec una nota diffusa questa sera dal Collettivo No Tap di Melendugno, che cos\u00ec continua:<\/p>\n\n\n\n<p><strong><em>&#8220;Motivo? almeno 3 punti di crepe nel mantello di esterno e almeno 15 &#8216;campate libere&#8217;, ovvero 15 punti in cui il metanodotto non poggia sul fondale ed \u00e8 quindi soggetto alle vibrazioni e alle correnti. L&#8217;urgenza e la complessit\u00e0 dell&#8217;intervento di manutenzione \u00e8 dimostrato dalla stessa procedura aperta al Ministero. <\/em><\/strong><\/p>\n\n\n\n<p><em><strong>Il cromo VI, lo stermino degli ulivi, le emissioni fuggitive di metano tra quattro centri abitati scoperte un mese fa, ma siamo ancora sicuri che un gasdotto \u00e8 &#8216;solo un tubo&#8217;?&#8221;<\/strong><\/em>.<\/p>\n\n\n\n<p>&#8220;E&#8217; solo un tubo&#8221;, frase destinata ad essere tramandata ai posteri, lo disse Matteo Renzi a Lecce nel settembre 2017, cercando di minimizzare i lavori in corso d&#8217;opera.<\/p>\n\n\n\n<p>A proposito dell&#8217;allora presidente del Consiglio, i Salentini stanno ancora aspettando le riduzioni  sulle bollette che egli promise.<\/p>\n\n\n\n<p>Quelli che si opposero alla costruzione del gasdotto, stanno aspettando pure che si concluda il processo penale a carico dei vertici di Tap e dei loro esecutori dei lavori, che dopo quattro anni e passa \u00e8 ancora, proprio come le tubature, in alto mare, cos\u00ec giusto per capire se avevano ragione a voler chiedere di evitare un&#8217;opera da essi ritenuta inutile, dannosa e pericolosa, oppure se avevano torto, e scusate se \u00e8 poco.<\/p>\n\n\n\n<p>Intanto siamo andati a verificare la notizia &#8216;clamorosa&#8217; di oggi.<\/p>\n\n\n\n<p>E&#8217; vero. <\/p>\n\n\n\n<p>Sul sito del Ministero dell&#8217;Ambiente e della Sicurezza Energetica &#8211; sezione Valutazioni e Autorizzazioni Ambientali:&nbsp;VAS &#8211; VIA &#8211; AIA &#8211; Tap chiede di effettuare<strong> &#8220;Lavori di manutenzione della condotta offshore nell&#8217;area della scarpata continentale italiana esterna alle acque territoriali italiane&#8221;<\/strong>.<\/p>\n\n\n\n<p>Ci sono pure le relative documentazioni complete.<\/p>\n\n\n\n<p>Non abbiamo &#8211; non ho &#8211;  la competenza tecnica per stabilire da esse di che natura siano le &#8220;crepe&#8221; di cui parla il comunicato del Collettivo No Tap di Melendugno. <\/p>\n\n\n\n<p>Siamo preoccupati e basta.<\/p>\n\n\n\n<p>Se i responsabili  di Trans Adriatic Popeline potessero dirci qualcosa di pi\u00f9, dal momento che sul sito della multinazionale non c&#8217;\u00e8 nulla al riguardo, ma solo la loro discutibile informazione propagandistica, ci farebbero cosa gradita assai. ________<\/p>\n\n\n\n<p>L&#8217;APPROFODIMENTO nei nostri articoli del 15 e del 16 novembre scorsi<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"VHWChGnNmR\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/15\/236147\/\">E&#8217; RIPARTITO IL PROCESSO CONTRO TAP<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;E&#8217; RIPARTITO IL PROCESSO CONTRO TAP&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/15\/236147\/embed\/#?secret=89Pm0nNO6I#?secret=VHWChGnNmR\" data-secret=\"VHWChGnNmR\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"6IER9XD8te\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/16\/la-riflessione-il-gasdotto-tap-di-nuovo-al-centro-di-polemiche\/\">LA RIFLESSIONE \/ IL GASDOTTO TAP DI NUOVO AL CENTRO DI POLEMICHE<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;LA RIFLESSIONE \/ IL GASDOTTO TAP DI NUOVO AL CENTRO DI POLEMICHE&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/16\/la-riflessione-il-gasdotto-tap-di-nuovo-al-centro-di-polemiche\/embed\/#?secret=WwTKPgy6Bd#?secret=6IER9XD8te\" data-secret=\"6IER9XD8te\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p> <\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/06\/il-gasdotto-tap-ha-delle-crepe\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/06\/il-gasdotto-tap-ha-delle-crepe\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo _______ &#8220;Clamoroso ma non troppo, visto che le criticit\u00e0 dell&#8217;installazione in mare era un punto fermo dei dubbi che aleggiavano tra gli addetti ai lavori. Come in un film di cui si \u00e8 visto il trailer il TAP non tradisce. Dalla procedura di &#8216;esclusione VIA&#8217; apparsa in questi giorni sul sito del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":237096,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237095"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=237095"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237095\/revisions"}],"predecessor-version":[{"id":237099,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237095\/revisions\/237099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/237096"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=237095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=237095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=237095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}