{"id":237243,"date":"2024-12-12T00:02:00","date_gmt":"2024-12-11T23:02:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=237243"},"modified":"2024-12-10T15:05:35","modified_gmt":"2024-12-10T14:05:35","slug":"novita-editoriali-le-donne-i-cavalier-larme-gli-amori-le-cortesie-laudaci-imprese-canta-alessandro-romano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/12\/novita-editoriali-le-donne-i-cavalier-larme-gli-amori-le-cortesie-laudaci-imprese-canta-alessandro-romano\/","title":{"rendered":"NOVITA&#8217; EDITORIALI \/ LE DONNE, I CAVALIER, L&#8217;ARME, GLI AMORI, LE CORTESIE, L&#8217;AUDACI IMPRESE CANTA ALESSANDRO ROMANO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2048\" height=\"1556\" class=\"wp-image-237245\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/AR.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/AR.jpg 2048w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/AR-300x228.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/AR-1024x778.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/AR-768x584.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/AR-1536x1167.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/p>\n\n\n\n<p>di Raffaele Polo _______<\/p>\n\n\n\n<p>\u00c8 una vera e propria scommessa, questo <em><strong>&#8216;Fenicea&#8217;<\/strong><\/em> che, nel sottotitolo, svela il suo percorso: &#8216;Favola in ottava rima&#8217;. L&#8217;autore, <strong>Alessandro Romano<\/strong>, novello Ariosto, si cimenta nel non facile compito di realizzare un corposo volume (pagine 271, euro 18, Il Raggio Verde) che vuole essere il primo capitolo di una saga, scritta interamente in ottava rima, sulle orme dei poemi cavallereschi. In\u00a0 generi diversi che passano dal poema epico alla prosa come un moderno cantastorie innamorato. <\/p>\n\n\n\n<p>Ma ha un senso uno scritto cos\u00ec concepito, nella nostra attualit\u00e0?<\/p>\n\n\n\n<p>Alessandro \u00e8 convinto di s\u00ec, e invita tutti nell&#8217;Aula Consiliare del Municipio di Soleto, il giorno 15 dicembre dalle 17,30, alla presentazione del suo libro che prevede, in apertura, la proiezione del booktrailer e poi il dialogo con il Sindaco, Graziano Vantaggiato, la giornalista Antonietta Fulvio e Giuliana Paciolla, lettrice di audiolibri, speaker\u00a0 e doppiatrice.<\/p>\n\n\n\n<p>E non spaventi l&#8217;inusuale scritto: \u00e8 scorrevole e comprensibile, ricco di sollecitazioni e ammantato di un&#8217;atmosfera particolare che lko rende godibilissimo. Come il suo &#8216;incipit&#8217; che riportiamo integralmente:<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; All&#8217;inizio di Tutto era il Creatore.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;L&#8217;unica presenza nel Vuoto.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Era solo, ma scoppiava d&#8217;amore,<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; in un nulla silenzioso e immoto<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; dove non v&#8217;era alcun suono e odore,<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; in quel buio imperante e in moto.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; C&#8217;era solo Lui, con la sua Solitudine.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Come una condanna d&#8217;odio senza fine.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ecco: siamo entrati nel ritmo fascinoso delle ottave. E un mondo fantastico ci aspetta, pronto per essere scoperto anche in una realt\u00e0 altrimenti grigia e gelida come quello che ci circonda, ogni giorno della nostra vita&#8230; <\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"512\" height=\"714\" class=\"wp-image-237244\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/IMG-20241209-feni.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/IMG-20241209-feni.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/IMG-20241209-feni-215x300.jpg 215w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/12\/novita-editoriali-le-donne-i-cavalier-larme-gli-amori-le-cortesie-laudaci-imprese-canta-alessandro-romano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/12\/novita-editoriali-le-donne-i-cavalier-larme-gli-amori-le-cortesie-laudaci-imprese-canta-alessandro-romano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo _______ \u00c8 una vera e propria scommessa, questo &#8216;Fenicea&#8217; che, nel sottotitolo, svela il suo percorso: &#8216;Favola in ottava rima&#8217;. L&#8217;autore, Alessandro Romano, novello Ariosto, si cimenta nel non facile compito di realizzare un corposo volume (pagine 271, euro 18, Il Raggio Verde) che vuole essere il primo capitolo di una saga, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":237245,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237243"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=237243"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237243\/revisions"}],"predecessor-version":[{"id":237246,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237243\/revisions\/237246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/237245"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=237243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=237243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=237243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}