{"id":237283,"date":"2024-12-12T09:23:22","date_gmt":"2024-12-12T08:23:22","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=237283"},"modified":"2024-12-12T09:24:08","modified_gmt":"2024-12-12T08:24:08","slug":"disagi-patiti-dai-tifosi-giallorossi-a-roma-la-protesta-della-societa","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/12\/disagi-patiti-dai-tifosi-giallorossi-a-roma-la-protesta-della-societa\/","title":{"rendered":"DISAGI PATITI DAI TIFOSI GIALLOROSSI A ROMA, LA PROTESTA DELLA SOCIETA&#8217;"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"526\" height=\"523\" class=\"wp-image-237284\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/tifosi-lecce-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/tifosi-lecce-1.jpg 526w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/tifosi-lecce-1-300x298.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/tifosi-lecce-1-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/tifosi-lecce-1-60x60.jpg 60w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Nota ufficiale dell&#8217; U.S.Lecce _______ L&#8217;U.S. Lecce comunica che, in data odierna ha provveduto ad inoltrare agli organi competenti una nota nella quale sono stati evidenziati i ripetuti disagi patiti dai propri tifosi nella fase di accesso nel Settore Ospiti dello stadio Olimpico, in occasione della gara di campionato Roma &#8211; Lecce di sabato scorso. <\/p>\n\n\n\n<p>A preoccupare in particolar modo la scrivente \u00e8 stata la circostanza che, a subire tali disagi, sia<br>stata la stragrande maggioranza dei tifosi che hanno occupato l&#8217;intero Settore, compreso un elevato numero di famiglie con bambini. <\/p>\n\n\n\n<p>Nel manifestare il proprio disappunto per quanto accaduto, l\u2019U.S. Lecce ha chiesto che tutte le parti in causa (comprese le societ\u00e0 di calcio) si adoperino affinch\u00e9 si raggiunga un equilibrio tra la legittima necessit\u00e0 di garantire la sicurezza e l&#8217;incolumit\u00e0 pubblica e quella di assicurare<br>una partecipazione pi\u00f9 confortevole alle manifestazioni sportive.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/12\/disagi-patiti-dai-tifosi-giallorossi-a-roma-la-protesta-della-societa\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/12\/disagi-patiti-dai-tifosi-giallorossi-a-roma-la-protesta-della-societa\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nota ufficiale dell&#8217; U.S.Lecce _______ L&#8217;U.S. Lecce comunica che, in data odierna ha provveduto ad inoltrare agli organi competenti una nota nella quale sono stati evidenziati i ripetuti disagi patiti dai propri tifosi nella fase di accesso nel Settore Ospiti dello stadio Olimpico, in occasione della gara di campionato Roma &#8211; Lecce di sabato scorso. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":237284,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237283"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=237283"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237283\/revisions"}],"predecessor-version":[{"id":237285,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237283\/revisions\/237285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/237284"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=237283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=237283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=237283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}