{"id":23736,"date":"2014-01-21T19:35:56","date_gmt":"2014-01-21T19:35:56","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23736"},"modified":"2014-01-21T20:16:31","modified_gmt":"2014-01-21T20:16:31","slug":"gianfranco-fini-il-ventennio-e-la-destra-che-non-ce-di-valerio-melcore-2-puntata","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/21\/gianfranco-fini-il-ventennio-e-la-destra-che-non-ce-di-valerio-melcore-2-puntata\/","title":{"rendered":"GIANFRANCO FINI. IL VENTENNIO E LA DESTRA CHE NON C\u2019E\u2019 di Valerio Melcore 2\u00b0 puntata"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/Giorgio_almirante_con_fini.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/Giorgio_almirante_con_fini-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-23740\" \/><\/a>Fini ha deciso di presentare il suo libro anche a Cavallino, il mio paese.<br \/>\nL&#8217;amministrazione comunale mi ha fatto recapitare l&#8217;invito, come tante altre volte in occasioni della presentazione di questo o quel libro, solo che questa volta non posso mancare.<\/p>\n<p>Vorrei evitare di andare ad ascoltarlo, sopratutto in questo momento in cui Fini \u00e8 oggettivamente in difficolt\u00e0, provo un p\u00f2 di amarezza per lui.<\/p>\n<p>Senza alcun ruolo istituzionale o politico, abbandonato da tutti, non comprendo perch\u00e8 ha deciso di \u00a0impegnarsi nella presentazione di un libro nel quale per giustificare le proprie scelte, perdenti, \u00e8 costretto ad attaccare Berlusconi e a fare il mea culpa.<br \/>\nIn tutti questi anni in cui \u00e8 venuto nel Salento, quando riempiva le piazze e le sale, circondato da miriadi di personaggi locali che facevano a gara per farsi fotografare insieme al leader della destra italiana, ho evitato di cercarlo foss&#8217;anche solo per salutarlo.<br \/>\nAnche quando qualcuno mi riferiva che aveva chiesto di me.<br \/>\nMa mi chiedevo cosa avevo in comune con quest&#8217;uomo che era diventato uno dei pi\u00f9 importanti uomini politici italiani? Cosa avrei potuto chiedergli, cosa avrei potuto dirgli? La nostra visone della politica era molto diversa&#8230; e non da oggi.<br \/>\nFaceva impressione vedere il numero di fotografi, di giornalisti, di poliziotti, oltre allo\u00a0sciame di politici di tutte le risme che lo accompagnava prima e dopo aver tenuto un comizio o aver partecipato ad un incontro.<br \/>\nQualche volta l&#8217;ho seguito da lontano, ero contento per lui, per l&#8217;amico di un tempo al quale per\u00f2 nulla pi\u00f9 mi legava.<br \/>\nAvevo 20 anni e lui ne aveva 25, quando ci siamo conosciuti lui era \u00a0Segretario Nazionale del Fronte della Giovent\u00f9 credo che fosse il 1977, e io \u00a0ero stato nominato Segretario Provinciale del Fronte della Giovent\u00f9 da poco.<br \/>\nMi volle in Direzione Nazionale insieme a lui, e l\u00ec conobbi tanti amici, molti dei quali poi sono diventati importanti personaggi della vita politica italiana. Con uno di questi, Maurizio Gasparri ci siamo incontrati dopo qualche decennio e ci siamo abbracciati ricordando quelli che erano gli anni di piombo, tra lo sconcerto di quanti intorno a noi, deputati, consiglieri regionali, capicorrente, non riuscivano capire come mai tanta confidenza con un signore alla maggior parte di loro sconosciuto, si chiedevano chi fosse costui.<\/p>\n<p>Ma torniamo a Fini, dopo avermi fatto entrare nella Direzione Nazionale del FdG., mi disse chiaramente di imparare a fare i comizi perch\u00e8 da l\u00ec a 10 anni avrei dovuto fare il deputato. Io a Lecce, Brunetto a Brindisi, Francesco a Bari e cos\u00ec via.<\/p>\n<p>Ma il mio sogno non era certo quello di fare il deputato, a dire il vero a quell&#8217;epoca noi giovani del Fronte guardavamo con un certo sospetto, non solo i deputati del nostro partito ma anche i dirigenti.<br \/>\nI sogni che molti di noi cullavano erano altri, e d&#8217;altro canto quando i giovani smettono di sognare si avvicina il crepuscolo di un popolo.<\/p>\n<p>Erano sogni irrealizzabili? Si all&#8217;interno di quel partito, che viveva alla giornata non aveva le idee chiare non faceva elaborazione teorica, e si limitava a scimmiottare atteggiamenti e slogan che avevano fatto il loro tempo, era impossibile pensare che la destra potesse uscire dallo steccato dove si era fatta confinare.<\/p>\n<p>Continua&#8230;<\/p>\n<p>( nella foto da sx: Gianfranco Fini, Giorgio Almirante, Maurizio Gasparri e Almerigo Grilz)<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/21\/gianfranco-fini-il-ventennio-e-la-destra-che-non-ce-di-valerio-melcore-2-puntata\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/21\/gianfranco-fini-il-ventennio-e-la-destra-che-non-ce-di-valerio-melcore-2-puntata\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Fini ha deciso di presentare il suo libro anche a Cavallino, il mio paese. L&#8217;amministrazione comunale mi ha fatto recapitare l&#8217;invito, come tante altre volte in occasioni della presentazione di questo o quel libro, solo che questa volta non posso mancare. Vorrei evitare di andare ad ascoltarlo, sopratutto in questo momento in cui Fini \u00e8 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":23740,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23736"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23736"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23736\/revisions"}],"predecessor-version":[{"id":23742,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23736\/revisions\/23742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/23740"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}