{"id":237417,"date":"2024-12-16T13:54:07","date_gmt":"2024-12-16T12:54:07","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=237417"},"modified":"2024-12-16T13:54:36","modified_gmt":"2024-12-16T12:54:36","slug":"servizio-di-controllo-del-territorio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/16\/servizio-di-controllo-del-territorio\/","title":{"rendered":"SERVIZIO DI CONTROLLO DEL TERRITORIO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1201\" class=\"wp-image-237418\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-16-at-09.58.28.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-16-at-09.58.28.jpeg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-16-at-09.58.28-300x225.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-16-at-09.58.28-1024x769.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-16-at-09.58.28-768x576.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-16-at-09.58.28-1536x1153.jpeg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-16-at-09.58.28-400x300.jpeg 400w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p>Report della Questura di Lecce ________ <\/p>\n\n\n\n<p>Continuano i servizi straordinari di controllo del territorio nella Provincia di Lecce. Come deliberato in sede di Comitato Provinciale per l\u2019Ordine e la Sicurezza Pubblica e successivamente pianificato in sede di Tavolo Tecnico del Questore, negli ultimi 7 giorni si sono svolti i Servizi Interforze c.d. \u201cAlto Impatto\u201d.<\/p>\n\n\n\n<p>Tali servizi hanno&nbsp;la finalit\u00e0 di&nbsp;incrementare la sicurezza&nbsp;grazie alla presenza congiunta delle Forze dell\u2019Ordine ed alla loro sinergica azione sul territorio, prevenendo e reprimendo reati predatori e non solo.<\/p>\n\n\n\n<p><strong>Polizia di Stato, Arma dei Carabinieri e Guardia di Finanza <\/strong>hanno condotto una capillare e approfondita attivit\u00e0 di controllo a Taurisano, Casarano, Cutrofiano, Secl\u00ec, Aradeo, Gallipoli, Melissano, Salice Salentino, Trepuzzi, Monteroni, Nard\u00f2 Copertino, Galatone, Martano, Castrignano d\u00e8 Greci, Muro Leccese, Poggiardo, Tricase e Tiggiano.<\/p>\n\n\n\n<p>I controlli hanno spaziato in diversi ambiti, dal controllo del territorio, identificazione di persone appiedate e avventori di locali, al contrasto al traffico di sostanze stupefacenti, ai controlli amministrativi agli esercizi commerciali.<\/p>\n\n\n\n<p>In totale sono 4 gli arresti eseguiti in flagranza di reato di detenzione ai fini di spaccio di sostanza stupefacente, 3 gli arresti eseguiti in esecuzione di ordinanze dell\u2019A.G., 4 gli indagati a piede libero per traffico di stupefacenti e 2 per porto abusivo di armi, infine 15 le segnalazioni per uso personale di stupefacenti.<\/p>\n\n\n\n<p>Assidui anche i controlli amministrativi: 55 esercizi commerciali sono stati controllati dalle forze dell\u2019ordine.<\/p>\n\n\n\n<p>Massiccio il bilancio finale: 1869 persone identificate, 240 dei quali con precedenti penali e\/o di polizia, e 875 veicoli fermati.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/16\/servizio-di-controllo-del-territorio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/16\/servizio-di-controllo-del-territorio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report della Questura di Lecce ________ Continuano i servizi straordinari di controllo del territorio nella Provincia di Lecce. Come deliberato in sede di Comitato Provinciale per l\u2019Ordine e la Sicurezza Pubblica e successivamente pianificato in sede di Tavolo Tecnico del Questore, negli ultimi 7 giorni si sono svolti i Servizi Interforze c.d. \u201cAlto Impatto\u201d. Tali [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":237418,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237417"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=237417"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237417\/revisions"}],"predecessor-version":[{"id":237419,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237417\/revisions\/237419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/237418"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=237417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=237417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=237417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}