{"id":237509,"date":"2024-12-17T06:59:00","date_gmt":"2024-12-17T05:59:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=237509"},"modified":"2024-12-17T19:07:19","modified_gmt":"2024-12-17T18:07:19","slug":"una-panchina-rossa-a-cerfignano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/17\/una-panchina-rossa-a-cerfignano\/","title":{"rendered":"UNA PANCHINA ROSSA A CERFIGNANO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" class=\"wp-image-237510\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/images.jpeg\" alt=\"\"><\/p>\n\n\n\n<p>Dai promotori dell&#8217;iniziativa, riceviamo e volentieri pubblichiamo (nella foto un&#8217;immagine di repertorio) _______<\/p>\n\n\n\n<p>Sabato 21 dicembre&nbsp; ore 17.00 presso il comune di Cerfignano frazione di Santa Cesarea Terme sar\u00e0 inaugurata l\u2019istallazione della Panchina Rossa per ricordare le donne vittime di violenza.<\/p>\n\n\n\n<p>Seguiranno saluti e interventi dal Sindaco Dott. <strong>Pasquale Bleve<\/strong><\/p>\n\n\n\n<p>Presidente Associazione Anemos <strong>Anna Marsella<\/strong><\/p>\n\n\n\n<p>Dott.ssa <strong>Anna Leo<\/strong> sociologa. Mediatrice Penale, Penale Minorile. Scrittrice<\/p>\n\n\n\n<p>Avv. <strong>Antonio Mastrolia<\/strong><\/p>\n\n\n\n<p>Presidente <strong>Rossano Corvaglia<\/strong> responsabile consorzio welfare di Poggiardo<\/p>\n\n\n\n<p>Consigliere&nbsp; <strong>Salvatore Maggio<\/strong><\/p>\n\n\n\n<p>Assistente sociale\u00a0 <strong>Raffaele Ciriolo<\/strong> <\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"720\" height=\"720\" class=\"wp-image-237511\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0083.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0083.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0083-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0083-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0083-60x60.jpg 60w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n\n\n\n<p><br><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/17\/una-panchina-rossa-a-cerfignano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/17\/una-panchina-rossa-a-cerfignano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Dai promotori dell&#8217;iniziativa, riceviamo e volentieri pubblichiamo (nella foto un&#8217;immagine di repertorio) _______ Sabato 21 dicembre&nbsp; ore 17.00 presso il comune di Cerfignano frazione di Santa Cesarea Terme sar\u00e0 inaugurata l\u2019istallazione della Panchina Rossa per ricordare le donne vittime di violenza. Seguiranno saluti e interventi dal Sindaco Dott. Pasquale Bleve Presidente Associazione Anemos Anna Marsella [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":237510,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237509"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=237509"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237509\/revisions"}],"predecessor-version":[{"id":237512,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237509\/revisions\/237512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/237510"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=237509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=237509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=237509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}