{"id":237635,"date":"2024-12-20T12:00:00","date_gmt":"2024-12-20T11:00:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=237635"},"modified":"2024-12-20T16:08:02","modified_gmt":"2024-12-20T15:08:02","slug":"daspo-per-tifoso-del-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/20\/daspo-per-tifoso-del-lecce\/","title":{"rendered":"DASPO PER TIFOSO DEL LECCE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"480\" height=\"600\" class=\"wp-image-237636\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/per-bove-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/per-bove-1.jpg 480w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/per-bove-1-240x300.jpg 240w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>Report della Questura di Lecce _______<\/p>\n\n\n\n<p>La Polizia di Stato ha notificato un DASPO per i fatti occorsi durante la partita Lecce-Juventus, del 01 dicembre u.s.<\/p>\n\n\n\n<p>In tale occasione, infatti, furono diversi gli episodi di accensione e lancio in campo di artifizi pirotecnici da parte dei tifosi locali.<\/p>\n\n\n\n<p>Il personale DIGOS, a seguito dell\u2019attenta visione delle immagini registrate dal sistema di videosorveglianza dello stadio, ha individuato uno dei responsabili del lancio di un artifizio pirotecnico. Il soggetto, ventiduenne di Surbo, gi\u00e0 conosciuto agli uffici informativi come facente parte della tifoseria organizzata, \u00e8 stato deferito all\u2019autorit\u00e0 giudiziaria per lancio di artifizio pirotecnico e non potr\u00e0 accedere alle manifestazioni sportive per 3 anni.<\/p>\n\n\n\n<p>Lecce, 20.12.2024<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/20\/daspo-per-tifoso-del-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/20\/daspo-per-tifoso-del-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report della Questura di Lecce _______ La Polizia di Stato ha notificato un DASPO per i fatti occorsi durante la partita Lecce-Juventus, del 01 dicembre u.s. In tale occasione, infatti, furono diversi gli episodi di accensione e lancio in campo di artifizi pirotecnici da parte dei tifosi locali. Il personale DIGOS, a seguito dell\u2019attenta visione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":237636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237635"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=237635"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237635\/revisions"}],"predecessor-version":[{"id":237637,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237635\/revisions\/237637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/237636"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=237635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=237635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=237635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}