{"id":237727,"date":"2024-12-24T00:02:00","date_gmt":"2024-12-23T23:02:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=237727"},"modified":"2024-12-23T15:16:27","modified_gmt":"2024-12-23T14:16:27","slug":"scolpire-la-cartapesta-personale-di-dante-vincenti-da-venerdi-27","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/24\/scolpire-la-cartapesta-personale-di-dante-vincenti-da-venerdi-27\/","title":{"rendered":"&#8220;Scolpire la cartapesta&#8221;, PERSONALE DI DANTE VINCENTI DA VENERDI&#8217; 27"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1440\" height=\"1425\" class=\"wp-image-237728\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/29497465_1797669043687614_4700304241854513152_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/29497465_1797669043687614_4700304241854513152_n.jpg 1440w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/29497465_1797669043687614_4700304241854513152_n-300x297.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/29497465_1797669043687614_4700304241854513152_n-1024x1013.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/29497465_1797669043687614_4700304241854513152_n-768x760.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/29497465_1797669043687614_4700304241854513152_n-60x60.jpg 60w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/p>\n\n\n\n<p>di <strong>Raffaele Polo<\/strong> ________ Si apre venerd\u00ec 27 dicembre 2024 alle ore 19, nelle sale dell\u2019ex Conservatorio Sant\u2019Anna, in via Santa Maria del Paradiso 8, la mostra di scultura dell\u2019artista Dante Vincenti, promossa dall\u2019amministrazione comunale di Lecce.<\/p>\n\n\n\n<p>Antonio Manzo, operatore culturale e guida turistica che traccia un breve ritratto di Dante Vincenti.<\/p>\n\n\n\n<p>Definendolo \u00ab&#8230;Artista &#8220;nel cuore&#8221;.  \u00c8 da quell&#8217; organo vitale e sensibile che parte e prende forma la sua Arte, originale e riflessiva.\u00a0 Grazie alla sua bravura, le Opere di carta si arricchiscono di umanit\u00e0. Unica e profonda&#8230;\u00bb\u00a0<\/p>\n\n\n\n<p>Nato a Lecce l\u201911 giugno 1957, negli anni\u00a0 Settanta Dante Vincenti inizia la sua attivit\u00e0 artistica dedicandosi allo studio delle tecniche pittoriche e scultoree presso la scuola di disegno Maccagnani. Dopo aver conseguito il diploma al Liceo Artistico nel 1976, comincia a partecipare a numerose rassegne regionali e nazionali ottenendo consensi e riconoscimenti. Nel 1998 riprende l\u2019antica arte della xilografia entrando a far parte del gruppo \u201cArte Viva\u201d. Dal 1999 ad oggi \u00e8 totalmente impegnato nell\u2019arte della cartapesta attraverso una personale sperimentazione e una continua ricerca.<\/p>\n\n\n\n<p>L\u2019artista ha voluto conciliare l\u2019antica arte artigianale leccese con la plasticit\u00e0 di sinuose figure che incarnano soggetti maschili e femminili tipici della propria terra. \u00c8 arrivato cos\u00ec ad una produzione artistica di alta qualit\u00e0, di cura dei dettagli realizzando oggetti unici e irripetibili. Da molti anni \u00e8 presente alla fiera natalizia di San Lucia, tra i maestri pupari, ma nell\u2019esposizione all\u2019ex Conservatorio si potranno ammirare per la prima volta a Lecce le sue creazioni in cartapesta utilizzata come materiale al pari di chi usa il legno o il marmo per scolpire. Una materia povera come la carta che l\u2019artista riesce a sublimare in forme scultoree contemporanee infondendo una nuova vita: attingendo dalla letteratura, dal mito e dall\u2019attualit\u00e0 Dante Vincenti riesce a creare sculture e figurazioni che trattano temi e sentimenti universali.<\/p>\n\n\n\n<p>\u00abNelle sue opere \u2013 si legge nel testo del prof. Angelo Micello \u2013 confluiscono tutte le forme d\u2019arte: dalla pittura alla scultura, all\u2019architettura, alla musica, che il Vincenti utilizza magistralmente per creare l\u2019armonia dell\u2019opera. Le sue creazioni spaziano dalla realt\u00e0 al mito, dal figurativo all\u2019immaginativo. Vedi queste creature emergere lentamente ma con forza e con furia quasi volessero lentamente da quella carta che le imprigiona sulla base. <\/p>\n\n\n\n<p>Vedo spesso sparsi in bottega fusi di carta di giornali strettamente legati, che costituiscono gli elementi per le sue sculture. Neppure con la fantasia riusciresti a pensare che da quella cartastraccia possano nascere s\u00ec belle opere.\u00bb<\/p>\n\n\n\n<p>La mostra potr\u00e0 essere visitata tutti i giorni con ingresso libero dalle 10.30 alle 13 e dalle 16 alle 20.30.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1200\" height=\"1600\" class=\"wp-image-237729\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Dante-Vincenti-sacro-e-profano-2023.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Dante-Vincenti-sacro-e-profano-2023.jpeg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Dante-Vincenti-sacro-e-profano-2023-225x300.jpeg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Dante-Vincenti-sacro-e-profano-2023-768x1024.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Dante-Vincenti-sacro-e-profano-2023-1152x1536.jpeg 1152w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/24\/scolpire-la-cartapesta-personale-di-dante-vincenti-da-venerdi-27\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/24\/scolpire-la-cartapesta-personale-di-dante-vincenti-da-venerdi-27\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo ________ Si apre venerd\u00ec 27 dicembre 2024 alle ore 19, nelle sale dell\u2019ex Conservatorio Sant\u2019Anna, in via Santa Maria del Paradiso 8, la mostra di scultura dell\u2019artista Dante Vincenti, promossa dall\u2019amministrazione comunale di Lecce. Antonio Manzo, operatore culturale e guida turistica che traccia un breve ritratto di Dante Vincenti. Definendolo \u00ab&#8230;Artista &#8220;nel [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":237728,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237727"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=237727"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237727\/revisions"}],"predecessor-version":[{"id":237730,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237727\/revisions\/237730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/237728"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=237727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=237727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=237727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}