{"id":237735,"date":"2024-12-23T18:12:03","date_gmt":"2024-12-23T17:12:03","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=237735"},"modified":"2024-12-23T18:12:08","modified_gmt":"2024-12-23T17:12:08","slug":"chiuso-un-bar-di-otranto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/23\/chiuso-un-bar-di-otranto\/","title":{"rendered":"CHIUSO UN BAR DI OTRANTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1280\" height=\"720\" class=\"wp-image-237736\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Sigilli-3.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Sigilli-3.jpg 1280w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Sigilli-3-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Sigilli-3-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/12\/Sigilli-3-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n\n\n\n<p>Report della Questura di Lecce ________<\/p>\n\n\n\n<p>Nella mattinata di sabato u.s., i poliziotti del Commissariato di P.S. di Otranto hanno dato esecuzione al provvedimento ex art. 100 T.U.L.P.S, emesso dal Questore di Lecce, notificando ai legali rappresentanti della attivit\u00e0 di un esercizio pubblico \u2013 bar, la sospensione dell\u2019attivit\u00e0 di intrattenimento per 10 giorni.<\/p>\n\n\n\n<p>Tale provvedimento arriva dopo la valutazione di una serie di violazioni di tipo amministrativo e penale da parte del locale, che si sono reiterate nel tempo, con particolare incidenza nel periodo estivo e durante le festivit\u00e0. Il bar ha una particolare attrattiva per il pubblico giovanile che si intrattiene, spesso fino a notte tarda, con la musica ad alto volume, diffusa da impianti stereofonici posti all\u2019esterno del locale. Tenuto conto dell\u2019ubicazione dell\u2019attivit\u00e0 di intrattenimento nel pieno centro idruntino, il notevole afflusso di persone in detti periodi crea il problema della vivibilit\u00e0 e del diritto al riposo del vicinato.<\/p>\n\n\n\n<p>Il 19 dicembre u.s. \u00e8 stato segnalato che dagli inizi del corrente mese l\u2019attivit\u00e0 di intrattenimento \u00e8 ripresa e si sono verificati diversi episodi di diffusione della musica ad &nbsp;altissimo volume che ha costretto i residenti della zona a fa intervenire le forze dell\u2019ordine. Gli episodi nonostante tutto si sono ripetuti nelle serate successive.<\/p>\n\n\n\n<p>Le varie attivit\u00e0 di controllo e le indagini amministrative della Polizia di Stato hanno consentito di verificare che, in diversi momenti, sono stati commessi degli abusi e violazioni, nonch\u00e9 il mancato rispetto delle prescrizioni relative alla corretta gestione dell\u2019attivit\u00e0, pregiudizievoli per l\u2019ordine e la sicurezza pubblica.<\/p>\n\n\n\n<p>A seguito di tali attivit\u00e0 il Questore della provincia di Lecce, per contenere il fenomeno della \u201cmovida\u201d nel centro storico idruntino ed evitare la proliferazione di comportamenti illeciti o abusivi, ha emesso il provvedimento sanzionatorio ex. Art.100 che sospende l\u2019attivit\u00e0 dell\u2019esercizio pubblico per 10 giorni.<\/p>\n\n\n\n<p>Lecce, 21 dicembre 2024<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/23\/chiuso-un-bar-di-otranto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/12\/23\/chiuso-un-bar-di-otranto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report della Questura di Lecce ________ Nella mattinata di sabato u.s., i poliziotti del Commissariato di P.S. di Otranto hanno dato esecuzione al provvedimento ex art. 100 T.U.L.P.S, emesso dal Questore di Lecce, notificando ai legali rappresentanti della attivit\u00e0 di un esercizio pubblico \u2013 bar, la sospensione dell\u2019attivit\u00e0 di intrattenimento per 10 giorni. Tale provvedimento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":237736,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237735"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=237735"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237735\/revisions"}],"predecessor-version":[{"id":237737,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/237735\/revisions\/237737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/237736"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=237735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=237735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=237735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}