{"id":23798,"date":"2014-01-24T09:43:03","date_gmt":"2014-01-24T09:43:03","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23798"},"modified":"2014-01-24T09:43:03","modified_gmt":"2014-01-24T09:43:03","slug":"partecipo-allomicidio-caroppo-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/24\/partecipo-allomicidio-caroppo-arrestato\/","title":{"rendered":"PARTECIP\u00d2 ALL\u2019OMICIDIO CAROPPO: ARRESTATO"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/24\/partecipo-allomicidio-caroppo-arrestato\/de-trane-oronzo-stampa\/\" rel=\"attachment wp-att-23799\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/DE-TRANE-ORONZO-stampa-150x150.jpg\" alt=\"\" title=\"DE TRANE ORONZO stampa\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-23799\" \/><\/a>Verso le 13.00 di oggi, i militari del Nucleo Investigativo hanno notificato a DE TRANE Oronzo 36enne leccese, un ordine di carcerazione emesso dalla Corte d\u2019Appello di Taranto a seguito della recente pronuncia della Cassazione che ha confermato la sentenza della Corte d\u2019Assisse d\u2019appello nei confronti del DE TRANE per i reati di: associazione di stampo mafioso, concorso in omicidio e porto abusivo di armi. I fatti dell\u2019odierno ordine di carcerazione si riferiscono all\u2019omicidio di CAROPPO Mario avvenuto nel maggio del 2002. Il DE TRANE in particolare \u2013 assolto nella sentenza di 1\u00b0 grado \u2013 fu riconosciuto responsabile in appello. Egli guidava l\u2019autovettura Renault Scenic sulla quale prendevano posto due dei killer di Caroppo. DE TRANE \u00e8 stato associato alla Casa Circondariale di Lecce per scontare la pena residua di 10 anni 4 mesi e 23 giorni di reclusione.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/24\/partecipo-allomicidio-caroppo-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/24\/partecipo-allomicidio-caroppo-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Verso le 13.00 di oggi, i militari del Nucleo Investigativo hanno notificato a DE TRANE Oronzo 36enne leccese, un ordine di carcerazione emesso dalla Corte d\u2019Appello di Taranto a seguito della recente pronuncia della Cassazione che ha confermato la sentenza della Corte d\u2019Assisse d\u2019appello nei confronti del DE TRANE per i reati di: associazione di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23799,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23798"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23798"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23798\/revisions"}],"predecessor-version":[{"id":23801,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23798\/revisions\/23801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/23799"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}