{"id":238129,"date":"2025-01-05T16:33:56","date_gmt":"2025-01-05T15:33:56","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=238129"},"modified":"2025-01-05T17:28:26","modified_gmt":"2025-01-05T16:28:26","slug":"un-ringraziamento-ai-medici-del-vito-fazzi-di-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/05\/un-ringraziamento-ai-medici-del-vito-fazzi-di-lecce\/","title":{"rendered":"UN RINGRAZIAMENTO AI MEDICI DEL VITO FAZZI DI LECCE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1706\" height=\"1266\" class=\"wp-image-238137\" style=\"width: 900px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/vito-fazzi-infermiera.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/vito-fazzi-infermiera.jpg 1706w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/vito-fazzi-infermiera-300x223.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/vito-fazzi-infermiera-1024x760.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/vito-fazzi-infermiera-768x570.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/vito-fazzi-infermiera-1536x1140.jpg 1536w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>di <strong>Valerio Melcore<\/strong> _______ Sono trascorsi oltre sei mesi da quando mi recai presso l&#8217;Ospedale Vito Fazzi di Lecce, perch\u00e9 quella difficolt\u00e0 a respirare, gi\u00e0 avvertita nei giorni precedenti, era aumentata. <\/p>\n\n\n\n<p>Giunto al Pronto Soccorso, a differenza di quello che mi aspettavo, fui accolto immediatamente, fatto sdraiare su una barella e  indossare la maschera per l&#8217;ossigeno. Mentre aspettavo di sapere cosa mi stava succedendo, un medico mi prese in consegna, il dottor <strong>GIRASOLI Claudio<\/strong>, un cardiologo, che guardando il medico che mi aveva accolto all&#8217;ingresso, gli fece il gesto col pollice alzato dicendogli che la prognosi che aveva azzardato era corretta, embolia polmonare. <\/p>\n\n\n\n<p>Embolia polmonare? Rivolto al dottore, gli chiesi cosa avessi e lui con molta calma mi disse che il mio corpo \u00e8 pieno di emboli. Sapendo bene, per aver vissuto un lutto in famiglia, che anche a causa di un solo embolo si pu\u00f2 morire, gli chiesi quale fosse in Italia la migliore struttura ospedaliera che potesse trattare quella patologia. Dell&#8217;ospedale di Lecce non mi fidavo. <\/p>\n\n\n\n<p>Il dottor Girasoli mi guard\u00f2 sorridendo e spieg\u00f2 che per me quello di Lecce era il miglior ospedale possibile e che se mi fossi alzato dalla  lettiga dopo tre passi sarei potuto finire al Creatore. Per cui mi misi l&#8217;anima in pace e mi affidai ai medici pregando il Padreterno che desse loro una mano. <\/p>\n\n\n\n<p>Sette lunghi giorni e sette notti, nel reparto di terapia intensiva cardiologica e poi altrettanti nel reparto di cardiologia. Il dottor Girasoli aiutato da un suo collega e da quegli angeli che sono le infermiere, mi misero gli aghi nelle vene dei polsi e uno nella giugulare, quest&#8217;ultimo credo che servisse per introdurre un liquido specifico atto a scioglier quei benedetti, maledetti, emboli. Ci tengo a ringraziare quelle splendide persone che si prendono cura dei pazienti 24 su 24, che sono gli <strong>infermieri\/e<\/strong>  insieme a tutti gli <strong>operatori socio-sanitari<\/strong>. <\/p>\n\n\n\n<p>Il dottor Girasoli mi tranquillizz\u00f2, tornando sull&#8217;argomento affrontato all&#8217;ingresso nel Pronto Soccorso, spiegandomi che lui era originario di Roma, che aveva conosciuto diversi ospedali nella capitale e che quello di Lecce di certo \u00e8 una buona struttura ospedaliera che si colloca oltre la media nazionale. Il giorno dopo and\u00f2 via perch\u00e9 aveva preso dieci giorni di ferie. Mi salut\u00f2 dicendomi di tenere duro che ci teneva a rivedermi al suo rientro. Cosa che fece, fu molto gentile e di ci\u00f2 gli sono grato.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ovviamente come tutti i salentini che si rispettino, quando qualcuno finisce in ospedale, famiglia, parenti,  amici si mobilitano, per trovare un &#8220;aggancio&#8221;, qualcuno a cui raccomandare il proprio caro. Un medico, un infermiere, un barelliere, un usciere,  insomma qualcuno che ci permetta di avere un trattamento di favore.<br>E io, come disse qualcuno a mia insaputa, mi ritrovai con un santo in paradiso.<br>Per cui pure io ebbi la mia brava e bella infermiera specializzata, che il giorno dopo il ricovero venne a trovarmi e mentre io facevo i conti col Padreterno, lei mi faceva  l&#8217;ennesimo prelievo, all&#8217;incirca uno ogni mezz&#8217;ora, mi fece un sorriso e mi disse. &#8221; Sono <strong>Rossana<\/strong>, l&#8217;amica di tua nipote, di qualsiasi cosa hai bisogno&#8230;&#8221; ringraziai con un cenno del capo.<\/p>\n\n\n\n<p><br>Dopo il primo giorno si presero cura di me il dottor <strong>DONATEO Mario<\/strong>, il dottor <strong>GARZYA Massimiliano<\/strong>, il dottor <strong>STENDARDO Antonio<\/strong>, la dottoressa <strong>MARINO Elena<\/strong>,  la dottoressa <strong>MAZZELLA Tiziana<\/strong>, il dottor <strong>DE LEONARDIS Michele<\/strong> e infine, ma come suol dirsi, non per ultima, la simpaticissima dottoressa <strong>CUCURACHI Maria Rosaria<\/strong>.<\/p>\n\n\n\n<p>Spero di non aver dimenticato nessuno.<\/p>\n\n\n\n<p>La professionalit\u00e0 dei medici e del personale, accompagnate dalla componente umana che si manifesta in un profondo rispetto per il paziente sono componenti benefiche che contribuiscono senz&#8217;altro alla ripresa sia fisica che psicologica dell&#8217;ammalato. <\/p>\n\n\n\n<p><br>Quanto sopra a dimostrazione che anche nel nostro Salento<strong>\u00a0<\/strong>abbiamo strutture sanitarie eccellenti che meritano tutto il nostro supporto, in un periodo in cui, a ragione o a torto, si tende a sottolineare gli aspetti negativi, mi pare giusto lodare le tante professionalit\u00e0 e il quotidiano lavoro svolto da tante persone con amore nei confronti degli ammalati e di cui siamo testimoni.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/05\/un-ringraziamento-ai-medici-del-vito-fazzi-di-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/05\/un-ringraziamento-ai-medici-del-vito-fazzi-di-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Valerio Melcore _______ Sono trascorsi oltre sei mesi da quando mi recai presso l&#8217;Ospedale Vito Fazzi di Lecce, perch\u00e9 quella difficolt\u00e0 a respirare, gi\u00e0 avvertita nei giorni precedenti, era aumentata. Giunto al Pronto Soccorso, a differenza di quello che mi aspettavo, fui accolto immediatamente, fatto sdraiare su una barella e indossare la maschera per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238129"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=238129"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238129\/revisions"}],"predecessor-version":[{"id":238144,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238129\/revisions\/238144"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=238129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=238129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=238129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}