{"id":23816,"date":"2014-01-25T06:37:12","date_gmt":"2014-01-25T06:37:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23816"},"modified":"2014-01-25T06:37:12","modified_gmt":"2014-01-25T06:37:12","slug":"pericolosi-banditi-arrestati-dalla-polizia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/25\/pericolosi-banditi-arrestati-dalla-polizia\/","title":{"rendered":"PERICOLOSI BANDITI ARRESTATI DALLA POLIZIA"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-23816 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/25\/pericolosi-banditi-arrestati-dalla-polizia\/schermata-2014-01-25-a-07-35-13\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/Schermata-2014-01-25-a-07.35.13-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/25\/pericolosi-banditi-arrestati-dalla-polizia\/schermata-2014-01-25-a-07-35-19\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/Schermata-2014-01-25-a-07.35.19-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/25\/pericolosi-banditi-arrestati-dalla-polizia\/schermata-2014-01-25-a-07-35-26\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/Schermata-2014-01-25-a-07.35.26-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Alle prime ore della mattinata odierna, in provincia di Bari, il Servizio Centrale Operativo e le Squadre Mobili di Lecce, Bari e Foggia hanno concluso una prima fase di una complessa operazione di polizia che ha consentito di disarticolare un pericoloso sodalizio criminale, riconducibile a pregiudicati baresi, dedito alla commissione di assalti a furgoni portavalori, realizzati con l\u2019utilizzo di armi \u201cad alto volume di fuoco\u201d, attivo in diverse province.<\/p>\n<p>&nbsp;<\/p>\n<p>In particolare, sono stati eseguiti 3 fermi di indiziato di delitto nei confronti di Angelo FALCO, del\u201962, Michele FALCO, del\u201982 e Pierpaolo PEREZ, del\u201969, tutti baresi, emessi dalla Procura della Repubblica di Foggia, ritenuti i componenti, insieme ad altre persone ancora da identificare, appartenenti al commando che, il 6 dicembre scorso, nei pressi del casello autostradale di Cerignola (FG), aveva rapinato il furgone portavalori dell\u2019istituto \u201cNP Service\u201d di Foggia.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019assalto, che aveva fruttato un bottino di due milioni di euro, era stato realizzato da un gruppo di almeno 10 persone, dotate di kalashnikov che, bloccata l\u2019autostrada con dei TIR dati alle fiamme, avevano esploso numerosi colpi d\u2019arma da fuoco all\u2019indirizzo delle guardie particolari giurate, \u201csquarciando\u201d il furgone mediante una lancia termica. Si erano, successivamente, dati alla fuga incendiando altre autovetture e percorrendo l\u2019autostrada contromano.<\/p>\n<p>&nbsp;<\/p>\n<p>Le serrate indagini venivano affidate agli investigatori delle province interessate, coordinati dalle Procure della Repubblica di Foggia, Bari e Lecce. La Squadra Mobile di Lecce ha seguito la fase delle indagini preliminari dopo la tentata rapina avvenuta nella provincia salentina il 2 gennaio dello scorso anno. Le indagini, complesse e sofisticate che hanno richiesto l\u2019uso di innovativi strumenti investigativi, sono state orientate verso un\u2019organizzazione criminale composta da soggetti pregiudicati di origine foggiana e barese, sospettati di essere gli autori di altri assalti ai danni di furgoni portavalori, commessi con analoghe modalit\u00e0, nelle province di Bari, Lecce, Foggia e Matera.<\/p>\n<p>&nbsp;<\/p>\n<p>Contestualmente alle fasi esecutive dei provvedimenti restrittivi, con il supporto di equipaggi del Reparto Prevenzione Crimine e del Reparto Volo di Bari e delle Unit\u00e0 cinofile della Polizia di Stato, sono state eseguite anche 15 perquisizioni a carico di altri soggetti emersi dalle indagini, ritenuti appartenenti alla medesima consorteria malavitosa.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019operazione si inquadra in un pi\u00f9 vasto dispositivo di contrasto alle forme pi\u00f9 gravi della criminalit\u00e0 predatoria, realizzato nelle predette province pugliesi, sviluppato da appositi gruppi di lavoro composti da investigatori del Servizio Centrale Operativo e delle squadre Mobili della Puglia.<\/p>\n<p>&nbsp;<\/p>\n<p>I dettagli dell\u2019operazione saranno comunicati nel corso di una conferenza stampa che si terr\u00e0, alle ore 11.30 del 24.1.2014, presso la Procura della Repubblica di Foggia, alla presenza del Procuratore della Repubblica Dr DE CASTRIS e degli investigatori.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/25\/pericolosi-banditi-arrestati-dalla-polizia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/25\/pericolosi-banditi-arrestati-dalla-polizia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Alle prime ore della mattinata odierna, in provincia di Bari, il Servizio Centrale Operativo e le Squadre Mobili di Lecce, Bari e Foggia hanno concluso una prima fase di una complessa operazione di polizia che ha consentito di disarticolare un pericoloso sodalizio criminale, riconducibile a pregiudicati baresi, dedito alla commissione di assalti a furgoni portavalori, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23816"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23816"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23816\/revisions"}],"predecessor-version":[{"id":23820,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23816\/revisions\/23820"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}