{"id":238544,"date":"2025-01-18T18:10:43","date_gmt":"2025-01-18T17:10:43","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=238544"},"modified":"2025-01-18T18:15:00","modified_gmt":"2025-01-18T17:15:00","slug":"a-cagliari-preparati-agli-eventi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/18\/a-cagliari-preparati-agli-eventi\/","title":{"rendered":"A CAGLIARI, PREPARATI AGLI EVENTI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"384\" height=\"131\" class=\"wp-image-238545\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/download-9.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/download-9.jpeg 384w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/download-9-300x102.jpeg 300w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><\/p>\n\n\n\n<p>(Rdl) ________ Seduta di rifinitura questo pomeriggio al Via del Mare, in cui Filip Marchwi\u0144ski ha riportato un trauma distorsivo del ginocchio destro: si sottoporr\u00e0 nelle prossime ore ad esami strumentali.<\/p>\n\n\n\n<p>Prima della partenza alla volta dell&#8217;isola, Marco Giampaolo ha parlato con i giornalisti.<\/p>\n\n\n\n<p>Ecco una sintesi delle sue dichiarazioni:<\/p>\n\n\n\n<p><strong>\u201c<\/strong><em>Il\u00a0Cagliari \u00e8 una formazione che si fa rispettare, un campo ostico&#8230;<\/em><\/p>\n\n\n\n<p><em>Sar\u00e0 una gara pesante con una posta in palio succulenta per entrambe. Non \u00e8 una partita da dentro-fuori ma gornata potrebbe fare la differenza<\/em>&#8230;<\/p>\n\n\n\n<p><em>Dobbiamo essere preparati agli eventi. Dobbiamo stare dentro nei momenti decisivi della partita, credo che si tratti di una buona prova di maturit\u00e0 anche nella consapevolezza di cosa siamo come squadra<\/em>&#8230;&#8221;<\/p>\n\n\n\n<p>La formazione?<\/p>\n\n\n\n<p><em>&#8220;Ho fatto le mie valutazuoni, ma voglio pensarci su ancora una notte&#8221;<\/em><\/p>\n\n\n\n<p>Krstovic? <\/p>\n\n\n\n<p><em>&#8220;Ha tantissimi margini di miglioramento e pu\u00f2 correggere subito delle cose facilmente correggibili. Diventer\u00e0 un giocatore ancora pi\u00f9 forte&#8221;<\/em>.<\/p>\n\n\n\n<p>Si gioca  allo stadio Unipol Domus, ex Sant&#8217;Elia, di Cagliari domenica 19 gennaio. Fischio di inizio del signor Luca Sacchi di Macerata\u00a0alle 15.\u00a0<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/18\/a-cagliari-preparati-agli-eventi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/18\/a-cagliari-preparati-agli-eventi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) ________ Seduta di rifinitura questo pomeriggio al Via del Mare, in cui Filip Marchwi\u0144ski ha riportato un trauma distorsivo del ginocchio destro: si sottoporr\u00e0 nelle prossime ore ad esami strumentali. Prima della partenza alla volta dell&#8217;isola, Marco Giampaolo ha parlato con i giornalisti. Ecco una sintesi delle sue dichiarazioni: \u201cIl\u00a0Cagliari \u00e8 una formazione che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":238545,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238544"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=238544"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238544\/revisions"}],"predecessor-version":[{"id":238547,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238544\/revisions\/238547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/238545"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=238544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=238544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=238544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}