{"id":238551,"date":"2025-01-20T00:02:00","date_gmt":"2025-01-19T23:02:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=238551"},"modified":"2025-01-18T18:45:48","modified_gmt":"2025-01-18T17:45:48","slug":"il-canto-dei-lendini-un-romanzo-ambientato-nellalbania-del-kanun","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/20\/il-canto-dei-lendini-un-romanzo-ambientato-nellalbania-del-kanun\/","title":{"rendered":"\u201cIl canto dei lendini\u201d, UN ROMANZO AMBIENTATO NELL\u2019ALBANIA DEL KANUN"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"320\" height=\"320\" class=\"wp-image-238552\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/473311766_122189319992059926_1846706085062263148_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/473311766_122189319992059926_1846706085062263148_n.jpg 320w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/473311766_122189319992059926_1846706085062263148_n-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/473311766_122189319992059926_1846706085062263148_n-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/473311766_122189319992059926_1846706085062263148_n-60x60.jpg 60w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/p>\n\n\n\n<p>di <strong>Raffaele Polo<\/strong> ________<\/p>\n\n\n\n<p>L\u2019Albania dei primi anni del comunismo e la dura legge del Kanun \u2013 il codice d\u2019onore che segna i destini della gente comune \u2013 sono il motore della storia narrata dallo scrittore contemporaneo <strong>Manfred Bushi<\/strong>, classe \u201969, nato nel villaggio di Krajne, quando la Terra delle Aquile era il regno delle contraddizioni, ed emigrato in Italia nel \u201994.&nbsp;&nbsp;&nbsp; <\/p>\n\n\n\n<p><em><strong>\u201cIl canto dei lendini\u201d <\/strong><\/em>(104 pagine, 14 Euro) \u00e8 il titolo della prima novit\u00e0 Besa Muci del 2025, una proposta letteraria che arriva dai Balcani e che sar\u00e0 in libreria e negli store online dal 24 gennaio.<\/p>\n\n\n\n<p>Un banalissimo malinteso fra due vicini di casa d\u00e0 inizio a una catena di vendette. Nell\u2019Albania dei primi anni del comunismo, la legge del Kanun, il codice d\u2019onore, condiziona la vita della gente comune e ne determina le scelte. Cos\u00ec, l\u2019esistenza della giovane madre Dilore viene stravolta e la donna di colpo si ritrova, con i due figli piccoli, internata in un campo insieme ad altri personaggi: comunisti convinti e disillusi, madri sole come lei, bey musulmani, preti cattolici, contadini, eleganti borghesi. Tuttavia, \u00e8 proprio qui che Dilore prende coscienza della propria forza e, con determinazione, lotta per conquistare il proprio posto nel mondo e la sua indipendenza di donna.<\/p>\n\n\n\n<p>L&#8217;autore ci regala un romanzo che, nella sua brevit\u00e0, senza retorica n\u00e9 partigianeria, \u00e8 in grado di condensare un pezzo di storia dell\u2019Albania, con tutte le sue contraddizioni, in una prosa mai scontata ma, al contrario, icastica e potente.<\/p>\n\n\n\n<p>Manfred Bushi \u00e8 nato nel villaggio di Krojne, in Albania, nel 1969. Finita la scuola superiore, si \u00e8 diplomato presso la scuola della Polizia di Stato. Emigrato in Italia nel 1994, ha frequentato la Facolt\u00e0 di Lettere e Filosofia presso l\u2019Universit\u00e0 di Modena a Reggio Emilia. Attualmente vive e lavora a Modena.<\/p>\n\n\n\n<p>Ma cosa sono i lendini? Ce lo dice la storia naturale:<\/p>\n\n\n\n<p>Le <em>lendini <\/em>sono le uova deposte dai pidocchi, parassiti ematofagi dei mammiferi, appartenenti all&#8217;ordine degli Anoplura o Siphunculata.<\/p>\n\n\n\n<p>A casa nostra, nel Salento, si dice: Puru li pureci tenenu la tosse&#8230;<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"179\" height=\"281\" class=\"wp-image-238554\" style=\"width: 600px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/download-1-1.jpeg\" alt=\"\"><\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/20\/il-canto-dei-lendini-un-romanzo-ambientato-nellalbania-del-kanun\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/20\/il-canto-dei-lendini-un-romanzo-ambientato-nellalbania-del-kanun\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo ________ L\u2019Albania dei primi anni del comunismo e la dura legge del Kanun \u2013 il codice d\u2019onore che segna i destini della gente comune \u2013 sono il motore della storia narrata dallo scrittore contemporaneo Manfred Bushi, classe \u201969, nato nel villaggio di Krajne, quando la Terra delle Aquile era il regno delle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":238552,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238551"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=238551"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238551\/revisions"}],"predecessor-version":[{"id":238556,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238551\/revisions\/238556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/238552"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=238551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=238551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=238551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}