{"id":23861,"date":"2014-01-26T08:25:17","date_gmt":"2014-01-26T08:25:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23861"},"modified":"2014-01-26T08:25:17","modified_gmt":"2014-01-26T08:25:17","slug":"sequestrati-186-kg-di-marijuana","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/26\/sequestrati-186-kg-di-marijuana\/","title":{"rendered":"SEQUESTRATI 186 KG. DI MARIJUANA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\">Durante la scorsa notte, i Carabinieri della Stazione Carabinieri di Melendugno e dell\u2019Aliquota Operativa, a seguito di perquisizione all\u2019interno di un fabbricato rustico, sito in Marina di san Foca, scovavano e sottoponevano a sequestro\u00a0sette grandi borsoni che contenevano all\u2019interno 162 panetti di marijuana. Il peso complessivo della sostanza si aggira sui 186 chilogrammi, ed era gi\u00e0 essiccata e pronta per essere immessa sul mercato. Nell\u2019immediatezza sono partite le indagini dei Carabinieri, sotto la direzione della Procura di Lecce, per far luce sia sulla provenienza dei borsoni che sui successivi canali di distribuzione al dettaglio.<\/p>\n<p align=\"center\"><em><span style=\"text-decoration: underline\"><br \/>\n<\/span><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/26\/sequestrati-186-kg-di-marijuana\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/26\/sequestrati-186-kg-di-marijuana\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Durante la scorsa notte, i Carabinieri della Stazione Carabinieri di Melendugno e dell\u2019Aliquota Operativa, a seguito di perquisizione all\u2019interno di un fabbricato rustico, sito in Marina di san Foca, scovavano e sottoponevano a sequestro\u00a0sette grandi borsoni che contenevano all\u2019interno 162 panetti di marijuana. Il peso complessivo della sostanza si aggira sui 186 chilogrammi, ed era [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23861"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23861"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23861\/revisions"}],"predecessor-version":[{"id":23862,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23861\/revisions\/23862"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}