{"id":238687,"date":"2025-01-22T13:30:48","date_gmt":"2025-01-22T12:30:48","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=238687"},"modified":"2025-01-22T13:33:37","modified_gmt":"2025-01-22T12:33:37","slug":"sulla-centrale-a-bio-gas-di-cafore-arriva-il-no-del-comune-di-lecce-lassessore-gianpaolo-scorrano-ne-spiega-le-ragioni-non-senza-polemica-avete-visto-e-ora-fatti-e-non-parole","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/22\/sulla-centrale-a-bio-gas-di-cafore-arriva-il-no-del-comune-di-lecce-lassessore-gianpaolo-scorrano-ne-spiega-le-ragioni-non-senza-polemica-avete-visto-e-ora-fatti-e-non-parole\/","title":{"rendered":"SULLA CENTRALE A BIO GAS DI CAFORE ARRIVA IL NO DEL COMUNE DI LECCE. L&#8217;ASSESSORE GIANPAOLO SCORRANO NE SPIEGA LE RAGIONI. NON SENZA POLEMICHE CON TUTTI: &#8216;AVETE VISTO? E ORA FATE FATTI E NON PAROLE&#8217;"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1148\" height=\"1148\" class=\"wp-image-238688\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/369047589_10228713115867323_2776353886181285775_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/369047589_10228713115867323_2776353886181285775_n.jpg 1148w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/369047589_10228713115867323_2776353886181285775_n-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/369047589_10228713115867323_2776353886181285775_n-1024x1024.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/369047589_10228713115867323_2776353886181285775_n-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/369047589_10228713115867323_2776353886181285775_n-768x768.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/01\/369047589_10228713115867323_2776353886181285775_n-60x60.jpg 60w\" sizes=\"(max-width: 1148px) 100vw, 1148px\" \/><\/p>\n\n\n\n<p>Comunicazione istituzionale del Comune di Lecce __________<\/p>\n\n\n\n<p>Impianto di biometano, il Comune di Lecce esprime parere contrario alla Pas (Procedura Abilitativa Semplificata). Dichiarazione dell&#8217;assessore all&#8217;Urbanistica, Gianpaolo Scorrano.<br><br>&lt;Dopo mesi di sterili polemiche, il settore Urbanistica del Comune di Lecce ha ufficialmente comunicato alla societ\u00e0 proponente i motivi ostativi alla realizzazione dell&#8217;impianto di biometano.<br><br>Nonostante i pronostici di un probabile via libera e l\u2019assenza di pareri negativi vincolanti da parte di tutti gli Enti che hanno partecipato alla Conferenza di Servizi, l\u2019Ufficio urbanistico ha evidenziato nel proprio provvedimento le diverse criticit\u00e0 tecniche e progettuali, non<br>limitandosi all\u2019impatto paesaggistico e al mancato rispetto della distanza dall&#8217;abbazia di Cerrate e, ancor pi\u00f9, dalla cava dismessa.<br><br>Le principali problematiche riscontrate:<br><br>1. Impatto odorigeno: si ritiene che gli odori prodotti dall\u2019impianto, soprattutto in primavera ed estate con le alte temperature, possano danneggiare il territorio circostante, incluso l\u2019abbazia di Cerrate e la vicina masseria Melcarne.<br>Inoltre, manca la progettazione di qualsivoglia opera per mitigare la diffusione degli odori.<br><br>2. Viabilit\u00e0 e traffico: non \u00e8 stato previsto un piano per gestire il traffico generato dall\u2019impianto, in una zona di alto valore ambientale e turistico. Questo potrebbe causare un significativo aumento dell\u2019inquinamento acustico e atmosferico, con impatti negativi sui residenti e sulle attivit\u00e0 ricettive della zona.<br><br>3. Collegamento al metanodotto: non \u00e8 stato presentato un progetto per collegare l\u2019impianto al metanodotto di trasporto esistente, che richiederebbe un\u2019ulteriore autorizzazione specifica (AUA).<br><br>Il Comune di Lecce ha lavorato sodo e con attenzione, valutando non solo le distanze legali dai siti tutelati, ma anche i potenziali impatti ambientali e sociali su un\u2019area di particolare pregio gi\u00e0 compromessa dalla presenza di numerosi impianti di energie rinnovabili.<br><br>Ai sindaci di Surbo e di Trepuzzi, che tanto \u201cinutile polverone\u201d avevano alzato prima ancora di conoscere l\u2019esito della Conferenza di Servizi e il pronunciamento del competente Comune di Lecce, si chiede ora analoga presa di posizione, oltre all\u2019adozione di tutti gli atti consequenziali<br>(revoca dell\u2019AUA), per la chiusura immediata dell\u2019impianto di Biogas di propriet\u00e0 dell\u2019Eni ricadente in territorio surbino e che, ad oggi, risulterebbe ancora inadempiente rispetto alle prescrizioni effettuate da Arpa Puglia pi\u00f9 di un anno addietro.<br><br>\u00c8 giunto il momento di passare dalle parole ai fatti. Si chiudano, dunque, tutti gli impianti nocivi gi\u00e0 esistenti e si intervenga con urgenza in Regione Puglia per modificare il Disegno di Legge \u201caree idonee\u201d che non tutela sufficientemente il territorio, la salute e il futuro di tutti i salentini.<br>Il resto sono solo chiacchiere&gt;. __________<\/p>\n\n\n\n<p>L&#8217;APPROFONDIMENTO nel nostro articolo del 4 novembre scorso e in quello ad esso collegato<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"33kqd5N33m\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/04\/235783\/\">SURBO NON VUOLE LA CENTRALE A BIO GAS DI CAFORE E IL SINDACO TRIO VA A LECCE, COMPETENTE A DECIDERE. OTTIENE SOLO GENTILEZZE FORMALI, MA NIENTE DI CONCRETO. POLI BORTONE: &#8220;L&#8217;impianto di biometano \u00e8 una piccola cosa&#8221;<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;SURBO NON VUOLE LA CENTRALE A BIO GAS DI CAFORE E IL SINDACO TRIO VA A LECCE, COMPETENTE A DECIDERE. OTTIENE SOLO GENTILEZZE FORMALI, MA NIENTE DI CONCRETO. POLI BORTONE: &#8220;L&#8217;impianto di biometano \u00e8 una piccola cosa&#8221;&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/11\/04\/235783\/embed\/#?secret=snvoOskYXN#?secret=33kqd5N33m\" data-secret=\"33kqd5N33m\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/22\/sulla-centrale-a-bio-gas-di-cafore-arriva-il-no-del-comune-di-lecce-lassessore-gianpaolo-scorrano-ne-spiega-le-ragioni-non-senza-polemica-avete-visto-e-ora-fatti-e-non-parole\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/01\/22\/sulla-centrale-a-bio-gas-di-cafore-arriva-il-no-del-comune-di-lecce-lassessore-gianpaolo-scorrano-ne-spiega-le-ragioni-non-senza-polemica-avete-visto-e-ora-fatti-e-non-parole\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Comunicazione istituzionale del Comune di Lecce __________ Impianto di biometano, il Comune di Lecce esprime parere contrario alla Pas (Procedura Abilitativa Semplificata). Dichiarazione dell&#8217;assessore all&#8217;Urbanistica, Gianpaolo Scorrano. &lt;Dopo mesi di sterili polemiche, il settore Urbanistica del Comune di Lecce ha ufficialmente comunicato alla societ\u00e0 proponente i motivi ostativi alla realizzazione dell&#8217;impianto di biometano. Nonostante i [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":238688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238687"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=238687"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238687\/revisions"}],"predecessor-version":[{"id":238690,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/238687\/revisions\/238690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/238688"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=238687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=238687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=238687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}