{"id":239120,"date":"2025-02-03T11:27:00","date_gmt":"2025-02-03T10:27:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=239120"},"modified":"2025-02-03T20:09:27","modified_gmt":"2025-02-03T19:09:27","slug":"controlli-dei-carabinieri-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/03\/controlli-dei-carabinieri-2\/","title":{"rendered":"CONTROLLI DEI CARABINIERI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1054\" height=\"562\" class=\"wp-image-239121\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/cara.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/cara.jpg 1054w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/cara-300x160.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/cara-1024x546.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/cara-768x410.jpg 768w\" sizes=\"(max-width: 1054px) 100vw, 1054px\" \/><\/p>\n\n\n\n<p>Report del Comando Provinciale dei Carabinieri di Lecce _______<\/p>\n\n\n\n<p>LOTTA ALLA MALAMOVIDA SALENTINA. CONTROLLI SERRATI DEI CARABINIERI: 1 ARRESTO PER STUPEFACENTI E SOSPENSIONE DELL\u2019ATTIVITA\u2019 DI INTRATTENIMENTO.<br>Week-end caratterizzato da serrati controlli che i Carabinieri del Comando Provinciale di Lecce hanno messo in campo per la lotta alla malamovida ed al contrasto alle piazze di spaccio, nonch\u00e8 prevenzione dei principali fenomeni criminali maggiormente diffusi.<br>\u00c8 stato questo il contesto in cui i Carabinieri del Nucleo Operativo e Radiomobile della Compagnia di Lecce, coadiuvati dai militari della Stazione di Monteroni di Lecce, hanno arrestato nella flagranza di reato un giovane 22enne, del posto, ritenuto presunto responsabile di detenzione ai fini di spaccio di sostanze verosimilmente stupefacenti.<br>Si tratta di uno studente a carico del quale i Carabinieri hanno eseguito una perquisizione personale e domiciliare. Nel corso delle operazioni, il 22enne \u00e8 stato trovato in possesso di tre involucri, in cellophane, contenenti complessivamente quasi 15 grammi di sostanza presumibilmente stupefacente del tipo \u201chashish\u201d che lo stesso teneva occultata all\u2019interno di un pensile nella propria camera da letto. Unitamente a tale sostanza, i militari hanno rinvenuto anche un bilancino di precisione e materiale vario per il confezionamento. Tutto \u00e8 stato sottoposto a sequestro a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<br>Al termine delle operazioni di polizia, il giovane \u00e8 stato arrestato e, come disposto dal P.M. di turno presso la Procura della Repubblica di Lecce che conduce le indagini, sottoposto alla misura cautelare personale degli arresti domiciliari.<br>Parallelamente a tale operazione, i militari della Stazione di Lecce Santa Rosa, coadiuvati da militari del Nucleo Ispettorato del Lavoro di Lecce (N.I.L.) e del Nucleo Antisofisticazione e Sanit\u00e0 (N.A.S.) a seguito di specifici controlli, hanno segnalato alle competenti Autorit\u00e0 la proprietaria di un locale di intrattenimento del capoluogo salentino, per inosservanza delle norme in materia di salute e sicurezza sui luoghi di lavoro.<br>L\u2019amaro epilogo \u00e8 toccato ad una giovanissima imprenditrice, individuata quale responsabile del locale di intrattenimento presso cui i Carabinieri hanno accertato numerose violazioni in tema di sicurezza sul lavoro. Al termine dei controlli, la donna \u00e8 stata segnalata alle competenti Autorit\u00e0 per varie violazioni, tra le quali, per non aver inviato al medico competente due lavoratori dipendenti e fornito un\u2019adeguata formazione sui rischi aziendali ad un altro dipendente. All\u2019imprenditrice \u00e8 stato irrogato anche il<br>provvedimento di sospensione dell\u2019attivit\u00e0 imprenditoriale per aver impiegato due soggetti irregolari, con relativa contestazione di sanzioni amministrative per complessivi euro 13.000. Nel medesimo contesto ispettivo, personale del N.A.S. ha contestato alla titolare altre violazioni in materia di sicurezza alimentare e comminato sanzioni per ulteriori euro 3.000.<br>I due impiegati irregolari sono stati inoltre segnalati dai Carabinieri poich\u00e9 trovati in possesso di modica quantit\u00e0 di sostanza presumibilmente stupefacente del tipo \u201chashish\u201d.<br>\u00c8 importante sottolineare che tutti i procedimenti si trovano nella fase preliminare e che l\u2019eventuale colpevolezza in ordine ai reati contestati, dovr\u00e0 essere accertata in sede di processo nel contraddittorio tra le parti.<br>Lecce 03.02.2025.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/03\/controlli-dei-carabinieri-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/03\/controlli-dei-carabinieri-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report del Comando Provinciale dei Carabinieri di Lecce _______ LOTTA ALLA MALAMOVIDA SALENTINA. CONTROLLI SERRATI DEI CARABINIERI: 1 ARRESTO PER STUPEFACENTI E SOSPENSIONE DELL\u2019ATTIVITA\u2019 DI INTRATTENIMENTO.Week-end caratterizzato da serrati controlli che i Carabinieri del Comando Provinciale di Lecce hanno messo in campo per la lotta alla malamovida ed al contrasto alle piazze di spaccio, nonch\u00e8 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":239121,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/239120"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=239120"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/239120\/revisions"}],"predecessor-version":[{"id":239122,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/239120\/revisions\/239122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/239121"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=239120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=239120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=239120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}