{"id":23948,"date":"2014-01-29T06:49:42","date_gmt":"2014-01-29T06:49:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23948"},"modified":"2014-01-29T06:49:42","modified_gmt":"2014-01-29T06:49:42","slug":"kiev-arrivano-i-nostri","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/29\/kiev-arrivano-i-nostri\/","title":{"rendered":"KIEV&#8230;ARRIVANO I NOSTRI"},"content":{"rendered":"<p>Tra l&#8217;entusiasmo dei rivoltosi pro-Europa e le paure del Presidente ucraino Yanukovych sono sbarcati a Kiev &#8220;i nostri&#8221;.<br \/>\nOvvero,scesi dall&#8217;aereo senza correre alcun rischio,il ministro degli esteri della Ue,Catherine Ashton,e 12 europarlamentari sono corsi ad abbracciare i loro protetti &#8220;rivoltosi&#8221;.<br \/>\nVisto il numero,scatta spontaneo il paragone con la missione &#8220;altissima&#8221; dei dodici &#8220;apostoli della libert\u00e0&#8221;.<br \/>\nE,quasi miracolo,appena arrivati hanno ricevuto le dimissioni del Premier Azarov ed il ritiro delle leggi sull&#8217;ordine pubblico.<br \/>\nPotenza della Unione Europea (e degli Usa,aggiungo io).<br \/>\nSpesso,nel mondo,basta la parola&#8230;..!!<br \/>\nIn Italia,una volta,era la r\u00e9clame di un noto purgante,<a href=\"https:\/\/webmaildomini.aruba.it\/ext_aruba\/classic\/html\/mainframe.html?_v_=v4r2b13.20131107_1145?lang=it&amp;flavour=basic&amp;theme=ext_aruba\/classic&amp;useSprite=0\">oggi<\/a>\u00a0sembra faccia ancora effetto,basta vedere Yanokovych.<br \/>\nPutin,secondo linea seguita,ha protestato per l&#8217;ingerenza occidentale negli affari interni ucraini.<br \/>\nMa c&#8217;\u00e8 Sochi,l&#8217;Olimpiade incombe e,si sa,quando ci sono i Giochi le armi dovrebbero tacere.<br \/>\nPutin ha detto : &#8220;se mi recassi ad Atene,cosa accadrebbe ?&#8221;.<br \/>\nAppunto,Presidente&#8230;.proprio questo mi chiedo. Perch\u00e9 non sbarca ad Atene ?<br \/>\nSenza apostoli,non ne avrebbe bisogno.<br \/>\nMolti,moltissimi europei guardano alla Russia ed a lei con grande attenzione.<br \/>\nLa Unione Europea non \u00e8 per nulla amata,in Europa.<br \/>\nBasterebbe che la Russia non facesse sentire soli ed abbandonati a se stessi quanti tentano di resistere a questo regime di banchieri,burocrati e magnacci vari.<br \/>\nIn fin dei conti ,quando Putin ha fatto sul serio, gli Usa ed i suoi servi Ue sono scesi a pi\u00fa miti consigli.<br \/>\nLa Siria insegna.<\/p>\n<p>Vincenzo Mannello<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/29\/kiev-arrivano-i-nostri\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/29\/kiev-arrivano-i-nostri\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Tra l&#8217;entusiasmo dei rivoltosi pro-Europa e le paure del Presidente ucraino Yanukovych sono sbarcati a Kiev &#8220;i nostri&#8221;. Ovvero,scesi dall&#8217;aereo senza correre alcun rischio,il ministro degli esteri della Ue,Catherine Ashton,e 12 europarlamentari sono corsi ad abbracciare i loro protetti &#8220;rivoltosi&#8221;. Visto il numero,scatta spontaneo il paragone con la missione &#8220;altissima&#8221; dei dodici &#8220;apostoli della libert\u00e0&#8221;. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23948"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23948"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23948\/revisions"}],"predecessor-version":[{"id":23950,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23948\/revisions\/23950"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}