{"id":239653,"date":"2025-02-18T11:20:37","date_gmt":"2025-02-18T10:20:37","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=239653"},"modified":"2025-02-18T11:20:41","modified_gmt":"2025-02-18T10:20:41","slug":"provvedimenti-per-tifoso-gallipolino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/18\/provvedimenti-per-tifoso-gallipolino\/","title":{"rendered":"PROVVEDIMENTI PER TIFOSO GALLIPOLINO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"694\" class=\"wp-image-239654\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/475677110_122221379198064993_8123029984132694438_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/475677110_122221379198064993_8123029984132694438_n.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/475677110_122221379198064993_8123029984132694438_n-300x217.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/475677110_122221379198064993_8123029984132694438_n-768x555.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n\n\n\n<p>Report della Questura di Lecce _________<\/p>\n\n\n\n<p><strong>DASPO a carico di un tifoso<\/strong> <strong>gallipolino che lanci\u00f2 di materiale pericoloso durante la partita Gallipoli-Bisceglie<\/strong><\/p>\n\n\n\n<p>Ieri \u00e8 stato notificato dagli agenti della Polizia di Stato la misura preventiva del DASPO ad un 46enne di Gallipoli che avrebbe lanciato materiale pericoloso durante l\u2019incontro di calcio del 26 gennaio u.s. tra ASD Citt\u00e0 di Gallipoli e ASD Unione Calcio Bisceglie.<\/p>\n\n\n\n<p>L\u2019uomo dagli spalti della \u201ccurva sud\u201d, che ospitava un nutrito gruppo di tifosi locali tra cui anche giovanissimi, come evidenziato dai filmati degli operatori di Polizia Scientifica, ha lanciato verso il campo di gioco almeno due dei tre ordigni che sono deflagrati a ridosso delle barriere anti-scavalco. Il gesto, pericoloso sia per chi era sugli spalti nei pressi dell\u2019autore del lancio e sia per chi era nelle vicinanze del luogo di deflagrazione \u00e8 stato considerato pericoloso e pregiudizievole per l\u2019ordine e la sicurezza pubblica.<\/p>\n\n\n\n<p>Il Questore della provincia di Lecce ha emesso con la misura del DASPO per la durata di un anno che vieta al destinatario del provvedimento l\u2019accesso agli impianti sportivi nazionali nonch\u00e9 alle zone limitrofe degli stessi per tutta la durata degli incontri e per due ore prima e due ore dopo la fine degli incontri.<\/p>\n\n\n\n<p>Il provvedimento \u00e8 finalizzato a prevenire la reiterazione delle condotte pregiudizievoli dell\u2019ordine e della sicurezza pubblica che considerata la stagione piena di incontri calcistici potrebbe essere motivo di ulteriori exploit di violenza da stadio.<\/p>\n\n\n\n<p>Lecce, 18 febbraio 2025<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/18\/provvedimenti-per-tifoso-gallipolino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/18\/provvedimenti-per-tifoso-gallipolino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report della Questura di Lecce _________ DASPO a carico di un tifoso gallipolino che lanci\u00f2 di materiale pericoloso durante la partita Gallipoli-Bisceglie Ieri \u00e8 stato notificato dagli agenti della Polizia di Stato la misura preventiva del DASPO ad un 46enne di Gallipoli che avrebbe lanciato materiale pericoloso durante l\u2019incontro di calcio del 26 gennaio u.s. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":239654,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/239653"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=239653"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/239653\/revisions"}],"predecessor-version":[{"id":239655,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/239653\/revisions\/239655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/239654"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=239653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=239653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=239653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}