{"id":240009,"date":"2025-02-26T15:35:35","date_gmt":"2025-02-26T14:35:35","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=240009"},"modified":"2025-02-26T15:35:38","modified_gmt":"2025-02-26T14:35:38","slug":"una-leggenda-alla-seconda-giovinezza-in-anteprima-da-maldarizzi-automotive-la-nuova-grande-panda-a-bari-lunedi-3-marzo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/26\/una-leggenda-alla-seconda-giovinezza-in-anteprima-da-maldarizzi-automotive-la-nuova-grande-panda-a-bari-lunedi-3-marzo\/","title":{"rendered":"UNA LEGGENDA ALLA SECONDA GIOVINEZZA. IN ANTEPRIMA DA MALDARIZZI AUTOMOTIVE LA NUOVA GRANDE PANDA A BARI LUNEDI&#8217; 3 MARZO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1706\" class=\"wp-image-240010\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda-scaled.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda-scaled.jpg 2560w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda-768x512.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda-1536x1023.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n\n\n\n<p>Lancio della nuova Grande Panda, che arriver\u00e0 in Puglia per la prima volta il 3 marzo. <\/p>\n\n\n\n<p>Per l&#8217;occasione Maldarizzi Automotive ha organizzato un evento luned\u00ec 3 marzo alle 18.00<\/p>\n\n\n\n<p>Showroom Fiat Maldarizzi Automotive in via Oberdan 2 (ingresso parcheggio via Apulia, 7).\u00a0<\/p>\n\n\n\n<p><strong><em>Un ritorno in Grande Panda: Maldarizzi Automotive presenta la novit\u00e0 Fiat a Bari.<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Il 3 marzo l\u2019evento di lancio nella storica sede del brand Stellantis<\/em><\/strong><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1791\" class=\"wp-image-240011\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda_schieramento-1-scaled.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda_schieramento-1-scaled.jpg 2560w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda_schieramento-1-300x210.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda_schieramento-1-1024x716.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda_schieramento-1-768x537.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda_schieramento-1-1536x1075.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/02\/FiatGrandePanda_schieramento-1-2048x1433.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Pu\u00f2 una leggenda vivere una seconda giovinezza? Fiat risponde a questa domanda rivisitando un modello iconico che ha segnato gli anni \u201880 e ha rappresentato per milioni di automobilisti un simbolo di libert\u00e0: la nuova Grande Panda.&nbsp;<\/p>\n\n\n\n<p>Dopo il debutto nazionale che riporta il brand torinese del Gruppo Stellantis a dominare il segmento B, il nuovo \u201cfamily mover\u201d Fiat sar\u00e0 presentato il 3 marzo da Maldarizzi Automotive. Il reveal avverr\u00e0 a partire della 18:30 nella ex-sede storica Fiat di Via Oberdan, 2 (Bari) e i partecipanti avranno l\u2019occasione di scoprire la Nuova Grande Panda e di rivivere in tutto e per tutto il sapore di quegli anni che hanno reso celebre il leggendario modello Fiat.&nbsp;<\/p>\n\n\n\n<p>In soli 4 metri, la vettura offre spazio e comfort per gli spostamenti in citt\u00e0. Le linee ortogonali audaci, i fari LED pixel che strizzano l\u2019occhio al retrogaming ed il logo in 3D su entrambi i lati rendono la Nuova Grande Panda dal carattere audace e futuristico.&nbsp;<\/p>\n\n\n\n<p>Gli interni raccontano il ruolo pionieristico della casa torinese nell\u2019ambito della sostenibilit\u00e0, con l\u2019utilizzo di BAMBOX Bamboo Fiber Tex\u00ae, un tessuto innovativo realizzato per il 33% con vere fibre di bamb\u00f9. Ogni Grande Panda, inoltre, contiene materiale derivante dal riciclo di circa 140 confezioni di cartone per bevande.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Disponibile in due nuove motorizzazioni: la versione ibrida monta un motore turbo a 3 cilindri da 100 CV ed una batteria a ioni di litio da 48 V; la versione full electric dispone di una batteria da 44 kWh e garantisce un\u2019autonomia fino a 320 Km. La ricarica \u00e8 semplice e veloce grazie al cavo retrattile anteriore, caratteristica distintiva del nuovo modello Fiat.&nbsp;<\/p>\n\n\n\n<p>L\u2019evento del 3 marzo non sar\u00e0 solo l\u2019occasione per scoprire tutte le caratteristiche di Grande Panda, ma rappresenter\u00e0 anche un importante momento di incontro con l\u2019arte contemporanea. Verr\u00e0, infatti, presentata ufficialmente <em>Vochocento 2024<\/em>, una coloratissima scultura in stile <em>alebrije<\/em> donata dagli artisti Ricardo Macias e Fernando Gobea. <em>Vochocento 2024 <\/em>simboleggia lo stretto rapporto che lega Maldarizzi Automotive al Messico, un legame che si riflette nella carica di Console degli Stati Uniti Messicani ricoperta dal fondatore dell\u2019azienda Francesco Maldarizzi.&nbsp;&nbsp;<\/p>\n\n\n\n<p>L\u2019evento \u00e8 aperto al pubblico e per partecipare baster\u00e0 registrarsi al seguente: <a href=\"https:\/\/bit.ly\/4hSXCXx\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/bit.ly\/4hSXCXx<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/26\/una-leggenda-alla-seconda-giovinezza-in-anteprima-da-maldarizzi-automotive-la-nuova-grande-panda-a-bari-lunedi-3-marzo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/02\/26\/una-leggenda-alla-seconda-giovinezza-in-anteprima-da-maldarizzi-automotive-la-nuova-grande-panda-a-bari-lunedi-3-marzo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Lancio della nuova Grande Panda, che arriver\u00e0 in Puglia per la prima volta il 3 marzo. Per l&#8217;occasione Maldarizzi Automotive ha organizzato un evento luned\u00ec 3 marzo alle 18.00 Showroom Fiat Maldarizzi Automotive in via Oberdan 2 (ingresso parcheggio via Apulia, 7).\u00a0 Un ritorno in Grande Panda: Maldarizzi Automotive presenta la novit\u00e0 Fiat a Bari. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":240010,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240009"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=240009"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240009\/revisions"}],"predecessor-version":[{"id":240012,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240009\/revisions\/240012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/240010"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=240009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=240009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=240009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}