{"id":240475,"date":"2025-03-09T12:15:46","date_gmt":"2025-03-09T11:15:46","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=240475"},"modified":"2025-03-09T12:15:50","modified_gmt":"2025-03-09T11:15:50","slug":"h80-nostalgia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/09\/h80-nostalgia\/","title":{"rendered":"H&#8217;80 NOSTALGIA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1200\" height=\"675\" class=\"wp-image-240476\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/468424267_122128707986391262_1374940160526105548_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/468424267_122128707986391262_1374940160526105548_n.jpg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/468424267_122128707986391262_1374940160526105548_n-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/468424267_122128707986391262_1374940160526105548_n-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/468424267_122128707986391262_1374940160526105548_n-768x432.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n\n\n\n<p>(g.p.) __________<\/p>\n\n\n\n<p>\u00abLo diceva\u00a0Neruda\u00a0che di giorno si suda \u2013 Ma la notte no!<br>Rispondeva\u00a0Picasso, io di giorno mi scasso \u2013 Ma la notte no!\u00bb<\/p>\n\n\n\n<p>Quaranta anni fa, avevamo tutti quaranta anni di meno, ed eravamo tutti pi\u00f9 contenti e anzi pi\u00f9 felici. Anche perch\u00e9 tutti, ma proprio tutti quanti &#8211; un fenomeno che non aveva precedenti e non avr\u00e0 seguiti &#8211; a tarda sera vedevamo in tv Renzo Arbore.<\/p>\n\n\n\n<p>Nel 1985 cominci\u00f2 e si esaur\u00ec la breve, ma intensissima saga, di &#8220;Quelli della notte&#8221;. Interrotta non perch\u00e9 non aveva successo, bens\u00ec perch\u00e9 ne aveva troppo. Seguita nel 1987, con le stesse caratteristiche e con gli stessi esiti, da quella di &#8220;Indietro tutta&#8221;.<\/p>\n\n\n\n<p>Dopo aver rivoluzionato la radio, nel decennio precedente, insieme a Gianni Boncompagni, con &#8220;Alto gradimento&#8221;, modello ineguagliabile e ineguagliato, cos\u00ec, con questi due programmi cult,  Renzo Arbore rivoluzioner\u00e0 la televisione, spargendo buonumore.<\/p>\n\n\n\n<p>Erano gli anni Ottanta del nostro divertimento, leggeri, ottimisti, coinvolgenti, che spronavano a intraprendere, a fare, con un tocco abbondante di ritrovata fiducia.<\/p>\n\n\n\n<p>Lo specchio, ne furono quei due programmi televisivi.<\/p>\n\n\n\n<p>Personaggi simpaticamente surreali, improvvisazione assoluta, ironia a profusione, batture folgoranti, uso del doppio senso che, pur tagliente, non scadeva mai nella volgarit\u00e0 tormentoni irresistibili, satira del politicamente corretto, anche se allora non si diceva cos\u00ec, una manciata vagamente futurista, un esercizio continuo di genio creativo.<\/p>\n\n\n\n<p>\u00abNon capisco, ma mi adeguo\u00bb.<\/p>\n\n\n\n<p>\u00abChiamo io, o chiama lei?\u00bb\u00a0<\/p>\n\n\n\n<p>Sullo sfondo, la denuncia del potere enorme acquisito dalla televisione, capace ormai, a compiuta realizzazione della terribile profezia pasoliniana, non solo di influenzare, ma pure di condizionare proprio la nostra esistenza, \u00a0dettando ormai l&#8217;organizzazione del tempo e gestendo i rapporti interpersonali.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Vedi lo sponsor, il fantomatico <em>Cacao Meravigliao<\/em>, del tutto inventato, per la disperazione di legioni di potenziali acquirenti che continuavano a richiederlo nei supermercati.<\/p>\n\n\n\n<p>E quando la moglie stanca e assonnata andava a letto prima della fine, il marito la rassicurava: <\/p>\n\n\n\n<p>\u00abVENGO dopo il tigg\u00ec\u00bb\u00a0<\/p>\n\n\n\n<p> <\/p>\n\n\n\n<p> <\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/09\/h80-nostalgia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/09\/h80-nostalgia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.) __________ \u00abLo diceva\u00a0Neruda\u00a0che di giorno si suda \u2013 Ma la notte no!Rispondeva\u00a0Picasso, io di giorno mi scasso \u2013 Ma la notte no!\u00bb Quaranta anni fa, avevamo tutti quaranta anni di meno, ed eravamo tutti pi\u00f9 contenti e anzi pi\u00f9 felici. Anche perch\u00e9 tutti, ma proprio tutti quanti &#8211; un fenomeno che non aveva precedenti [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":240476,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240475"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=240475"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240475\/revisions"}],"predecessor-version":[{"id":240477,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240475\/revisions\/240477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/240476"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=240475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=240475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=240475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}