{"id":24052,"date":"2014-02-03T07:49:51","date_gmt":"2014-02-03T07:49:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24052"},"modified":"2014-02-03T07:49:51","modified_gmt":"2014-02-03T07:49:51","slug":"le-foibe-sabato-9-febbraio-un-incontro-per-la-giornata-del-ricordo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/le-foibe-sabato-9-febbraio-un-incontro-per-la-giornata-del-ricordo\/","title":{"rendered":"LE FOIBE: SABATO 9 FEBBRAIO UN INCONTRO PER LA GIORNATA DEL RICORDO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/FOIBE.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/FOIBE-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-24053\" \/><\/a>Promosso dall\u2019Associazione Culturale ControCorrente &#8211; sabato 9 febbraio alle ore 18,00 a Melissano in Piazza Immacolata presso il Centro Culturale \u201cQuintino Scozzi\u201d- , si terr\u00e0 un incontro per la ricorrenza della Giornata del Ricordo.<br \/>\nInterverranno:<br \/>\nMario De Cristofaro (Movimento Social Popolare)<br \/>\nRoberto Tundo (Circoli \u201cPrima l\u2019Italia\u201d)<br \/>\nAntonio Cardigliano (ControCorrente)<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/le-foibe-sabato-9-febbraio-un-incontro-per-la-giornata-del-ricordo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/le-foibe-sabato-9-febbraio-un-incontro-per-la-giornata-del-ricordo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Promosso dall\u2019Associazione Culturale ControCorrente &#8211; sabato 9 febbraio alle ore 18,00 a Melissano in Piazza Immacolata presso il Centro Culturale \u201cQuintino Scozzi\u201d- , si terr\u00e0 un incontro per la ricorrenza della Giornata del Ricordo. Interverranno: Mario De Cristofaro (Movimento Social Popolare) Roberto Tundo (Circoli \u201cPrima l\u2019Italia\u201d) Antonio Cardigliano (ControCorrente)<\/p>\n","protected":false},"author":4,"featured_media":24053,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24052"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24052"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24052\/revisions"}],"predecessor-version":[{"id":24054,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24052\/revisions\/24054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/24053"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}