{"id":240690,"date":"2025-03-15T14:47:00","date_gmt":"2025-03-15T13:47:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=240690"},"modified":"2025-03-15T16:15:06","modified_gmt":"2025-03-15T15:15:06","slug":"due-brillanti-operazioni-antidroga-dei-carabinieri-sequestrata-anche-quantitativo-di-micidiale-eroina","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/15\/due-brillanti-operazioni-antidroga-dei-carabinieri-sequestrata-anche-quantitativo-di-micidiale-eroina\/","title":{"rendered":"DUE BRILLANTI OPERAZIONI ANTIDROGA DEI CARABINIERI, SEQUESTRATO ANCHE QUANTITATIVO DI MICIDIALE EROINA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" class=\"wp-image-240692\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/CASERMA-CC-LECCE-25-NOVEMBRE-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/CASERMA-CC-LECCE-25-NOVEMBRE-1.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/CASERMA-CC-LECCE-25-NOVEMBRE-1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/CASERMA-CC-LECCE-25-NOVEMBRE-1-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/CASERMA-CC-LECCE-25-NOVEMBRE-1-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n\n\n\n<p>Report del Comando Provinciale dei Carabinieri di Lecce __________<\/p>\n\n\n\n<p><br> Continuano in tutta la Provincia le operazioni di controllo del territorio dei carabinieri per prevenire situazioni di degrado legate al traffico di stupefacenti. Altri due spacciatori sono finiti in manette.<\/p>\n\n\n\n<p><br>Il primo pusher arrestato \u00e8 un 49enne di San Cesario gi\u00e0 conosciuto alle Forze dell\u2019Ordine per i suoi precedenti penali. L\u2019indagine \u00e8 stata condotta dai carabinieri del Nucleo Operativo e Radiomobile di Lecce, che dopo aver controllato per alcuni giorni le abitudini dell\u2019uomo, venerd\u00ec sera sono entrati in azione e lo hanno fermato per un controllo. <\/p>\n\n\n\n<p>A casa sua, gli uomini dell\u2019Arma hanno trovato nascosti nella camera da letto ben 160 grammi di eroina \u201cbrown sugar\u201d, un tipo di droga che deve la sua fama ad un celebre brano dei Rolling Stones, chiamata cos\u00ec per il suo colore che ricorda il caramello o lo zucchero di canna. Oltre alla droga, \u00e8 stato sequestro tutto il materiale per pesare e confezionare le dosi da spacciare, fra cui un bilancino di precisione. Inoltre, sono stati sequestrati 150 euro in contanti ritenuti provento dell\u2019attivit\u00e0 di spaccio.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br>La seconda indagine antidroga \u00e8 stata invece portata a termine lo stesso giorno a Poggiardo, dai carabinieri della caserma locale, che hanno chiuso il cerchio intorno ad un ventenne sospettato di aver messo in piedi un giro di spaccio di cocaina. I primi appostamenti sono serviti a studiare la situazione, poi i militari dell\u2019Arma si sono organizzati per cercare di mandare a monte i piani del ragazzo.<br>Quando i carabinieri hanno fatto ingresso nell\u2019abitazione del giovane, che vive stabilmente a casa della nonna, hanno potuto approfittare del fattore sorpresa, dato che stava ancora dormendo. Invitato a tirare fuori tutta la droga in suo possesso, lui ha consegnato soltanto pochi grammi di hashish che aveva a portata di mano nella sua camera, forse convinto che sarebbe bastato quel gesto di collaborazione per evitare la perquisizione. I militari dell\u2019Arma, invece, hanno voluto andare a fondo della questione e sono cos\u00ec arrivati a perquisire il garage, dove hanno trovato sotto il sellino di uno scooter nella sua disponibilit\u00e0 una ventina di dosi di cocaina, nonch\u00e9 tutto il necessario per preparare le palline da vendere.<\/p>\n\n\n\n<p><br>Dopo aver illustrato i dettagli delle due operazioni al Pubblico Ministero della Procura della Repubblica di Lecce, il 49 enne di Lecce e il 20enne di Poggiardo sono stati arrestati con l\u2019accusa di \u201cDetenzione di stupefacenti ai fini di spaccio\u201d, invece la droga sequestrata sar\u00e0 analizzate in laboratorio per appurare il principio attivo. <\/p>\n\n\n\n<p>Per entrambi sono stati disposti gli arresti domiciliari, in attesa dell\u2019udienza di convalida.<br>Si precisa che il procedimento \u00e8 nella fase delle indagini preliminari, per cui l\u2019indagato \u00e8 da ritenersi innocente fino a sentenza definitiva.<br>Lecce, 15 marzo 2025.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1179\" height=\"1137\" class=\"wp-image-240691\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/IMG-20250315-WA0014.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/IMG-20250315-WA0014.jpg 1179w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/IMG-20250315-WA0014-300x289.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/IMG-20250315-WA0014-1024x988.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/IMG-20250315-WA0014-768x741.jpg 768w\" sizes=\"(max-width: 1179px) 100vw, 1179px\" \/> <\/p>\n\n\n\n<p>__________<\/p>\n\n\n\n<p>AGGIORNAMENTO della redazione di leccecronaca.it<\/p>\n\n\n\n<p>I presunti spacciatori arrestati sono Davide Miglietta, 49 anni, di San Cesario di Lecce, con precedenti specifici; e Lorenzo Presta, 20 anni, di Poggiardo.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/15\/due-brillanti-operazioni-antidroga-dei-carabinieri-sequestrata-anche-quantitativo-di-micidiale-eroina\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/15\/due-brillanti-operazioni-antidroga-dei-carabinieri-sequestrata-anche-quantitativo-di-micidiale-eroina\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report del Comando Provinciale dei Carabinieri di Lecce __________ Continuano in tutta la Provincia le operazioni di controllo del territorio dei carabinieri per prevenire situazioni di degrado legate al traffico di stupefacenti. Altri due spacciatori sono finiti in manette. Il primo pusher arrestato \u00e8 un 49enne di San Cesario gi\u00e0 conosciuto alle Forze dell\u2019Ordine per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":240693,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240690"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=240690"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240690\/revisions"}],"predecessor-version":[{"id":240695,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240690\/revisions\/240695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/240693"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=240690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=240690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=240690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}